{"id":104409,"date":"2025-04-28T15:37:04","date_gmt":"2025-04-28T13:37:04","guid":{"rendered":"https:\/\/kath-akademie-bayern.de\/?post_type=media-library&#038;p=104409"},"modified":"2025-04-29T09:31:13","modified_gmt":"2025-04-29T07:31:13","slug":"die-schlacht-von-adrianopel-378-und-der-gotenkrieg-376-382","status":"publish","type":"media-library","link":"https:\/\/kath-akademie-bayern.de\/en\/mediathek-eintrag\/die-schlacht-von-adrianopel-378-und-der-gotenkrieg-376-382\/","title":{"rendered":"Die Schlacht von Adrianopel (378) und der Gotenkrieg 376-382"},"content":{"rendered":"<h3><strong>I.<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>Das Erscheinen der Hunnen um 375 im n\u00f6rdlichen Schwarzmeerraum brachte die bisherige politische und soziale Ordnung n\u00f6rdlich von der Donau aus dem Gleichgewicht. Der Historiker Ammianus Marcellinus berichtet \u00fcber die Panik, die sich damals unter den Goten ausbreitete. Bei den Goten habe sich das Ger\u00fccht verbreitet, dass das vorher noch nie gesehenes Menschengeschlecht, d.h. die Hunnen, das sich wie ein Sturmwind von hohen Bergen aus einem abgelegenen Winkel aufgemacht habe, jeden Widerstand breche und in Tr\u00fcmmer lege. Nach einem misslungenem Versuch, den Hunnen Widerstand zu leisten, kam es bei den Tervingen zu Teilungen und die Mehrheit der Ethnie lie\u00df ihren bisherigen Herrscher Athanarich im Stich und wanderte unter der F\u00fchrung von Alaviv und Fritigern nach S\u00fcden, um neue Wohnsitze zu finden. Dar\u00fcber hinaus wanderten \u2013 ebenfalls nach S\u00fcden \u2013 auch die Greutungen unter Alatheus und Safrax, die inzwischen sogar Gruppierungen der Hunnen und Alanen f\u00fcr sich gewonnen hatten.<\/p>\n<p>Im Jahr 376 sammelten sich Tausende von Fl\u00fcchtlingen am Donauufer. Infolge der durch den Angriff der Hunnen hervorgerufenen Verwirrung und der daraus resultierenden Migrationen entstand eine Situation, die f\u00fcr die R\u00f6mer ziemlich neu war. An der r\u00f6mischen Grenze standen Tausende potentielle Immigranten, und nicht Invasoren, die nur an Beute und Pl\u00fcnderung d\u00e4chten. Sie wollten vor den Hunnen fliehen und erhofften sich Sicherheit jenseits der Donau. Man sollte dabei auch die wirtschaftlichen Folgen der Migrationen n\u00f6rdlich\u00a0 der Donau in Betracht ziehen. Es geht vor allem um die St\u00f6rung des labilen Gleichgewichts im Bereich der Nahrungsmittelversorgung. Die Nahrungsmittel, die die Tervingen ja immer durch den Handel mit den R\u00f6mern erg\u00e4nzen mussten, wie der Mangel infolge des Embargos in den Jahren 367-369 dies gezeigt hatte, waren nun nicht ausreichend f\u00fcr die wandernden Barbarenmassen.<\/p>\n<p>Wir wissen nicht, wie viele Menschen die Donauufer im Jahr 376 belagerten. Die Quellen berichten \u00fcbereinstimmend \u00fcber eine gro\u00dfe Masse von Barbaren. Nur Eunapios von Sardes gibt eine pr\u00e4zise Zahl an und spricht \u00fcber fast 200.000 Kriegern. Obwohl diese Angabe zu bezweifeln ist, ist es nicht ausgeschlossen, dass sie sich nicht nur auf die wehrf\u00e4higen M\u00e4nner beziehen k\u00f6nnte, sondern auf die gesamte Masse der Tervingen. Es ist aber klar, dass es so viele potentielle Immigranten gab, dass die gesamte Situation eine ganz neue und \u00fcberraschende Herausforderung f\u00fcr die ostr\u00f6mische Regierung darstellte.<\/p>\n<p>Die Lebensmittel jenseits der Donau gingen schnell zu Ende, wie dies Ammian bezeugt, der berichtet, dass der gr\u00f6\u00dfte Teil der Tervingen infolge des Mangels an Lebensmitteln stark geschw\u00e4cht gewesen sei und deswegen Athanarich im Stich gelassen habe. Laut Ammian hielten die nach einem Ausweg aus ihrer schwierigen Situation suchenden Tervingen Thrakien f\u00fcr besonders attraktiv, denn es habe sehr fruchtbaren Boden gehabt und sei durch die Weite der Donaustr\u00f6mung von den Gebieten getrennt worden, in denen die Hunnen agierten. Damit wies Ammian auf zwei h\u00f6chste Priorit\u00e4ten der Goten hin: \u00e4u\u00dfere Sicherheit und Sicherstellung der Versorgung mit notwendigen Lebensmitteln. Diese Priorit\u00e4ten werden auch der Politik und den Erwartungen der gotischen F\u00fcrsten in beiden Teilen des r\u00f6mischen Reiches in den folgenden Jahren zugrunde liegen.<\/p>\n<p>Die Tervingen des Alaviv und Fritigern schickten Unterh\u00e4ndler zu Kaiser Valens und versprachen nach seinen Gesetzen zu leben und Hilfstruppen zu stellen, wenn er ihnen Teile Thrakiens oder M\u00f6siens zur Ansiedlung anweise. Die R\u00f6mer aber waren sich wohl nicht v\u00f6llig dessen bewusst, was wirklich n\u00f6rdlich von der Donau passierte und wie gro\u00df das Ausma\u00df der Wanderungen war. Einen Einblick in Entscheidungsfindungsprozess am Kaiserhof gew\u00e4hrt uns wiederum Ammian. Einige kaiserliche Berater waren der Meinung, dass man einen konkreten Nutzen aus der Aufnahme der Tervingen ziehen k\u00f6nne. In erster Linie hoffte man auf die Verst\u00e4rkung der kaiserlichen Armee: die Immigranten k\u00f6nnten in die Armee eingezogen werden. Au\u00dferdem dachte man an \u00f6konomischen Nutzen: man k\u00f6nnte auf die Zwangsaushebung in den Provinzen verzichten, daf\u00fcr aber eine Geldabl\u00f6se fordern.<\/p>\n<p>Im Prinzip war die Idee, die Goten auf dem Reichsboden aufzunehmen und militarisch auszunutzen, keine Neuigkeit. Kleinere barbarische Gruppen waren schon fr\u00fcher aufgenommen worden. Neu war allerdings das Ausma\u00df der gew\u00fcnschten Ansiedlung \u2013 so viele Imigranten waren auf einmal noch nicht aufgenommen worden. Die hochrangigen Politiker am Hof des Valens dachten wohl nicht daran, welche logistische Schwierigkeiten und Versorgungsprobleme ein solches Unternehmen nach sich z\u00f6ge. Die Migranten sollten Land und Haustiere erhalten \u2013 \u00fcber weitere Details der Vereinbarung berichten aber die Quellen nicht.<\/p>\n<p>Die Aufnahme der Tervingen war nicht nur eine Chance, ihr milit\u00e4risches Potential auszunutzen, sondern auch in der Tat die einzige M\u00f6glichkeit den milit\u00e4rischen Konflikt mit den zum \u00c4u\u00dfersten getriebenen Barbaren zu vermeiden. Es stellte sich n\u00e4mlich die Frage, ob die lokalen r\u00f6mischen Truppen eine gro\u00dfangelegte barbarische Invasion damals erfolgreich h\u00e4tten abwehren k\u00f6nnen. Valens bereitete sich ja auf einen Krieg gegen Persien vor und brauchte daher keinen Krieg auf dem Balkan. Zieht man dies in Betracht, scheinen die Motive, von denen sich Valens leiten lie\u00df, nicht nur nicht sinnlos, sondern sogar sehr pragmatisch.<\/p>\n<p>Dar\u00fcber hinaus agierte er sehr vorsichtig, selbst wenn Ammian dies nicht bezeugen will. Als Garanten f\u00fcr das Wohlverhalten der Ank\u00f6mmlinge sollten Geiseln dienen \u2013 laut Zosimos lie\u00df der Kaiser viele gotische Kinder nach Asien bringen. Und Valens wollte auch nicht alle gotischen Migranten aufnehmen. Eine positive Antwort auf ihre Bitte erhielten nur die Tervingen des Alaviv und Fritigern. Wir wissen, dass auch andere gotische Gruppen an der Donau erschienen und ebenfalls um die Aufnahme baten. Sie bekamen hingegen einen abschl\u00e4gigen Bescheid.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>II.<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>Die \u00dcberquerung der Donau muss im Sommer 376 stattgefunden haben. Man d\u00fcrfte somit danach fragen, wo der Fehler lag, warum es zum Konflikt kam. Es scheint vor allem, dass die R\u00f6mer das Ausma\u00df der Migration falsch beurteilten und die erforderlichen Sicherheitsma\u00dfnahmen nicht beachteten. Die Zahl der Immigranten wurde nicht sorgf\u00e4ltig gesch\u00e4tzt, selbst wenn die Beamten die Anzahl der \u00fcber die Donau \u00fcbergesetzten Goten rechnerisch zu erfassen versuchten. Man kontrollierte auch nicht die Bewaffnung der Ank\u00f6mmlinge. Vieles deutet darauf hin, dass die Tervingen nicht entwaffnet wurden. Ein weiteres Problem bildeten Korruption sowie Missachtung der Pflichten durch Beamte und Soldaten, die laut Eunapios und Zosimos die Goten entwaffnen und z\u00e4hlen sollten. Sie h\u00e4tten aber ihre Pflichten vernachl\u00e4ssigt, da sie sich um den Erwerb von Sklaven, sch\u00f6nen Jungfrauen und J\u00fcnglingen gek\u00fcmmert h\u00e4tten, wie Eunapios \u00fcberliefert.<\/p>\n<p>Ein Teil der f\u00fcr die Organisation des \u00dcbergangs zust\u00e4ndigen Beamten versuchte sich offensichtlich auf Kosten der Einwanderer zu bereichern. Laut Ammian lag der Grund f\u00fcr die kommende Katastrophe gerade im Verhalten der r\u00f6mischen Verantwortlichen. Er verweist auf Lupicinus, <em>comes per Thracias<\/em> and <em>dux<\/em> Maximinus, denen die Organisation des ganzen Unternehmens \u00fcbertragen war, und stellt fest, dass ihre uners\u00e4ttliche Habgier die Quelle aller \u00dcbel gewesen sei. Dar\u00fcber hinaus l\u00f6ste die \u00dcberquerung das Hauptproblem der Goten nicht: auf dem r\u00f6mischen Boden litten sie nach wie vor Hunger, w\u00e4hrend die R\u00f6mer sie nicht ausreichend mit Nahrung versorgten.<\/p>\n<p>Lupicinus und Maximinus machten aus dem Hunger der Tervingen ein Gesch\u00e4ft und verkauften die Lebensmittel auf dem Schwarzmarkt zu enorm \u00fcberh\u00f6hten\u00a0Preisen. Es kam sogar dazu, dass man Hundefleisch gegen einen Sklaven einhandelte. Die Not war dabei so gro\u00df, dass es unter diesen eingetauschten Sklaven sogar Verwandte der Vornehmen unter den Tervingen gab. Die Goten f\u00fchlten sich dadurch zus\u00e4tzlich erniedrigt und gedem\u00fctigt und dachten an die Rache.<\/p>\n<p>Denn dass sich die Tervingen eine derart miserable Behandlung l\u00e4ngerfristig nicht gefallen lassen, konnte man leicht voraussagen. Selbst die Tatsache, dass diese gro\u00dfe Menge an Menschen nicht entwaffnet war, barg in sich riesiges Konfliktpotential. Es verwundert also nicht, dass sich bald Unmut \u00fcber die schlechte Behandlung und mangelnde Versorgung mit Lebensmitteln unter den Tervingen erhob. Lupicinus war sich wohl bewusst, welche Stimmungen bei den Tervingen herrschten. Um die Probleme verhindern zu k\u00f6nnen, zog er Truppen heran, um so die eingewanderten Barbaren wieder zum Abzug aus dem Donauraum zu zwingen.<\/p>\n<p>Durch den Abzug der Soldaten aus den Lagern an der Donau war die Donaugrenze zumindest teilweise von den r\u00f6mischen Truppen entbl\u00f6\u00dft. Dies nutzten andere barbarische Gruppen aus: weil die r\u00f6mischen Truppen und die Donauflotte woanders besch\u00e4ftigt wurden, setzten sowohl die Greutungen des Alatheus und Safrax mit ihren alanischen und hunischen Verb\u00fcndeten als auch die Gruppe des Farnobius und die Taifalen zum r\u00f6mischen Ufer des Flusses \u00fcber.<\/p>\n<p>Durch den milit\u00e4rischen Druck zwang Lupicinus die Tervingen das Donauufer im Fr\u00fchling 377 zu verlassen und nach S\u00fcden in Richtung Marcianopel abzuziehen. Wohl Anfang 377 wurden Fritigern und Alaviv von Lupicinus zu einem Gastmahl nach Marcianopel eingeladen, wobei ihre Leute weit von der Stadt ferngehalten wurden. Lupicinus muss nach einer Vers\u00f6hnung und Verbesserung der gotisch-r\u00f6mischen Verh\u00e4ltnisse gestrebt haben. Wenig zuverl\u00e4ssig scheint hingegen die \u00dcberlieferung des Jordanes zu sein, dass der r\u00f6mische Feldherr von vornherein die Ermordung der Gotenf\u00fcrsten plante. In diesem Fall h\u00e4tte er alles besser vorbereitet und zielstrebiger agiert.<\/p>\n<p>Zuzustimmen ist der Meinung von Herwig Wolfram, dass Misstrauen und falsche Einsch\u00e4tzung der Lage zu unkontrollierten Aktionen gef\u00fchrt h\u00e4tten. Die Tervingen forderten Einlass in die Stadt, um sich die Lebensmittel zu verschaffen. Dabei kam es aber zu Streitigkeiten mit den Einwohnern und zu einem Handgemenge, wobei es auf der r\u00f6mischen Seite Opfer gab. Unterdessen tagte Lupicinus mit den gotischen Anf\u00fchrern. Auf die Nachricht von den K\u00e4mpfen geriet er in Panik und handelte ohne Logik und Konsequenz. Zuerst lie\u00df er die Begleiter seiner G\u00e4ste t\u00f6ten, dann aber lie\u00df er Fritigern und andere Goten frei. Er hoffte naiv darauf, dass Fritigern seine Leute vor der Stadt beruhigen werde. Diese dramatischen Ereignisse gaben den Tervingen nun einen Anlass zum offenen Aufstand und der Krieg brach aus.<\/p>\n<p>Als die Gruppen der Goten die Umgebung von Marcianopel pl\u00fcnderten, versuchte Lupicinus die Rebellion im Keim zu ersticken. Er handelte schnell, aber letztlich erfolglos. Neun Meilen von Marcianopel entfernt kam es zu einer Schlacht, in der viele r\u00f6mische Soldaten get\u00f6tet wurden, w\u00e4hrend Lupicinus selbst sich durch Flucht retten konnte. Der Sieg gab den Tervingen neuen Mut. Sie r\u00fcsteten sich mit r\u00f6mischen Waffen aus und zogen \u00fcberall umher, ohne auf Widerstand zu sto\u00dfen. Zu den Rebellen str\u00f6mte auch eine Menge von armen Landbewohnern, Sklaven, Minenarbeitern und Steuerfl\u00fcchtlingen zu. Zweifelsohne wurden die Goten im Jahr 377 zu einer ernsthaften, gut bewaffneten milit\u00e4rischen Macht, selbst wenn sie keine festgef\u00fcgte homogene Struktur aufwiesen.<\/p>\n<p>Sp\u00e4testens nach der Schlacht bei Marcianopel erkannte Valens, wie ernst die Lage auf dem Balkan war. Aus diesem Grund gab er den Plan einer milit\u00e4rischen Auseinandersetzung mit Persien auf und wollte alle Streitigkeiten auf diplomatischem Weg l\u00f6sen. Allerdings kam er erst im Sommer 378 mit seiner Hauptstreitmacht nach Konstantinopel. Valens schickte aber die Heerf\u00fchrer Profuturus und Trajan mit einigen Legionen aus Armenien voraus. Diese Kampfgruppe muss nicht besonders gro\u00df gewesen sein, denn Ammian betont, dass sie den Barbaren an Zahl weit unterlegen war.<\/p>\n<p>Gleichzeitig bat Valens, den Westkaiser, seinen Neffen Gratian, um milit\u00e4rische Hilfe. Dieser setzte bald den <em>comes domesticorum<\/em> Richomeres und den Heermeister Frigeridus in Marsch. Zuerst erreichten aber die aus dem Osten kommenden Truppen die Balkanprovinzen. Das strategische Konzept des Profuturus und Trajan setzte das Abdr\u00e4ngen der Rebellen nach Norden voraus, um sie zwischen der Donau und den w\u00fcsten Ein\u00f6den einzuschlie\u00dfen. Hier sollte der Hunger die Barbaren zur Kapitulation zwingen. Und es gelang den R\u00f6mern, zumindest kurzfristig, die Hauptgruppe der Goten nach Norden zur\u00fcckzudr\u00e4ngen. Im Sp\u00e4tsommer 377 vereinigten Profuturus und Trajan ihre Kr\u00e4fte mit den westlichen Verst\u00e4rkungen, die unter dem Kommando von Richomeres standen \u2013 Frigeridus war hingegen erkrankt und nahm an den K\u00e4mpfen nicht teil.<\/p>\n<p>So war eine betr\u00e4chtliche r\u00f6mische Armee bei Ad Salices (wahrscheinlich in der N\u00e4he von Tomi) versammelt, wo sie nur in geringer Entfernung der gotischen Wagenburg gegen\u00fcberstand. Dies muss bedeuten, dass der r\u00f6mische Plan zumindest teilweise verwirklicht wurde, da sich ja die Hauptmasse der Tervingen im n\u00f6rdlichen Teil der Balkanprovinzen befand.<\/p>\n<p>Die Schlacht bei Ad Salices ging unentschieden aus, wobei beide Seiten hohe Verluste erlitten. Die R\u00f6mer zogen sich nach Marcianopel zur\u00fcck, w\u00e4hrend die Goten sieben Tage ihre Wagenburg nicht verlie\u00dfen. Bald danach kehrte Richomeres nach Westen zur\u00fcck, um weitere Verst\u00e4rkungen herbeizuf\u00fchren. Profuturus und Trajan nutzten hingegen die Situation aus und sperrten die Balkanp\u00e4sse. Alle Lebensmittel waren schon fr\u00fcher in die St\u00e4dte transportiert worden. Die r\u00f6mische F\u00fchrung plante durch die Abriegelung der Balkanp\u00e4sse die Barbaren im m\u00f6sisch-skythischem Raum einzuschlie\u00dfen und auszuhungern.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>III.<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>Auf diese Weise wurden die Tervingen zwischen Donau, Schwarzem Meer und Balkan eingeschlossen. Man darf davon ausgehen, dass die R\u00f6mer dieses strategische Konzept schon vor der Schlacht bei ad Salices in die Tat umzusetzen anfingen. Es stellt sich allerdings die Frage, warum die R\u00f6mer den Angriff auf die Goten bei ad Salices riskierten, wenn sie einen alternativen Plan hatten, der nicht so gef\u00e4hrlich war wie eine offene Schlacht. Meines Erachtens liegt die Antwort darauf in der Tatsache begr\u00fcndet, dass die r\u00f6mische F\u00fchrung klar erkannte, dass die Tervingen Fritigerns nur Teil des gr\u00f6\u00dferen Problems sind. Denn s\u00fcdlich der Donau agierten zu diesem Zeitpunkt mehrere barbarische Gruppen.<\/p>\n<p>Ammian, unsere Hauptquelle, wei\u00df aber \u00fcber andere Barbaren sehr wenig. Der Angriff auf die Goten bei Ad Salices l\u00e4sst sich somit als einen vergeblichen Versuch deuten, eine der feindlichen Gruppen m\u00f6glichst schnell auszuschalten. Die R\u00f6mer m\u00fcssen sich vor einer m\u00f6glichen Zusammenarbeit der Tervingen mit anderen Gruppen gef\u00fcrchtet haben, wobei es wahrscheinlich ist, dass einige dieser feindlichen Truppen s\u00fcdlich des Balkangebirges agierten. Die R\u00f6mer mussten somit verschiedene Szenarien in Betracht ziehen und sich auf Bedrohung von mehreren Seiten vorbereiten.<\/p>\n<p>Auf die Nachricht von der Schlacht bei ad Salices schickte Kaiser Valens den <em>magister equitum<\/em> Saturninus als Unterst\u00fctzung f\u00fcr die wenig effektiven Profuturus und Trajan. Inzwischen unternahmen auch die Goten Fritigerns die ersten erfolgslosen Versuche, die Blockade zu durchbrechen. Sie litten Hunger, denn alles E\u00dfbare in den Gebieten Skythiens und Nordm\u00f6siens war schon verzehrt war. In dieser Situation verst\u00e4ndigte sich Fritigern mit den Hunnen und Alanen. Die moderne Forschung nimmt an, dass diese mit den Greutungen des Alatheus und Safrax die sogenannte Drei-V\u00f6lker-Konfederation bildeten. Diese heterogene Gruppe entstand noch jenseits der Donau. Es bleibt dahingestellt, wo die Truppen des Alatheus und Safrax waren \u2013 es liegt aber nahe, dass sie s\u00fcdlich vom Balkan handelten. Dies w\u00fcrde aber bedeuten, dass die r\u00f6mischen Einheiten, die die Balkanp\u00e4sse kontrollierten, von zwei Seiten w\u00fcrden angegriffen werden k\u00f6nnen.<\/p>\n<p>Saturninus wurde von dieser Gefahr durch die von ihm aufgestellten Vorposten rechtzeitig informiert, weswegen er mit einem geschickten R\u00fcckzug begann \u2013 er \u00f6ffnete die Sperren und zog geordnet die Wachmannschaften ab. Die Truppen der Tervingen und ihre Verb\u00fcndeten ergossen sich in der Folge pl\u00fcndernd \u00fcber ganz Thrakien bis zum Rhodope-Gebirge. Eine der r\u00f6mischen Einheiten wurde von den Barbaren beim Schanzen \u00fcberrascht und v\u00f6llig vernichtet.<\/p>\n<p>Unterdessen war der Feldherr Frigeridus von Gratian erneut nach Thrakien beordert worden, um bei Beroea die wichtigsten Stra\u00dfenkreuzungen zu sperren. Er verf\u00fcgte aber \u00fcber keine gro\u00dfen Kr\u00e4fte und konnte den Barbaren keinen effektiven Widerstand leisten. Unter dem Druck der gotischen Verb\u00e4nde zog er sich in Richtung Illyrien zur\u00fcck. Auf dem R\u00fcckzug stie\u00df er auf gotisch-taifalische Pl\u00fcnderungsschar unter Farnobius. Er besiegte die Barbaren, deren \u00dcberreste er in Oberitalien als Kolonen ansiedeln lie\u00df. Er konnte danach auch den strategisch wichtigen Succi-Pass sichern und dadurch die Bewegungsfreiheit der Goten auf Thrakien beschr\u00e4nken.<\/p>\n<p>Als Gratian im Jahr 378 seinem Onkel zu Hilfe kommen und nach Osten mit seinem Heer marschieren wollte, griffen die alamanischen Lentienser R\u00e4tien an. Gratian unterbrach nun den Anmarsch nach Thrakien und ging zur Gegenoffensive \u00fcber. Er besiegte die Alamanen, verlor aber dabei sehr viel Zeit, so dass sein Heer auf dem thrakischen Kriegsschauplatz nicht rechtzeitig erschien. Im Mai 378 traf Valens mit den besten Truppen der Ostarmee in Konstantiopel ein. Er verlie\u00df die Hauptstadt wieder er am 11. Juni. Als die Aktivit\u00e4t der gotischen Pl\u00fcnderungsscharen im Bereich der Rhodopen dem Kaiser gemeldet wurde, beauftragte er den Heermeister Sebastianus, diese abzufangen und zu vernichten. Die Kampfgruppe des Sebastianus, die etwa 2000 Mann umfasste, stie\u00df n\u00f6rdlich von Adrianopel auf eine mit Beute beladene Schar der Goten, die er vernichtend schlagen konnte. Unterdessen erfuhr auch Fritigern, dass der Kaiser mit einem starken Heer nach Thrakien kam, so konzentrierte er seine Kr\u00e4fte, die zwischen Beroea und Nikopolis operiert hatten. Beide Seiten bereiteten sich also auf eine milit\u00e4rische Entscheidung.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>IV.<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>Im August kam Valens bis kurz vor Adrianopel, wo er das Lager schlug und auf das Eintreffen Gratians und dessen Heeres wartete. Dorthin kam dann aber nur der <em>comes domesticorum<\/em> Richomeres und \u00fcberbrachte dem Augustus des Ostreichs die Bitte Gratians, auf ihn noch\u00a0 kurze Zeit zu warten und die Goten erst nach der Vereinigung beider Armeen anzugreifen. In dieser Situation berief Valens einen Kriegsrat ein. Man war sich aber nicht dar\u00fcber einig, welcher Entschluss getroffen werden sollte. Insbesondere Sebastianus, der seinen j\u00fcngsten Erfolg \u00fcbersch\u00e4tzte, und seine Anh\u00e4nger pl\u00e4dierten f\u00fcr den sofortigen Angriff, w\u00e4hrend der <em>magister equitum<\/em> Victor riet, auf Gratians Heer zu warten und mit westlicher Unterst\u00fctzung gegen die Goten vorzugehen.<\/p>\n<p>Laut Ammian lie\u00df sich Valens vor allem von dem Motiv der Eifersucht leiten: Er habe es dem Mitkaiser gleichtun wollen, auf dessen Sieg \u00fcber die Alamannen er neidisch gewesen sei. Die moderne Forschung erkl\u00e4rt aber die Entscheidung des Valens, die Schlacht ohne die westlichen Verst\u00e4rkungen zu schlagen, vor allem aus milit\u00e4rischen bzw. politischen Motiven. Zweifelsohne war sich Valens seines \u00dcbergewichts sicher, weil er sich auf die Meldungen seiner Aufkl\u00e4rer st\u00fctzte, die die St\u00e4rke der Goten nur auf 10\u00a0000 Mann sch\u00e4tzten. Ammian betont aber ausdr\u00fccklich, dass diese Berechnungen falsch waren: Es handelte sich hier nur um einen Teil der gotischen Kr\u00e4fte, den die R\u00f6mer irrt\u00fcmlich f\u00fcr die ganze feindliche Streitmacht hielten.<\/p>\n<p>Einen zus\u00e4tzlichen zu erw\u00e4genden Faktor konnte das Streben danach bilden, die Gesamtheit der gotischen Kr\u00e4fte auf einen Streich zu vernichten. Dar\u00fcber hinaus sind auch strategische Gr\u00fcnde zu beachten: Valens erfuhr, dass die Goten auf den Posten Nike marschierten. Deswegen bestand die Gefahr, dass die Barbaren die Verkehrswege unterbrechen und ihn von Konstantinopel abschneiden k\u00f6nnten. Unter diesen Bedingungen muss der Kaiser den sofortigen Angriff auf die Goten als die beste L\u00f6sung betrachtet haben.<\/p>\n<p>Am Morgen des 9. August 378 setzte sich die r\u00f6mische Armee in Marsch, wobei der Tross und das Gep\u00e4ck im Lager bei Adrianopel zur\u00fcckgelassen wurden. Nach einem langen Marsch, der etwa acht Stunden dauerte, bekamen die R\u00f6mer am fr\u00fchen Nachmittag das gotische Lager zu Gesicht. Die r\u00f6mischen Soldaten hatten Hunger und Durst und waren sowohl vom langen und schweren Marsch als auch von der gl\u00fchenden Hitze erm\u00fcdet. Um die Hitze zu verst\u00e4rken, setzten die Goten die weiten Ebenen in Brand. Es gibt keine zuverl\u00e4ssigen Zahlenangaben, aufgrund derer man feststellen k\u00f6nnte, wie gro\u00df beide Armeen bei Adrianopel waren. Insgesamt k\u00f6nnte das r\u00f6mische Heer etwa 24.000 bis 26.000 Mann umfasst haben. Die St\u00e4rke des gotischen Heeres ist ebenfalls unbekannt, aber mit Sicherheit war es gr\u00f6\u00dfer als 10.000 Mann. Fritigern konnte meines Erachtens, \u00e4hnlich wie Valens, bei Adrianopel insgesamt \u00fcber etwa 25.000 Soldaten, vielleicht etwas mehr, verf\u00fcgen. Die Mehrheit seines Heeres bildete das Fu\u00dfvolk. Dazu kamen aber noch die Greutungen, Alanen und Hunnen hinzu, die beritten waren. Ihre St\u00e4rke ist auf etwa 4000 bis 5000 Mann zu sch\u00e4tzen. Das Schlachtfeld lag 12 Meilen von Adrianopel entfernt, d.h. etwa 18 Kilometer Der genaue Ort des Kampfes ist aber unbekannt.<\/p>\n<p>Das Gros des gotischen Fu\u00dfvolkes nahm eine gute Verteidigungsstellung auf einem H\u00fcgel inmitten einer kreisf\u00f6rmigen Wagenburg ein. Die Wagenburg wurde zum zentralen und wichtigsten Punkt der gotischen Befestigungen. Au\u00dferhalb der Befestigungen befand sich hingegen die greuthungisch-alanisch-hunnische Reiterei, \u00fcber deren Anwesenheit die R\u00f6mer nichts wussten und auf deren Flankenangriff sie nicht vorbereitet waren.<\/p>\n<p>Als die Feinde in Sicht kamen, begriff die r\u00f6mische F\u00fchrung wohl, dass die Kr\u00e4fte der Barbaren weitaus gr\u00f6\u00dfer waren als erwartet, und dass die Goten eine sehr g\u00fcnstige Verteidigungsstellung eingenommen hatten. An diesem Tag versuchten die Goten aber noch, Friedensverhandlungen aufzunehmen. Die erste Gesandtschaft wurde wegen ihres niedrigen Ranges nicht beachtet. Laut Ammian wollten die Goten damit nur Zeit gewinnen, damit die Reiterei von Alatheus und Safrax rechtzeitig Stellung beziehen konnte.<\/p>\n<p>Unmittelbar vor Ausbruch der Schlacht schickte Fritigern erneut eine Botschaft. Diesmal entschied Valens, Verhandlungen zu beginnen. Die R\u00f6mer waren sogar bereit, Geiseln zu stellen. Fritigern zog die Sache absichtlich in die L\u00e4nge: Zum einen brauchte er Zeit f\u00fcr Alatheus und Safrax, zum anderen war er wirklich kompromissbereit. Aus dem Bericht Ammians geht hervor, dass es unter den Goten keine Einm\u00fctigkeit gab, wobei die Gruppe um Fritigern in der Tat bereit war, Frieden mit Rom zu schlie\u00dfen. Ungeachtet der wirklichen Intentionen beider Seiten machte die Disziplinlosigkeit der r\u00f6mischen Truppen jeglichen Verhandlungen ein Ende.<\/p>\n<p>Valens verlor sehr schnell die Kontrolle \u00fcber das Geschehen. Zwei r\u00f6mische Abteilungen \u2013 <em>sagittarii<\/em> and <em>scutarii<\/em> \u2013 griffen ohne Befehl die gotischen Befestigungen an. Damit kam es spontan zur Schlacht. Dieser Angriff der Scutarier und Sagittarier wurde schnell zur\u00fcckgeschlagen. Ihre Flucht provozierte aber die Reaktion der r\u00f6mischen Infanterie auf dem linken Fl\u00fcgel und diese r\u00fcckte vor. Dadurch kam der linke Fl\u00fcgel schnell bis unmittelbar an die Wagenburg heran. Als die R\u00f6mer hier erfolgreich nach vorne dr\u00e4ngten, erschien die greuthungisch-alanisch-hunnische Kavallerie des Alatheus und Safrax auf dem Schlachtfeld, was die R\u00f6mer v\u00f6llig \u00fcberraschte. Das Eingreifen der Reiterei in die Schlacht wirkte sich entscheidend auf den Verlauf des Geschehens aus. Denn die Reiter des Alatheus und Safrax griffen unerwartet die r\u00f6mische Flanke an.<\/p>\n<p>Der Flankenangriff \u00fcberraschte die r\u00f6mische Reiterei, die keinen Widerstand leistete und die Flucht ergriff. Der vorger\u00fcckte linke r\u00f6mische Fl\u00fcgel war entbl\u00f6\u00dft, die gotischen, hunnischen und alanischen Reiter umfassten die r\u00f6mische Infanterie und gelangten in den R\u00fccken der gesamten r\u00f6mischen Schlachtreihe. Auch das gotische Fu\u00dfvolk verlie\u00df die Wagenburg und ging auf der ganzen Linie zum Gegenangriff \u00fcber. Es ist klar, dass die Katastrophe auf dem vorger\u00fccktem linken Fl\u00fcgel begann: Von dieser Flanke her wurde die r\u00f6mische Infanterie aufgerollt. Trotz der kritischen Situation leisteten die R\u00f6mer einige Stunden tapferen Widerstand. Der umzingelte linke r\u00f6mische Fl\u00fcgel wurde fast v\u00f6llig vernichtet. In anderen Abschnitten hielten die r\u00f6mischen Linien ungef\u00e4hr bis zum Abend.<\/p>\n<p>Auf dem Schlachtfeld fand auch der Kaiser Valens den Tod. Bei Adrianopel entkam kaum ein Drittel der Armee; au\u00dfer dem Kaiser fanden zahlreiche hohe Offiziere den Tod. Insgesamt kann man die r\u00f6mischen Verluste auf etwa 16.000 Tote sch\u00e4tzen. Die Niederlage resultierte nicht aus einer falschen Strategie des Valens, sondern aus ganz konkreten Schw\u00e4chen im taktischen Bereich und aus einem bestimmten Verlauf des Geschehens auf dem Schlachtfeld: Die r\u00f6mische Armee wurde \u00fcberraschend von der Flanke und dann im R\u00fccken angegriffen, und dies reichte aus, die Schlacht zu entscheiden. Dar\u00fcber hinaus waren die r\u00f6mischen Soldaten vor Hunger, Durst und wegen des langen Marsches in brennender Hitze ersch\u00f6pft.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>V.<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>Die L\u00f6sung des Gotenproblems, die Gratian dem Feldherr Theodosius, den er zum Rang des Kaisers am 19. Januar 379 erhob, konnte nicht mehr in der blo\u00dfen Verdr\u00e4ngung der Goten aus den Reichsgrenzen bestehen. Dies zu schaffen, war Rom nun einfach zu schwach. Man suchte allerdings zuerst nach radikalen Methoden der Bew\u00e4ltigung der Krise. So wurden in Asien zahlreiche gotische Soldaten, die fr\u00fcher Aufnahme gefunden hatten und \u00fcber verschiedene St\u00e4dte und Lager verteilt waren, auf Befehl des Heermeisters Julius ermordet. Theodosius musste aber vor allem eine neue Ostarmee aufstellen. Viele Einheiten, die wir aus der <em>Notitia Dignitatum<\/em> kennen, wurden von diesem Kaiser 379 und 380 geschaffen. Selbst die Goten wurden damals wieder in gro\u00dfer Zahl angeworben.<\/p>\n<p>Es ist nicht v\u00f6llig klar, wie sich die Ereignisse auf dem Kriegsschauplatz es Balkans 379 bis 382 entwickelten, weil der Bericht des Zosimos, der auf Eunapios zur\u00fcckgeht, wenig pr\u00e4zise ist und deutliche K\u00fcrzungen aufweist. Theodosius setzte sich wohl zum Hauptziel, Konstantinopel zu sichern, denn seine Handlungen konzentrierten sich auf Thrakien. 379 errang Modares, der Gote im r\u00f6mischen Dienst, einen Sieg \u00fcber gotische Pl\u00fcnderer in Thrakien. Bald erkannte man aber, dass eine milit\u00e4rische L\u00f6sung nicht erreichbar ist \u2013 die Goten f\u00fcgten der neuen kaiserlichen Armee eine weitere dem\u00fctigende Niederlage zu, zahlreiche Soldaten desertierten vom Schlachtfeld, und Theodosius musste sich durch Flucht retten. dann Thessalien und Mazedonien fielen gotischen Pl\u00fcnderern zum Opfer.<\/p>\n<p>Auf Theodosius\u2019 Hilfegesuch schickte ihm Gratian ein starkes Korps unter Bauto und Arbogast. Es gelang ihnen, die Goten erneut nach Niederm\u00f6sien zu verdr\u00e4ngen. Mehr erreichte man nicht. Gef\u00e4hrdet wurde auch Pannonien von den Greutungen und ihren hunisch-alanischen Verb\u00fcndeten. Wenn der Historiker Jordanes Recht hat, kam Gratian damals zum Schluss, dass nur Verhandlungen auf diplomatischem Weg eine Chance f\u00fcr dauerhaften Frieden er\u00f6ffnen und schloss ein Abkommen mit den Eindringlingen, wohl noch im Jahr 380. Er siedelte sie in den Provinzen Pannonia II und Valeria an. Theodosius selbst zog am 24. November 380 in Konstantinopel ein.<\/p>\n<p>Nach einigen Erfolgen sowie Misserfolgen gelangte Theodosius eigentlich wieder an den Ausgangspunkt; er stand wieder vor dem Problem der Ansiedlung der Goten auf r\u00f6mischem Boden gegen ihren Dienst f\u00fcr das r\u00f6mische Reich. Er wusste aber besser als Valens, welche Bedrohungen und Auswirkungen dies nach sich zieht. Er war dabei imstande, gewisse freundliche Gesten zu machen, durch welche er sich bei den Goten gro\u00dfes Ansehen verschaffte, so dass sie ihn nicht nur als einen r\u00f6mischen Kaiser, sondern auch als einen Freund der Goten und einen Bef\u00fcrworter des Friedens wahrnahmen: \u201eama\u00adtor pacis generisque Gothorum.\u201c<\/p>\n<p>Dieser geschickte politische Kurs l\u00e4sst sich im ehrenvollen Empfang des Athanarich in Konstantinopel am 11. Januar 381 erkennen, der aus seinem Land vertrieben wurde, und im gro\u00dfen Gepr\u00e4nge, mit dem Theodosius ihn nach dessen pl\u00f6tzlichen Tod bestatte. Dies war eine Demonstration der r\u00f6mischen St\u00e4rke aber auch ein Zeichen der Friedensbereitschaft. Auf diese Weise machte Theodosius den Goten ein verlockendes Angebot und bewies, dass er Teile von ihnen f\u00fcr sich gewinnen konnte. Die Ausnutzung der inneren Spaltungen und Konfliktlinien zwischen den einzelnen gotischen Gruppen oder Anf\u00fchrern muss somit als einer der wichtigen Faktoren betrachtet werden, die bald zum Frieden f\u00fchren w\u00fcrden. Die K\u00e4mpfe h\u00f6rten zwar nicht sofort auf, aber beide Seiten waren nun wieder bereit, dem Krieg ein Ende zu machen.<\/p>\n<p>Am 3. Oktober 382 kam es zum Friedensschluss mit den Goten: Laut <em>Consularia Constantinopolitana<\/em> \u201eunterwarf sich das ganze Volk der Goten zusammen mit seinem K\u00f6nig dem r\u00f6mischen Reich\u201d. Der anonyme gotische rex, der die Verhandlungen mit dem Kaiser gef\u00fchrt hatte, ist unbekannt. Das Wesen des mit Goten geschlossenen Vertrags, dessen Einzelbestimmungen unbekannt sind, ist in der Forschung umstritten. Themistios, Pacatus, Orosius und andere r\u00f6mische Autoren deuten ihn als eine bedingungslose Kapitulation. Die r\u00f6mische Seite wollte darin die L\u00f6sung des Gotenproblems und den Sieg \u00fcber die Goten sehen.<\/p>\n<p>Es ist aber auch klar, dass die Goten steuerfreien Grundbesitz in Thrakien zugeteilt erhielten und im Gegenzug Truppen f\u00fcr den Kriegsfall \u2013 gegen Bezahlung \u2013 zu stellen versprachen. Wie die sp\u00e4teren Ereignisse zeigten, k\u00e4mpften sie in geschlossenen Verb\u00e4nden unter eigenen Anf\u00fchrern und lebten in Thrakien nach eigenem Recht unter eigenen F\u00fcrsten. Obwohl sie Oberhoheit des Kaisers anerkannten, genossen sie Autonomie. L\u00e4ngerfristig f\u00fchrte aber dieser Schwebezustand zwischen Reichsangeh\u00f6rigkeit und Autonomie zu den weiteren Konflikten.<\/p>\n<p>F\u00fcr die Zeitgenossen bedeutete Adrianopel einen wirklichen Schock. Die Kaiserpanegyriken an Theodosius, die von Themistios oder Pacatus in der ersten Dekade nach der Katastrophe gehalten wurden, bieten einen Einblick in die offizielle Deutung der j\u00fcngsten Ereignisse. Immer wieder betont man dort, dass diese Schlacht eine echte Katastrophe war \u2013 die r\u00f6mischen Armeen seien wie ein Schatten v\u00f6llig verschwunden, sagt Themistios. Der Frieden von 382 wurde von den Lobrednern als bestm\u00f6gliche L\u00f6sung des Problems und als Ausdruck der r\u00f6mischen Milde und Vernunft gedeutet. Der Redner Themistios versuchte 383, den Frieden zu rechtfertigen, indem er f\u00fcr die These pl\u00e4dierte, dass Theodosius erkannt habe, dass nur die Klugheit und nicht die milit\u00e4rische Macht den Frieden schaffen k\u00f6nne. Er habe gewusst, dass die v\u00f6llige Ausrottung der Goten unm\u00f6glich sei, so habe er Thrakien mit gotischen Bauern und nicht mit den Leichen der Toten f\u00fcllen wollen. Auf \u00e4hnliche Weise argumentierte Pacatus 389, der den Frieden von 382 als Beweis der\u00a0 Unterwerfung der Goten deutete.<\/p>\n<p>Dar\u00fcber hinaus l\u00f6ste Adrianopel eine Diskussion \u00fcber den Fortbestand des r\u00f6mischen Reiches aus, obwohl diese erst im 5. Jahrhundert richtig entflammte. So stellt Rufinus von Aquileia fest, dass diese Niederlage Anfang allen \u00dcbels f\u00fcr das Reich sei. Ammian, der seinen Glauben an Roms Ewigkeit an mehreren Stellen ausdr\u00fcckt, vergleicht Adrianopel mit Cannae und greift auf das Motiv der Krisenbew\u00e4ltigung zur\u00fcck: Rom habe die F\u00e4higkeit, sich nach Katastrophen zu erneuern. Schon einige Male h\u00e4tten die R\u00f6mer schwere Niederlagen erlitten, trotzdem h\u00e4tten sie immer den endg\u00fcltigen Sieg errungen. Adrianopel, \u00e4hnlich wie Cannae, sei kein Ende.<\/p>\n<p>Unter den Christen kursierten hingegen die Endzeiterwartungen. Adrianopel und sp\u00e4tere Niederlagen deutete man als Zeichen, die den Anbruch der Endzeit ank\u00fcndigten, wobei Ambrosius im Werk <em>De fide<\/em> annahm, dass die Kriege gegen die Goten, die er mit Gog, dem Feind des Auserw\u00e4hlten Volkes, identifiziert, schon von Ezechiel verk\u00fcndet worden seien: \u201e<em>Gog iste Gothus est. <\/em>Auf diese Art und Weise, noch bevor Alarich 410 Rom einnahm, hatten sich Fritigern und seine Tervingen, zumindest kurzfristig, in den Augen der R\u00f6mer in be\u00e4ngstigende Reiter der Apokalypse verwandelt.<\/p>","protected":false},"excerpt":{"rendered":"<p>I. &nbsp; Das Erscheinen der Hunnen um 375 im n\u00f6rdlichen Schwarzmeerraum brachte die bisherige politische und soziale Ordnung n\u00f6rdlich von der Donau aus dem Gleichgewicht. Der Historiker Ammianus Marcellinus berichtet \u00fcber die Panik, die sich damals unter den Goten ausbreitete. Bei den Goten habe sich das Ger\u00fccht verbreitet, dass das vorher noch nie gesehenes Menschengeschlecht,&hellip;<\/p>","protected":false},"author":5,"featured_media":32556,"menu_order":637,"template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"class_list":["post-104409","media-library","type-media-library","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Schlacht von Adrianopel (378) und der Gotenkrieg 376-382 - Katholische Akademie in Bayern<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kath-akademie-bayern.de\/en\/mediathek-eintrag\/die-schlacht-von-adrianopel-378-und-der-gotenkrieg-376-382\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Schlacht von Adrianopel (378) und der Gotenkrieg 376-382 - Katholische Akademie in Bayern\" \/>\n<meta property=\"og:description\" content=\"I. &nbsp; Das Erscheinen der Hunnen um 375 im n\u00f6rdlichen Schwarzmeerraum brachte die bisherige politische und soziale Ordnung n\u00f6rdlich von der Donau aus dem Gleichgewicht. Der Historiker Ammianus Marcellinus berichtet \u00fcber die Panik, die sich damals unter den Goten ausbreitete. Bei den Goten habe sich das Ger\u00fccht verbreitet, dass das vorher noch nie gesehenes Menschengeschlecht,&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kath-akademie-bayern.de\/en\/mediathek-eintrag\/die-schlacht-von-adrianopel-378-und-der-gotenkrieg-376-382\/\" \/>\n<meta property=\"og:site_name\" content=\"Katholische Akademie in Bayern\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/katholische.akademie.bayern\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-29T07:31:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kath-akademie-bayern.de\/wp-content\/uploads\/Geschichte.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"872\" \/>\n\t<meta property=\"og:image:height\" content=\"490\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"27 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/mediathek-eintrag\\\/die-schlacht-von-adrianopel-378-und-der-gotenkrieg-376-382\\\/\",\"url\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/mediathek-eintrag\\\/die-schlacht-von-adrianopel-378-und-der-gotenkrieg-376-382\\\/\",\"name\":\"Die Schlacht von Adrianopel (378) und der Gotenkrieg 376-382 - Katholische Akademie in Bayern\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/mediathek-eintrag\\\/die-schlacht-von-adrianopel-378-und-der-gotenkrieg-376-382\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/mediathek-eintrag\\\/die-schlacht-von-adrianopel-378-und-der-gotenkrieg-376-382\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/wp-content\\\/uploads\\\/Geschichte.jpg\",\"datePublished\":\"2025-04-28T13:37:04+00:00\",\"dateModified\":\"2025-04-29T07:31:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/mediathek-eintrag\\\/die-schlacht-von-adrianopel-378-und-der-gotenkrieg-376-382\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kath-akademie-bayern.de\\\/mediathek-eintrag\\\/die-schlacht-von-adrianopel-378-und-der-gotenkrieg-376-382\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/mediathek-eintrag\\\/die-schlacht-von-adrianopel-378-und-der-gotenkrieg-376-382\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/wp-content\\\/uploads\\\/Geschichte.jpg\",\"contentUrl\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/wp-content\\\/uploads\\\/Geschichte.jpg\",\"width\":872,\"height\":490},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/mediathek-eintrag\\\/die-schlacht-von-adrianopel-378-und-der-gotenkrieg-376-382\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Schlacht von Adrianopel (378) und der Gotenkrieg 376-382\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/#website\",\"url\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/\",\"name\":\"Katholische Akademie in Bayern\",\"description\":\"Kirche braucht Debatte: \u201ekatholisch\u201c mit Blick auf das Ganze \u2013 und \u201eakademisch\u201c im Vertrauen auf die Kraft der Argumente\",\"publisher\":{\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/#organization\",\"name\":\"Katholische Akademie in Bayern\",\"url\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/wp-content\\\/uploads\\\/Menue-Logo-Home@2x.png\",\"contentUrl\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/wp-content\\\/uploads\\\/Menue-Logo-Home@2x.png\",\"width\":496,\"height\":216,\"caption\":\"Katholische Akademie in Bayern\"},\"image\":{\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/katholische.akademie.bayern\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Schlacht von Adrianopel (378) und der Gotenkrieg 376-382 - Katholische Akademie in Bayern","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kath-akademie-bayern.de\/en\/mediathek-eintrag\/die-schlacht-von-adrianopel-378-und-der-gotenkrieg-376-382\/","og_locale":"en_GB","og_type":"article","og_title":"Die Schlacht von Adrianopel (378) und der Gotenkrieg 376-382 - Katholische Akademie in Bayern","og_description":"I. &nbsp; Das Erscheinen der Hunnen um 375 im n\u00f6rdlichen Schwarzmeerraum brachte die bisherige politische und soziale Ordnung n\u00f6rdlich von der Donau aus dem Gleichgewicht. Der Historiker Ammianus Marcellinus berichtet \u00fcber die Panik, die sich damals unter den Goten ausbreitete. Bei den Goten habe sich das Ger\u00fccht verbreitet, dass das vorher noch nie gesehenes Menschengeschlecht,&hellip;","og_url":"https:\/\/kath-akademie-bayern.de\/en\/mediathek-eintrag\/die-schlacht-von-adrianopel-378-und-der-gotenkrieg-376-382\/","og_site_name":"Katholische Akademie in Bayern","article_publisher":"https:\/\/www.facebook.com\/katholische.akademie.bayern\/","article_modified_time":"2025-04-29T07:31:13+00:00","og_image":[{"width":872,"height":490,"url":"https:\/\/kath-akademie-bayern.de\/wp-content\/uploads\/Geschichte.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"27 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kath-akademie-bayern.de\/mediathek-eintrag\/die-schlacht-von-adrianopel-378-und-der-gotenkrieg-376-382\/","url":"https:\/\/kath-akademie-bayern.de\/mediathek-eintrag\/die-schlacht-von-adrianopel-378-und-der-gotenkrieg-376-382\/","name":"Die Schlacht von Adrianopel (378) und der Gotenkrieg 376-382 - Katholische Akademie in Bayern","isPartOf":{"@id":"https:\/\/kath-akademie-bayern.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kath-akademie-bayern.de\/mediathek-eintrag\/die-schlacht-von-adrianopel-378-und-der-gotenkrieg-376-382\/#primaryimage"},"image":{"@id":"https:\/\/kath-akademie-bayern.de\/mediathek-eintrag\/die-schlacht-von-adrianopel-378-und-der-gotenkrieg-376-382\/#primaryimage"},"thumbnailUrl":"https:\/\/kath-akademie-bayern.de\/wp-content\/uploads\/Geschichte.jpg","datePublished":"2025-04-28T13:37:04+00:00","dateModified":"2025-04-29T07:31:13+00:00","breadcrumb":{"@id":"https:\/\/kath-akademie-bayern.de\/mediathek-eintrag\/die-schlacht-von-adrianopel-378-und-der-gotenkrieg-376-382\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kath-akademie-bayern.de\/mediathek-eintrag\/die-schlacht-von-adrianopel-378-und-der-gotenkrieg-376-382\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/kath-akademie-bayern.de\/mediathek-eintrag\/die-schlacht-von-adrianopel-378-und-der-gotenkrieg-376-382\/#primaryimage","url":"https:\/\/kath-akademie-bayern.de\/wp-content\/uploads\/Geschichte.jpg","contentUrl":"https:\/\/kath-akademie-bayern.de\/wp-content\/uploads\/Geschichte.jpg","width":872,"height":490},{"@type":"BreadcrumbList","@id":"https:\/\/kath-akademie-bayern.de\/mediathek-eintrag\/die-schlacht-von-adrianopel-378-und-der-gotenkrieg-376-382\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/kath-akademie-bayern.de\/"},{"@type":"ListItem","position":2,"name":"Die Schlacht von Adrianopel (378) und der Gotenkrieg 376-382"}]},{"@type":"WebSite","@id":"https:\/\/kath-akademie-bayern.de\/#website","url":"https:\/\/kath-akademie-bayern.de\/","name":"Catholic Academy in Bavaria","description":"Church needs debate: \"catholic\" looking at the whole - and \"academic\" trusting in the power of arguments","publisher":{"@id":"https:\/\/kath-akademie-bayern.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kath-akademie-bayern.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/kath-akademie-bayern.de\/#organization","name":"Catholic Academy in Bavaria","url":"https:\/\/kath-akademie-bayern.de\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/kath-akademie-bayern.de\/#\/schema\/logo\/image\/","url":"https:\/\/kath-akademie-bayern.de\/wp-content\/uploads\/Menue-Logo-Home@2x.png","contentUrl":"https:\/\/kath-akademie-bayern.de\/wp-content\/uploads\/Menue-Logo-Home@2x.png","width":496,"height":216,"caption":"Katholische Akademie in Bayern"},"image":{"@id":"https:\/\/kath-akademie-bayern.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/katholische.akademie.bayern\/"]}]}},"_links":{"self":[{"href":"https:\/\/kath-akademie-bayern.de\/en\/wp-json\/wp\/v2\/media-library\/104409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kath-akademie-bayern.de\/en\/wp-json\/wp\/v2\/media-library"}],"about":[{"href":"https:\/\/kath-akademie-bayern.de\/en\/wp-json\/wp\/v2\/types\/media-library"}],"author":[{"embeddable":true,"href":"https:\/\/kath-akademie-bayern.de\/en\/wp-json\/wp\/v2\/users\/5"}],"version-history":[{"count":1,"href":"https:\/\/kath-akademie-bayern.de\/en\/wp-json\/wp\/v2\/media-library\/104409\/revisions"}],"predecessor-version":[{"id":104410,"href":"https:\/\/kath-akademie-bayern.de\/en\/wp-json\/wp\/v2\/media-library\/104409\/revisions\/104410"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kath-akademie-bayern.de\/en\/wp-json\/wp\/v2\/media\/32556"}],"wp:attachment":[{"href":"https:\/\/kath-akademie-bayern.de\/en\/wp-json\/wp\/v2\/media?parent=104409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}