{"id":104411,"date":"2025-04-28T15:39:28","date_gmt":"2025-04-28T13:39:28","guid":{"rendered":"https:\/\/kath-akademie-bayern.de\/?post_type=media-library&#038;p=104411"},"modified":"2025-04-29T09:30:54","modified_gmt":"2025-04-29T07:30:54","slug":"alarich-i-karriere-eines-getriebenen","status":"publish","type":"media-library","link":"https:\/\/kath-akademie-bayern.de\/en\/mediathek-eintrag\/alarich-i-karriere-eines-getriebenen\/","title":{"rendered":"Alarich I. Karriere eines Getriebenen"},"content":{"rendered":"<h3><strong>I.<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>Am 24. August 410 war es dem terwingischen Goten Alarich gelungen, in das Zentrum der antiken Welt einzudringen; drei Tage pl\u00fcnderten seine Truppen die Tiberstadt, bevor sie sich am 27. August in Richtung S\u00fcden zur\u00fcckzogen. Bis heute wird dar\u00fcber ger\u00e4tselt, wie es so weit hatte kommen k\u00f6nnen; bereits direkt nach dem Fall der Stadt begannen die Konflikte um Schuld und Interpretation des Ungl\u00fccks zu toben. Es sind diese Auseinandersetzungen, die unsere \u00dcberlieferung dominieren, wohingegen das Ereignis selbst in den literarischen Zeugnissen kaum greifbar ist und auch der arch\u00e4ologische Befund bisher nur wenige Erkenntnisse ergeben hat.<\/p>\n<p>Ein einziges Dokument eines Zeitzeugen ist erhalten geblieben, und dieses beschr\u00e4nkt sich auf einen kurzen Satz: Darin hielt der Prediger Pelagius, der sich 410 in Rom befand, sp\u00e4ter fest, dass sich \u201edasselbe Bild des Todes allen\u201c gezeigt habe. Demgegen\u00fcber bietet das Geschichtswerk des spanischen Presbyters Orosius \u2013 ein Zeitgenosse, der die Ereignisse jedoch nicht miterleben musste \u2013 gerade im zentralen Kapitel \u00fcber die Einnahme der Stadt nicht viel mehr als eifrige Arbeit an einer frommen Legende: Die eingedrungenen Barbaren und die r\u00f6mische Bev\u00f6lkerung h\u00e4tten sich gemeinsam zu einer frommen Prozession formiert und hymnensingend liturgisches Ger\u00e4t in Sicherheit gebracht, die Invasoren dabei in der Rolle der Beschirmer der ver\u00e4ngstigten R\u00f6mer.<\/p>\n<p>Alarich selbst erscheint hier als Inbegriff des tugendhaft-frommen Eroberers, dem es in erster Linie um den Schutz der christlichen Bev\u00f6lkerung gegangen sei, der \u201eaus Gottesfurcht milde beim Morden\u201c agiert habe. Wie Zeitgenossen auf diese idealisierte Darstellung reagiert haben, wissen wir nicht. Viele von ihnen waren geflohen \u2013 einige Predigten, die Augustinus im nordafrikanischen Hippo gehalten hat, sprechen ganz direkt Fl\u00fcchtlinge an und versuchen ihnen Halt in schweren Zeiten zu vermitteln. Es sind dies Texte, die veranschaulichen, wie der Kirchenvater um eine ad\u00e4quate Deutung der Ereignisse rang. Das Resultat dieses Nachdenkens f\u00fcgte sich ab 412\/13 in Augustins theologischem Hauptwerk <em>De civitate Dei<\/em> (<em>Die Gottesstadt<\/em>) zusammen, das mit seiner radikalen Abwertung jeglicher Form irdischer Ordnung gegen\u00fcber der <em>civitas Dei<\/em> nicht nur einen tiefgr\u00fcndigen Weg wies, das Geschehen theologisch-philosophisch einzuordnen, sondern zugleich zu einer der Grundlagen der lateinischen Kirchengeschichte gerann.<\/p>\n<p>Es ist diese Form der intellektuellen Auseinandersetzung, die Alarichs Handstreich zu einem epochalen Ereignis erhob \u2013 eine Auseinandersetzung, die sich um Fragen des Verstehens und Deutens, um Verantwortung und Schuld drehte und sich rasch auf einen Konflikt zwischen Christen und Altgl\u00e4ubigen hin zuspitzte. Sie wird bis heute fortgef\u00fchrt und \u00fcberw\u00f6lbt dabei die Tatsache, dass die Eroberung der Stadt innerhalb der politischen Geschichte nicht mehr als eine Fu\u00dfnote darstellte. Denn l\u00e4ngst lagen die Brennpunkte des Geschehens an anderen Orten, und weder vermochte Alarich gro\u00dfen Nutzen aus dem Fall Roms zu ziehen noch konnte er damit die Herrschaft des Kaisers Honorius gef\u00e4hrden. Es war jedenfalls nicht der politische, sondern der ideelle Rang Roms, den Alarich aufs schwerste besch\u00e4digt hatte. Doch hatte dies \u00fcberhaupt im Interesse des Eroberers liegen k\u00f6nnen?<\/p>\n<p>In Alarich begegnen wir einer der Zentralgestalten der V\u00f6lkerwanderungszeit \u2013 eine jener schillernden Einzelpers\u00f6nlichkeiten, die in der Vergangenheit als Motoren jener grundlegenden Transformationsprozesse galten, die Antike und Mittelalter voneinander getrennt haben sollen. Und seit der Antike scheiden sich an der Bewertung Alarichs die Geister. Eine wirkm\u00e4chtige Charakteristik verfasste der angeblich gotische Historiograph Jordanes um die Mitte des 6. Jahrhunderts \u2013 also schon anderthalb Jahrhunderte nach Alarichs Tod \u2013 in Konstantinopel: \u201eAls aber Theodosius, der Liebhaber des Friedens und des Gotenvolkes, das Zeitliche gesegnet hatte [\u2026], wuchs bald der Verdruss der Goten [\u2026]; und weil sie f\u00fcrchteten, dass in einem zu langen Frieden ihre Tapferkeit verloren gehen k\u00f6nnte, setzten sie Alarich zum K\u00f6nig \u00fcber sich, der aus dem zweiten vornehmen Hause der Goten nach den Amalern, n\u00e4mlich dem der bewundernswerten Balthen stammte, die schon l\u00e4ngst wegen ihrer T\u00fcchtigkeit, n\u00e4mlich ihrer K\u00fchnheit, den Namen \u201aBalthen\u2018 bei den Menschen erworben hatten, d.h. \u201adie K\u00fchnen\u2018.\u201c<\/p>\n<p>Ein K\u00f6nigssohn also, dessen K\u00fchnheit bereits seinen Genen eingeschrieben gewesen sein soll und dessen Ruhm weithin strahlte \u2013 so weit, dass im 19. Jahrhundert Ferdinand Gregorovius\u00a0 (1821-1891) an den Ereignissen des Jahres 410 den Beginn des europ\u00e4ischen Mittelalters festmachen konnte, und noch Ludwig Schmidt (1862-1944), einer der gro\u00dfen V\u00f6lkerwanderungshistoriker des 20. Jahrhunderts, vermeinte in Alarich \u201eeine der kraftvollsten, sympathischsten Heldengestalten der germanischen Urzeit\u201c erkennen zu k\u00f6nnen.<\/p>\n<p>Heute ist man weitaus vorsichtiger, und im Allgemeinen sprechen Zur\u00fcckhaltung und Skepsis aus den j\u00fcngeren Beurteilungen des Terwingenf\u00fchrers. Ich selbst habe schon vor einiger Zeit auf die Zerrissenheit Alarichs im Spannungsfeld zwischen den divergierenden Interessen Roms \u2013 bei denen man noch einmal dezidiert zwischen dem westlichen und dem \u00f6stlichen Kaiserhof unterscheiden muss \u2013 sowie seiner eigenen Leute hingewiesen und die daraus resultierende Dynamik in Richtung einer regelrechten Verzweiflungstat im August 410 gedeutet. Diese Interpretation m\u00f6chte ich auch im Folgenden vertreten. Wer also war diese Figur, die auch in der aktuellen Forschung von der Anmutung des Tragischen umweht wird?<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>II.<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>Schon seine Herkunft liegt im Dunkel. Wenn Jordanes ihn im 6. Jahrhundert zu einem Hauptvertreter eines K\u00f6nigshauses der \u201aBalthen\u2018 erhebt, so geschieht das vor allem zu dem Zweck, neben den ostgotischen Amalern auch bei den Westgoten eine tatkr\u00e4ftige und identit\u00e4tsstiftende K\u00f6nigsfamilie zu konstruieren. Auch Claudians Behauptung, der Terwinge sei im Donaudelta auf der Insel Peuke geboren, reflektiert wohl eher die Vorstellung, dass eine Gestalt, die zeitlebens sichtbar zwischen der r\u00f6mischen und der barbarischen Sph\u00e4re pendelte, eben auch auf der Grenze zwischen beiden Sph\u00e4ren ihren Ursprung genommen haben m\u00fcsse. Nichts spricht allerdings dagegen, Alarichs Herkunft zumindest grob im Gebiet der unteren Donau zu verorten \u2013 denn dies war tats\u00e4chlich die Heimat der gotischen Terwingen. Doch mehr wissen wir nicht.<\/p>\n<p>Es gibt liebgewonnene Vorstellungen, von denen wir uns verabschieden sollten: so etwa der Gedanke, es habe in der zweiten H\u00e4lfte des 4. Jahrhunderts schon so etwas wie <em>die <\/em>Westgoten gegeben; stattdessen begegnen uns nach den Ereignissen 375-378 verschiedentlich kleinere Gruppen und Verb\u00e4nde unter unterschiedlichen Anf\u00fchrern, die nur lose zusammengef\u00fcgt waren bzw. nebeneinander, mitunter auch gegeneinander agierten. Eine dieser Gruppen stand im letzten Jahrzehnt des 4. Jahrhunderts unter der F\u00fchrung Alarichs \u2013 und damit dies so bleiben konnte und seine Anh\u00e4ngerschaft weiter wuchs, musste dieser sich in spektakul\u00e4ren, Erfolg verhei\u00dfenden Aktionen profilieren.<\/p>\n<p>Zwei Aspekte wird man zu ber\u00fccksichtigen haben: Zum einen die Tatsache, dass nach dem Tod Theodosius\u2018 I. im Jahr 395 kein Alleinerbe zur Verf\u00fcgung stand, sondern die Herrschaft auf seine beiden S\u00f6hne Arkadios (etwa 17 Jahre alt, Osten) und Honorius (10 Jahre alt, Westen) \u00fcberging \u2013 ein Jugendlicher und ein Kind, die sich sogleich in einem Netz aus konkurrierenden Beratern und wohlmeinenden F\u00fchrungsfiguren verfingen, die eifers\u00fcchtig ihre jeweiligen Macht- und Einflusssph\u00e4ren auszubauen bestrebt waren. Dieser Prozess setzte unmittelbar nach dem Tod des Theodosius ein und f\u00fchrte dazu, dass die \u00f6stliche und die westliche Reichsadministration sich nun rasch zu eigenst\u00e4ndigen Machtzentren entwickelten, die bald auch in Konflikt miteinander gerieten und sich, zumal in den Jahren um 400, mehrfach in Richtung eines B\u00fcrgerkriegs bewegten. Osten und Westen begannen allm\u00e4hlich getrennte Wege zu gehen.<\/p>\n<p>Der zweite Aspekt betrifft Alarich und seine Anh\u00e4ngerschaft direkt: Selbstverst\u00e4ndlich galt der gotisch dominierte, faktisch wohl recht heterogene Verband als Barbarentruppe und wurde prinzipiell zun\u00e4chst einmal zutiefst verachtet \u2013 wusste man doch aus jahrhundertealter Erfahrung, dass die R\u00f6mer sich ungeachtet aller R\u00fcckschl\u00e4ge letztlich noch jedem Barbarenverband \u00fcberlegen gezeigt hatten. Andererseits aber litt das Reich \u2013 zumal nach der schweren Niederlage gegen die Goten im Jahr 378 und seit dem ersten Jahrzehnt des 5. Jahrhunderts aufgrund zunehmender Barbareneinf\u00e4lle und B\u00fcrgerkriege \u2013 unter chronischem Soldatenmangel. Selbst ein Barbarenhaufen wie derjenige Alarichs stellte vor diesem Hintergrund ein Wertobjekt dar, das man nicht einfach vernichten durfte, sondern f\u00fcr je eigene Zwecke zu instrumentalisieren hatte.<\/p>\n<p>Alarich und sein Heerhaufen weckten also Begehrlichkeiten, einerseits in Konstantinopel, andererseits aber auch bei Stilicho, dem General, der f\u00fcr den unm\u00fcndigen Honorius im Westen die Amtsgesch\u00e4fte f\u00fchrte und sich einer wachsenden Anzahl an Krisenherden gegen\u00fcbersah, die milit\u00e4risches Eingreifen erforderten und Ressourcen verschlangen. Das d\u00fcrfte der Grund daf\u00fcr sein, dass Stilicho den Alarich-Verband insgesamt f\u00fcnfmal in eine aussichtslose Lage man\u00f6vriert, aber zum Unverst\u00e4ndnis so mancher Zeitgenossen stets verschont hatte. Stattdessen entwickelte sich Stilicho im Verlauf der Jahre zu Alarichs wichtigstem Ansprechpartner im r\u00f6mischen Westen; und es war dementsprechend seine Ermordung im Jahr 408, die letztlich auch den Untergang Alarichs einl\u00e4utete.<\/p>\n<p>Erstmals begegnet uns der Terwingenf\u00fchrer, als er sich 391 pl\u00fcndernd durch den Balkan bewegte. Dies war damals unruhiges Terrain, und aus diesem Grund begab sich Kaiser Theodosius pers\u00f6nlich an den Krisenherd \u2013 auf keinen Fall sollten sich Zust\u00e4nde wie im Jahr 378 wiederholen. An der Maritza wollte er den Aufr\u00fchrern entgegentreten und entging wohl nur mit knapper Not einem Desaster. Erst Stilicho gelang es 392, Alarich erstmals zum Abschluss eines Vertrages zu zwingen.<\/p>\n<p>Er muss ihn dabei eng an Rom gebunden haben, denn 394 agierte der Gote mit seinen Truppen als Unterfeldheer im Heer des Theodosius, das am Frigidus (im heutigen Slowenien) dem Usurpator Eugenius entgegentrat. Theodosius erkaufte seinen Sieg damals mit einem gewaltigen, vermutlich kalkulierten Blutzoll, den seine gotischen Einheiten zu entrichten hatten, die bei dieser Gelegenheit zugleich auf ein ungef\u00e4hrliches Ma\u00df reduziert wurden. Das d\u00fcrfte Unruhe in Alarichs Verband ausgel\u00f6st haben, die sich zu heftigem Groll auswuchs, als nach Theodosius\u2018 Tod (395) Stilicho s\u00e4mtliche Auxiliar-Einheiten entlie\u00df und Alarichs Verband damit die wirtschaftliche Grundlage entzog.<\/p>\n<p>Schon jetzt zeigt sich, dass Alarich niemals selbst das Heft des Handelns vollst\u00e4ndig in seinen H\u00e4nden hielt; denn wollte er verhindern, dass sein Verband sich aufl\u00f6ste und seine Anh\u00e4nger sich auf die Suche nach lukrativeren Bedingungen begaben, so musste er in die Offensive gehen. Einem barbarischen Truppenf\u00fchrer blieb in dieser Situation letztlich nur eine M\u00f6glichkeit: durch schmerzhafte Pl\u00fcnderungen r\u00f6mischer Gebiete den Druck auf die Regierung zu erh\u00f6hen. Genau dies geschah. Und w\u00e4hrend erstmals gr\u00f6\u00dfere hunnische Gruppen die Donau \u00fcberschritten und in Thrakien eindrangen, w\u00e4hrend weitere Hunnenverb\u00e4nde \u00fcber die Kaukasusp\u00e4sse im r\u00f6mischen Osten einfielen und entsetzliche Verheerungen anrichteten, verlie\u00df Alarich auf Weisung Stilichos Italien und bewegte sich donauabw\u00e4rts in Richtung Thrakien.<\/p>\n<p>In Konstantinopel, das den Pl\u00fcnder-Verband langsam n\u00e4her heranr\u00fccken sah, bekam man kalte F\u00fc\u00dfe \u2013 Alarichs Kalk\u00fcl ging also auf: Rufinos, damals der m\u00e4chtigste Mann am Hof, bot dem terwingischen Gotten ein neues Abkommen an. M\u00f6glicherweise beinhaltete es bereits seine Ernennung zum <em>magister militum per Illyricum<\/em>, d.h. zu einem regul\u00e4ren r\u00f6mischen General. Alarich jedenfalls war vorerst ruhiggestellt und zog sich nach Illyricum zur\u00fcck \u2013 ein geschickter Schachzug der ostr\u00f6mischen Diplomatie, denn die dadurch in Mitleidenschaft gezogenen Gebiete wurden von der westr\u00f6mischen Regierung beansprucht.<\/p>\n<p>Hier k\u00f6nnen wir erstmals ein Leitmotiv beobachten, das sich fortan durch die weitere Laufbahn Alarichs ziehen wird: Er geriet zwischen die Fronten des sich zuspitzenden Konfliktes zwischen den beiden Reichsteilen, ohne die erforderliche Autonomie entwickeln zu k\u00f6nnen, sich daraus zu befreien. Seine einzigen Waffen blieben Pl\u00fcnderung und Verheerung.<\/p>\n<p>Die weitere Geschichte Alarichs vollzog sich in <strong>drei <\/strong>Phasen: Zun\u00e4chst versuchte er auf dem Balkan bzw. in Griechenland seine Position zu behaupten; im Jahr 401 zog er nach Westen und drang ein erstes Mal in Italien ein, bevor dann in den Jahren 408-410 sich der Kampf um Rom zuspitzte. Werfen wir zun\u00e4chst einen Blick auf die erste Phase.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>III.<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>Dem zwischen Alarich und Rufinos geschlossenen Vertrag war keine lange Dauer beschieden, denn die Verheerungen, mit denen der weiterhin mobile Verband Makedonien und Nordgriechenland \u00fcberzog, konnten die westr\u00f6mische F\u00fchrung nicht unger\u00fchrt lassen, da diese ja selbst die betroffenen Gebiete ihrem Territorium zurechnete. Folgerichtig begab sich Stilicho 395 nach Thessalien und bezog bei Larissa Stellung gegen Alarichs Heer. Doch musste er sich auf Befehl des Ostkaisers Arkadios zur\u00fcckziehen und die Kontingente Konstantinopels (die sich seit dem Tod des Theodosius in Mailand unter Kontrolle des westlichen Hofes befunden hatten) in ihre Heimat entlassen.<\/p>\n<p>M\u00f6glicherweise geschah dies nicht ganz uneigenn\u00fctzig. Denn als die Soldaten in Konstantinopel eintrafen, zerfleischten sie vor den Augen des hilflosen Arkadios erst einmal Stilichos Gegenspieler im Osten, den m\u00e4chtigen Rufinos \u2013 f\u00fcr Alarich eine Katastrophe. Denn mit ihm hatte der Gote seinen unmittelbaren Ansprechpartner verloren; einmal mehr hing er in der Luft und war ein Opfer der innerr\u00f6mischen Konflikte geworden; und einmal mehr verblieb ihm nur ein Mittel, um seine Position neu zu festigen: Die Pl\u00fcnderung. Und so sammelte er seine Leute und drang erstmals in Zentralgriechenland ein. Konstantinopel vermochte keine Hilfe zu entsenden, da s\u00e4mtliche Reserven im Kampf gegen im Osten eingefallene Hunnen ben\u00f6tigt wurden.<\/p>\n<p>Einmal mehr sah sich in dieser Situation Stilicho zum Eingreifen veranlasst. Wohlwissend, dass er auf ostr\u00f6mischem Territorium intervenierte, schloss er Alarich im Fr\u00fchjahr 397 im Nordwesten der Peloponnes ein. Wir wissen nicht, was auf den dadurch erzwungenen Verhandlungen abgesprochen wurde; Alarich jedoch durfte abermals abziehen \u2013 vermutlich deshalb, weil Stilicho seine Aufmerksamkeit inzwischen einem anderen Krisenherd zuwenden musste: Unter dem Statthalter Gildo war in Afrika ein Aufstand ausgebrochen.<\/p>\n<p>Und wieder w\u00f6lbte sich der Dauerkonflikt zwischen den beiden Kaiserh\u00f6fen \u00fcber die Geschehnisse. Denn in Konstantinopel konnte man zwar einerseits erleichtert aufatmen ob des erzwungenen R\u00fcckzugs Alarichs; andererseits bot gerade dieser die Gelegenheit, Stilicho direkt zu attackieren, da er den Gegner nicht ausgeschaltet hatte: Und so wertete man die Entscheidung des Generals kurzerhand als Hochverrat und erkl\u00e4rte ihn zum Staatsfeind (<em>hostis<\/em>).<\/p>\n<p>W\u00e4hrend sich im Westen dadurch eine veritable Krise zusammenbraute, tappte Alarich weiterhin im politischen Niemandsland umher. Seine Lage gestaltete sich zunehmend prek\u00e4r, und einmal mehr sah er sich gen\u00f6tigt, im Rahmen seiner M\u00f6glichkeiten ein Zeichen zu setzen: Dieses Mal erkor er die nordwestgriechische Landschaft Epiros zum Ziel seiner Brandschatzungen und erzwang dadurch einen weiteren Vertrag. Eutropios, der Oberkammerherr des Arkadios und inzwischen einflussreichster Mann am Kaiserhof, best\u00e4tigte Alarich in seinem Amt als <em>magister militum per Illyricum<\/em> und wies den Goten Wohnsitze in Makedonien zu. Das war ein kluger Schachzug, denn auf diese Weise gewann Konstantinopel einen sehr kraftvollen Puffer gegen weitere Gebietsanspr\u00fcche aus dem Westen. Und tats\u00e4chlich kehrte nun f\u00fcr einige Jahre Ruhe ein. Erst 401 h\u00f6ren wir wieder von Alarich.<\/p>\n<p>Warum der Gotenverband sich damals erneut in Bewegung setzte und dieses Mal den Weg nach Westen suchte, wird diskutiert. Von besonderer Bedeutung d\u00fcrfte neben wachsendem Druck aufgrund der hunnischen Westbewegung von den Schwarzmeersteppen Richtung unterer Donau, m\u00f6glichen Versorgungsproblemen, dem Bed\u00fcrfnis nach frischer Beute und einem damit zusammenh\u00e4ngenden Bem\u00fchen Alarichs, seine F\u00fchrungsposition durch Leistung und Erfolge zu konsolidieren, vornehmlich der Umstand gewesen sein, dass sich in der \u00f6stlichen Reichsh\u00e4lfte die Stimmung gegen\u00fcber Barbaren radikal verschlechtert hatte; dies f\u00fchrte inzwischen auch zu politischen Aktionen, die bedrohliche Wirkungen zu entfalten vermochten.<\/p>\n<p>Denn zunehmend avancierte die Politik gegen\u00fcber den Barbaren zu einem gef\u00e4hrlichen Instrument innerhalb der weiterhin anhaltenden Machtk\u00e4mpfe im Umfeld des schwachen Kaisers Arkadios. Im Jahr 400 kam es in Konstantinopel zu einem grausamen Massaker an dem gotisch-st\u00e4mmigen Offizier Gainas und seinen in r\u00f6mischen Diensten stehenden vorwiegend gotischen Truppen. Lynchmorde und Pogrome wurden aber auch aus anderen Orten des Ostens gemeldet. Diese Entwicklungen d\u00fcrfte Alarich mit Sorgenfalten beobachtet haben: F\u00fcr mehrheitlich barbarische Verb\u00e4nde wurde es allm\u00e4hlich ungem\u00fctlich.<\/p>\n<p>So setzte sich der Gotenverband also im Herbst des Jahres 401 wieder in Bewegung und suchte sein Gl\u00fcck im r\u00f6mischen Westen. Ohne auf gr\u00f6\u00dferen Widerstand zu sto\u00dfen, zog er \u00fcber den Balkan und die Julischen Alpen und stand bereits am 18. November in Italien. Auch wenn der Versuch, das strategisch wichtige Aquileia einzunehmen, fehlschlug, verheerten die Goten im Winter 401\/02 Venetien. Und als sich im Fr\u00fchjahr 402 der Belagerungsring um die Kaiserresidenz Mailand schloss, d\u00fcrfte auch der letzte Zeitgenosse die Bedrohlichkeit der Lage realisiert haben.<\/p>\n<p>Kaiser Honorius spielte mit dem Gedanken, sich nach Gallien abzusetzen; doch wich die Regierung stattdessen in das g\u00fcnstig gelegene und gut befestigte Ravenna aus, das fortan Hauptsitz der westr\u00f6mischen Kaiser bleiben sollte. Ansonsten: Panik allerorten. Viele sahen das unmittelbare Ende der Welt vor sich. In Rom begann man hektisch mit der Ausbesserung der verkommenen Stadtmauern. Aber auf Stilicho war Verlass: Mit rasch rekrutierten Entsatz-Truppen brach er Alarichs Belagerungsring um Mailand auf und jagte die Goten zun\u00e4chst einmal auseinander. In zwei nachfolgenden Schlachten bei Pollentia (Pollenzo, Piemont), wo der Verband hohe Verluste erlitt und nicht zuletzt Alarichs Familie sowie reiches Pl\u00fcnderungsgut in r\u00f6mische H\u00e4nde fielen, und \u2013 im Sommer 402 \u2013 bei Verona wurden die Goten geschlagen.<\/p>\n<p>Alarichs Lage war hoffnungslos; eingeschlossen von Stilichos Heer, setzten Seuchen seinen K\u00e4mpfern zu, Unzufriedenheit und massenhafte Desertionen waren die Folge. Es schien, als h\u00e4tten Alarichs Leute den Glauben an ihren Anf\u00fchrer verloren. Aber zum f\u00fcnften Mal verschonte Stilicho seinen Lieblingsgegner und erm\u00f6glichte ihm, sich auf den Balkan abzusetzen, vermutlich in Richtung Pannonien, wo der Verband einige Jahre ben\u00f6tigte, um sich zu regenerieren. Der Kontakt zu Stilicho blieb allerdings bestehen, und im Jahr 405 bef\u00f6rderte der h\u00f6chste General des Westens den Goten erneut zum <em>magister militum per Illyricum <\/em>\u2013 ein demonstrativer Eingriff in die Souver\u00e4nit\u00e4t des Ostens und eigentlich nur dadurch erkl\u00e4rbar, dass Stilicho nun offensiv den Konflikt mit Konstantinopel suchte.<\/p>\n<p>Die nachfolgenden Ereignisse indes machten jegliches Planen unmittelbar zur Makulatur: Ein gewaltiger, bis dahin unbekannter Barbarenverband unter F\u00fchrung des Radagaisus tauchte wie aus dem Nichts auf und \u201e\u00fcberschwemmte\u201c (\u201einundavit\u201c hei\u00dft es in den Quellen) Italien. Es handelte sich dabei wohl um eine mehrheitlich aus Goten, aber auch versprengten anderen Barbaren, aus Provinzialen, Sklaven und desertierten Soldaten bestehende multiethnische Gruppe, die ebenfalls dem Vordringen der Hunnen ausgewichen sein d\u00fcrfte. Stilicho musste umgehend s\u00e4mtliche Reserven zusammenkratzen, die ihm noch verblieben waren. Doch er siegte bei Fiesole, und der Verband der Invasoren, der eine au\u00dfergew\u00f6hnliche Gr\u00f6\u00dfe erreicht haben muss, zerfiel; die Massen der Gefangenen lie\u00dfen angeblich den italischen Sklavenmarkt zusammenbrechen. Tausende Radagaisus-K\u00e4mpfer wurden in Stilichos Heer integriert. Andere jedoch setzten sich ab und schlossen sich Alarich an, dessen Anh\u00e4ngerschaft infolge dieser Ereignisse allm\u00e4hlich wieder anzuschwellen begann.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>IV.<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>Auch wenn man den Radagaisus-Albtraum mit M\u00fche \u00fcberstanden hatte, sollte sich keine Ruhe einstellen. Denn in der Silvesternacht 406\/07 \u00fcberschritt ein offenbar ebenfalls gewaltiges Heer, bestehend aus pl\u00fcndernden Gruppen ganz unterschiedlicher Herkunft, den Rhein und begann Gallien und ab 409 auch die Iberische Halbinsel zu verheeren; dieser Barbarenzug verband sich mit einer Serie von Usurpationen in Britannien. Innerhalb weniger Monate drohte die westr\u00f6mische Regierung die Kontrolle \u00fcber gro\u00dfe Teile ihrer Territorien zu verlieren. Der Aufl\u00f6sungsprozess des Westr\u00f6mischen Reiches hatte nun sichtbare Gestalt gewonnen.<\/p>\n<p>Stilicho sah sich gezwungen, eventuelle Pl\u00e4ne mit Blick auf den Osten aufzugeben. Bem\u00fchungen, die Integrit\u00e4t des Reiches halbwegs wiederherzustellen, ja dessen Fortexistenz zu behaupten, hatten nun unmittelbaren Vorrang, und damit \u00e4nderte sich erneut die Rolle Alarichs: Seine Truppen, so Stilichos Kalk\u00fcl, sollten ihren Beitrag dazu leisten, die Ordnung im <em>Imperium Romanum<\/em> wiederherzustellen. Zu keinem Zeitpunkt d\u00fcrfte der Alarich-Verband f\u00fcr Stilicho wichtiger gewesen sein als in der chaotischen Situation nach dem Rhein\u00fcbergang der Barbaren. Das aber erh\u00f6hte Alarichs Preis betr\u00e4chtlich.<\/p>\n<p>Ein lukratives Abkommen mit der westr\u00f6mischen Regierung, die angesichts der bedrohlichen Lage kaum Handlungsspielr\u00e4ume besa\u00df, leuchtete am Horizont auf. Stilicho jedoch verlor wertvolle Zeit damit, den Kaiser und seine Berater sowie die r\u00f6mischen Senatoren von der Notwendigkeit zu \u00fcberzeugen, die selbstbewusste Barbarentruppe zu hohen Kosten einzukaufen. Und so entschloss sich Alarich, dem Entscheidungsprozess aufzuhelfen, indem er 408 in <em>Noricum<\/em> eindrang und sich bedrohlich nah vor den Grenzen Italiens positionierte. 4000 Goldpfund (= 288.000 <em>solidi<\/em>) verlangte er nun daf\u00fcr, einfach nur stillzuhalten.<\/p>\n<p>Die Emp\u00f6rung unter den italischen Eliten wuchs, und man machte nun Stilicho als Vandalensohn und Halbbarbaren verantwortlich f\u00fcr eine angeblich barbarenfreundliche Politik, die das Imperium ausverkaufe. Ambitionierte Figuren im Umfeld des Honorius nutzten die Gelegenheit, um sich in Stellung zu bringen. Der Kaiser konnte nicht verhindern, dass sein bester und vermutlich auch loyalster Feldherr am 22. August 408 ermordet wurde.<\/p>\n<p>Alarich hatte damit einmal mehr einen berechenbaren und zuverl\u00e4ssigen Verhandlungspartner verloren, und die neue F\u00fchrung in Ravenna sah nun keinen Anlass mehr f\u00fcr weitere Verhandlungen mit dem Goten; man ging davon aus, weiterhin stark genug zu sein, um die anstehenden Probleme milit\u00e4risch l\u00f6sen zu k\u00f6nnen \u2013 eine verh\u00e4ngnisvolle Fehleinsch\u00e4tzung.<\/p>\n<p>Was also tun? Pl\u00fcndern und Drohen nach dem bew\u00e4hrten Muster. Alarich marschierte also in Italien ein und stand bereits im Oktober vor Rom. Sein Verband wuchs derweil zu bedrohlicher Gr\u00f6\u00dfe an, weil Sklaven und Unzufriedene jeglicher Couleur sich ihm anschlossen; das erh\u00f6hte umso mehr den Erfolgsdruck.<\/p>\n<p>Und w\u00e4hrend in der Ewigen Stadt Hunger und Seuchen um sich griffen, fiel dem Senat nichts Originelleres ein, als auch noch Stilichos Witwe Serena demonstrativ zu ermorden, was Alarich indes kaum beeindruckte. Wie gro\u00df die Panik der R\u00f6mer war, zeigt sich daran, dass Bischof Innozenz I. sogar die Durchf\u00fchrung paganer Riten zur Rettung der Stadt tolerierte. Als auch dies nichts an der Gesamtlage \u00e4nderte, nahm der Senat endlich Verhandlungen auf und erwirkte ein Abkommen, mit dem Rom sich freikaufen konnte. Der Preis war erwartet hoch: 5000 Pfund Gold, 30.000 Pfund Silber, 4000 Seidengew\u00e4nder und 3000 purpurfarbene Felle sowie 3000 Pfund Pfeffer \u2013 finanziert aus senatorischen Verm\u00f6gen und dem Einschmelzen wertvoller Kunstgegenst\u00e4nde. Alarich hingegen zog sich vorerst nach Etrurien zur\u00fcck. Er hatte reiche Beute gemacht, aber im Ergebnis nichts gewonnen. Denn was sollten seine zahllosen Anh\u00e4nger, die ihrerseits zu hungern drohten, mit purpurfarbenen Fellen und Seidengew\u00e4ndern anfangen?<\/p>\n<p>Alarich setzte weiter auf Verhandlungen, und r\u00f6mische Senatoren versuchten nun, in seinem Sinne beim Kaiser zu vermitteln. Der Gote beanspruchte Geldzahlungen und Versorgungsg\u00fcter f\u00fcr seine Leute, dar\u00fcber hinaus Siedlungsland in Venetien, Noricum und Dalmatien, ferner Stilichos Position als rangh\u00f6chster Feldherr des Reiches. Zudem belasteten die Eifers\u00fcchteleien der Amtstr\u00e4ger im Umfeld des Kaisers die Gespr\u00e4che, und die Hardliner setzten sich durch \u2013 auch dann noch, als Alarich sich zu Konzessionen bereitfand und nur noch Getreide sowie Siedlungsland in Noricum verlangte.<\/p>\n<p>Und wieder zeigte sich, dass die Handlungsm\u00f6glichkeiten begrenzt waren: Mit Pl\u00fcnderungen und Verheerungen lie\u00df sich kein allzu gro\u00dfer Druck mehr aufbauen, da die Ressourcen Italiens inzwischen aufgebraucht waren. Also trat Rom aufgrund seiner hohen symbolischen Bedeutung erneut in den Mittelpunkt des Geschehens. Alarich erhob jetzt den altgl\u00e4ubigen Senator Priscus Attalus zum Kaiser und versuchte dadurch Honorius in die Enge zu treiben. Doch der vermeintliche Marionettenkaiser schmiedete \u00fcberraschend eigene Pl\u00e4ne. Als er dann an Honorius die hochm\u00fctige Forderung, umgehend abzudanken, richtete, diskreditierte er damit auch Alarich f\u00fcr weitere Verhandlungen.<\/p>\n<p>In dieser verfahrenen Situation trafen unerwartet 4000 Soldaten aus dem Osten ein und \u00fcbernahmen die Verteidigung Ravennas; nun musste Alarich handeln: Er setzte den ungl\u00fccklichen Priscus kurzerhand wieder ab, behielt ihn aber unversehrt in seinem Gefolge. Jetzt h\u00e4tte der Weg f\u00fcr eine Wiederaufnahme der Gespr\u00e4che offen gestanden; aber Alarichs alter Rivale Sarus verhinderte alles Weitere, indem er den Gotenverband \u00fcberraschend attackierte und damit jegliche Verhandlungsbereitschaft zerst\u00f6rte.<\/p>\n<p>Und einmal mehr stellte sich die Frage: Was tun? Alarich, der angesichts des mittlerweile monatelangen Stillstands selbst unter massiven Druck seitens der eigenen Anh\u00e4nger geriet, war geradezu gezwungen, in spektakul\u00e4rer Weise zu reagieren, sich selbst als erfolgreicher Heerf\u00fchrer zu inszenieren und vor allem seinen Leuten endlich wieder materielle G\u00fcter in Aussicht zu stellen, nachdem s\u00e4mtliche Hoffnungen auf einen neuen Ansiedlungsvertrag sich nun erst einmal wieder zerschlagen hatten. Am 24. August 410 zogen seine Truppen daher in Rom ein.<\/p>\n<p>Was in den drei Tagen der Pl\u00fcnderung tats\u00e4chlich geschah, wissen wir nicht. Ich m\u00f6chte mich daher an dieser Stelle auch nicht weiter mit Spekulationen \u00fcber den Gang des Eroberungsgeschehens aufhalten; ich m\u00f6chte nicht weiter auf die Verzeichnung des Eroberers als gutm\u00fctig-milder Beschirmer der Stadt eingehen, der Kirchen geschont und sich beim Brandschatzen ma\u00dfvoll geriert haben soll; ich lasse zudem die nachfolgenden Debatten \u00fcber Schuld und Verantwortung aus, die literarische Sch\u00f6pfungen von dauerhafter Geltung hervorgebracht haben (Orosius, Augustinus, Rutilius Namatianus); und ich verzichte darauf, auf die Transformation der Romidee im Kontext des Geschehens einzugehen, auf die Losl\u00f6sung der realen Stadt von ihrer symbolischen Bedeutung, die ihr bis heute erhalten geblieben ist. Stattdessen werfen wir noch einen kurzen Blick auf das Geschehen nach Alarichs Abzug am 27. August und diskutieren abschlie\u00dfend die Frage, warum ich in dem Terwingenf\u00fchrer letztlich einen Getriebenen sehe.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>V.<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>Es ist wohl nicht g\u00e4nzlich verfehlt, in der Einnahme Roms auch ein Eingest\u00e4ndnis des Scheiterns zu sehen. Denn Alarich musste sich bewusst sein, dass er mit dem gewaltsamen Zugriff auf die <em>Urbs<\/em> jegliche Aussicht auf eine Wiederaufnahme von Verhandlungen zunichtemachte; aber er ging diesen Schritt dennoch, und dies zeigt, unter welch enormem Druck er stand und wie gering der Handlungsspielraum war, der sich ihm noch er\u00f6ffnete. Keines seiner langfristigen Ziele hatte er bis dahin erreichen k\u00f6nnen, weder ein hohes Amt noch sichere Ansiedlungsgebiete innerhalb des R\u00f6mischen Reiches; so reichhaltig die Beute auch war, eine Perspektive er\u00f6ffnete sie nicht.<\/p>\n<p>Unter immensem Erwartungsdruck seiner Anh\u00e4nger agierend, war Alarich geradezu in die <em>Urbs <\/em>hineingepresst worden und hatte sich durch seinen Handstreich endg\u00fcltig jeder weiteren Verhandlungsbasis benommen. Vielleicht hatte er den strategischen Wert Roms auch schlicht \u00fcbersch\u00e4tzt. Denn l\u00e4ngst lagen die wahren politischen Brennpunkte, wie eingangs schon angedeutet, an ganz anderen Orten \u2013 in Gallien vor allem, zudem in Britannien und Hispanien, aber auch in Afrika und nat\u00fcrlich auf dem Balkan. Rom aber war f\u00fcr die Regierung tempor\u00e4r verzichtbar.<\/p>\n<p>Und Alarich hatte nun andere Probleme: Seine Leute mussten weiterhin versorgt werden, und Italien war ausgelaugt. Einzig das kornreiche Sizilien oder gar die wohlhabenden Weiten Nordafrikas versprachen jetzt noch kurzfristige Hilfe sowie Gewinne auf l\u00e4ngere Sicht. Und so brachen die Goten bis zur Stra\u00dfe von Messina durch \u2013 und scheiterten an den Herausforderungen ihrer \u00dcberquerung. Man wandte sich nun zun\u00e4chst zur\u00fcck nach Norden und bezog angesichts der einsetzenden Winterk\u00e4lte in S\u00fcditalien Quartier. Da erkrankte Alarich und verstarb unerwartet noch im Jahr seines gr\u00f6\u00dften milit\u00e4rischen Triumphes in Cosentia (heute Cosenza).<\/p>\n<p>Das ist die Geschichte Alarichs, einer der zentralen Identifikationsgestalten sp\u00e4terer Generationen, die teils neidisch, teils nostalgisch auf den Goten als Heroen der V\u00f6lkerwanderungszeit sowie einer \u201edeutschen Fr\u00fchgeschichte\u201c, wie manche die Zeit auch bezeichneten, zur\u00fcckblickten. Bei dieser Verkl\u00e4rung wurde allerdings f\u00fcglich \u00fcbersehen, dass die Einnahme Roms nur in sehr oberfl\u00e4chlicher Betrachtung einen au\u00dferordentlichen politischen Erfolg darstellte. Faktisch bedeutete sie, wie angedeutet, eine politische Bankrotterkl\u00e4rung.<\/p>\n<p>\u00dcberhaupt nimmt sich Alarichs Bilanz auf den ersten Blick au\u00dferordentlich bescheiden aus: Fast jede wichtige Schlacht hat er verloren, allein die Einnahme Roms ist ihm gelungen; zuletzt aber hinterlie\u00df er einen ziellos umherirrenden Verband. Bereits f\u00fcr die meisten Zeitgenossen stellte der hom\u00f6ische Christ offenbar vor allem ein R\u00e4tsel dar; daf\u00fcr steht etwa Orosius mit seinem h\u00f6chst inkonsistenten Alarich-Bild, wenn er den Goten ebenso als Besch\u00fctzer der R\u00f6mer wie als Feind des Imperiums imaginiert. Andernorts findet sich hingegen die Behauptung, der Gotenf\u00fchrer sei von einem D\u00e4mon gegen Rom getrieben worden, und die meisten \u00c4u\u00dferungen ergehen sich in Polemik und Hasstiraden, derart mit konventionellen Barbarenstereotypen aufgeschwemmt, dass sie keinerlei historischen Wert beanspruchen k\u00f6nnen.<\/p>\n<p>Was wir unter all dem aber noch erkennen k\u00f6nnen ist, dass Alarich ein besonderes Charisma besessen haben muss. Dar\u00fcber erfahren wir aus den schriftlichen Zeugnissen allerdings kaum etwas, und dies gilt f\u00fcr seine Pers\u00f6nlichkeit insgesamt. Doch ist offenkundig, dass nur eine Figur von besonderer Durchsetzungsst\u00e4rke in der Lage gewesen sein kann, in den Wirren der Jahre um 400 trotz wiederholter R\u00fcckschl\u00e4ge, trotz teilweise exzeptioneller Verluste und in Konkurrenz zu m\u00f6glichen Alternativen wie Radagaisus oder Sarus den vielfach geplagten Verband nicht nur zusammenzuhalten, sondern auch noch kontinuierlich zu erweitern.<\/p>\n<p>Aber mit welchen Mitteln? Wodurch wurde die Koh\u00e4sion dieses Verbandes \u00fcberhaupt gew\u00e4hrleistet? Und wie hat man sich diesen konkret vorzustellen? Sp\u00e4testens seit dem Jahr 395 f\u00fchrte Alarich den K\u00f6nigstitel \u2013 genauer gesagt: einen Titel, den lateinische Autoren mit dem Terminus <em>rex <\/em>wiedergeben. Das mag sogar der tats\u00e4chlichen Bezeichnung, die Alarich sich zugelegt hatte, entsprochen haben, denn er hat den Titel auf dem Boden des <em>Imperium Romanum <\/em>erworben und musste ihn in irgendeiner Weise verst\u00e4ndlich gegen\u00fcber den R\u00f6mern kommunizieren. Letzteres war mit einem etablierten antiken Terminus nat\u00fcrlich leichter als mit einem weithin unbekannten gotischen Wort.<\/p>\n<p>Zwar wurde dar\u00fcber spekuliert, in welcher Beziehung der lateinische <em>rex <\/em>zu einem gotisch-terwingischen <em>reiks <\/em>gestanden haben mag, doch bleibt hier vieles im Ungewissen. Wir wissen auch nicht, welche konkreten Kompetenzen Alarich dadurch erworben hatte, dass er ab einem bestimmten Zeitpunkt als <em>rex <\/em>auftrat. Und er war auch nicht der einzige gotische <em>rex <\/em>seiner Zeit; Gestalten wie Radagaisus oder gar Sarus erscheinen in unseren Zeugnissen mit derselben Bezeichnung, aber Alarich muss ihnen doch etwas vorausgehabt haben: Er wurde jedenfalls \u2013 dies zeigt das Zeugnis des Olympiodoros \u2013 in einer Position wahrgenommen, die jene anderer <em>reges <\/em>deutlich \u00fcberragt haben muss.<\/p>\n<p>In der Erhebung Alarichs zum K\u00f6nig wird man ein wichtiges Element der (west-)gotischen Ethnogenese vermuten k\u00f6nnen. Der Zusammenhalt der Anh\u00e4ngerschaft Alarichs muss erheblich dadurch gest\u00e4rkt worden sein, dass die Mitglieder der Gruppe nun einen Identifikationspol erhielten, der eine institutionelle Fundierung besa\u00df; dass diese Institutionalisierung bereits unter Alarich einen recht hohen Grad erreicht haben muss, geht aus der Weitergabe des K\u00f6nigstitels an seinen Nachfolger Athaulf hervor; anders als im Fall des Radagaisus zerfiel der Verband n\u00e4mlich nicht nach dem Ende des Anf\u00fchrers, der folglich bereits zu Lebzeiten mehr war als ein ephemerer <em>warlord <\/em>oder Heerk\u00f6nig; Charisma und institutionelle Verankerung als Monarch flossen somit in der Person Alarichs zusammen.\u00a0 Dagegen gibt es keinerlei Anhaltspunkte f\u00fcr die These, dass Alarich das K\u00f6nigtum vor allem deshalb f\u00fcr sich habe beanspruchen k\u00f6nnen, weil er der Familie der Balthen entstammte; wahrscheinlicher ist eher der umgekehrte Prozess: Erst durch die Prominenz Alarichs d\u00fcrfte seine Familie einen besonderen Rang erhalten haben.<\/p>\n<p>Alarichs K\u00f6nigtum hatte wohl nur noch wenig mit der Stellung der terwingischen <em>reiks, <\/em>Unterf\u00fchrer oder Richter, als eine Art zentraler Anf\u00fchrer gemein. Seine F\u00fchrungsposition hatte sich konsequent und ausschlie\u00dflich auf r\u00f6mischem Territorium ausgebildet, und sein Verband entwickelte sich ebenfalls auf dem Gebiet r\u00f6mischer Provinzen von einem Hilfstruppenkontingent unter Theodosius I. hin zu einer bunt gemischten Gro\u00dfgruppe in den Jahren bis 410. Ihr geh\u00f6rten sicherlich nicht nur Goten, sondern auch Barbaren vielf\u00e4ltiger Herkunft sowie r\u00f6mische Provinzialen, entlaufene Sklaven usw. an. Zosimos zufolge soll der Verband zuletzt eine Gr\u00f6\u00dfe von 40.000 Angeh\u00f6rigen erreicht haben, \u00fcber deren soziale Zusammensetzung wir indes nichts wissen.<\/p>\n<p>Jene, die 410 die Ewige Stadt st\u00fcrmten, waren jedenfalls mitnichten s\u00e4mtlich Goten \u2013 und es waren vor allem auch nicht nur kriegf\u00fchrende M\u00e4nner: Aus der r\u00f6mischen Hilfstruppe hatte sich allm\u00e4hlich eine <em>gens <\/em>bzw. <em>natio <\/em>entwickelt, eine heterogene Identit\u00e4tsgruppe, in der unsere modernen Kategorien Armee und Volk zusammenflossen und die ihre innere Koh\u00e4renz vornehmlich durch die Ausrichtung auf den K\u00f6nig gewann. Dessen Position war immerhin derart gefestigt, dass man ihm auch Niederlagen, Misserfolge und eine allgemeine Perspektivlosigkeit \u2013 zumindest bis zum August 410 \u2013 nachsah. Dar\u00fcber hinaus k\u00f6nnten auch weiche Faktoren wie die gotische Sprache und die hom\u00f6ische Liturgie auf Grundlage der Wulfila-Bibel eine identit\u00e4tsstiftende Wirkung entfaltet haben, vielleicht sogar die Tatsache, dass die R\u00f6mer in Alarichs Anh\u00e4ngern die direkten Nachfahren jener Terwingen sahen, die 376 die Donau \u00fcberschritten hatten; m\u00f6glicherweise hatte sich Alarichs Gefolge diese Sichtweise zu eigen gemacht und daraus ein weiteres Argument zur Traditionsbildung und F\u00f6rderung des Zusammenhalts geschmiedet.<\/p>\n<p>Um es noch einmal zu betonen: Dieser Prozess vollzog sich vollst\u00e4ndig auf r\u00f6mischem Boden. Es ist daher grunds\u00e4tzlich verfehlt, den Alarich-Verband als Musterbeispiel f\u00fcr (ein-)wandernde V\u00f6lker anzusehen \u2013 ganz im Gegenteil: Ohne die Mitwirkung Roms h\u00e4tte sich das, was Herwig Wolfram als die \u201ewerdenden Westgoten\u201c bezeichnet hat, nie entwickeln k\u00f6nnen. Aus diesem Grund wird man auch der K\u00f6nigserhebung Alarichs eine doppelte Bedeutung zuweisen m\u00fcssen: Sie festigte den Verband nach innen, symbolisierte aber auch seine Geschlossenheit nach au\u00dfen. Komplement\u00e4r dazu verh\u00e4lt sich Alarichs permanenter Anspruch auf eine hohe Position innerhalb der r\u00f6mischen Milit\u00e4rhierarchie: Ebenso wie das K\u00f6nigtum bewirkte das Amt des <em>magister militum <\/em>eine institutionelle Verfestigung und st\u00e4rkte somit die Koh\u00e4sion der Gemeinschaft.<\/p>\n<p>Gleichzeitig konnte f\u00fcr deren Mitglieder ein Status innerhalb der r\u00f6mischen Welt definiert werden, denn dort bewegte sich ja der Verband: Alarichs Leute wurden nun wie regul\u00e4re Soldaten bezahlt, und der Anf\u00fchrer selbst erhielt Zugang zur h\u00f6chsten politischen B\u00fchne des Reiches. K\u00f6nigtum und <em>magisterium militum <\/em>korrespondierten jedenfalls, ja bedingten einander und konstituierten in ihrer Verzahnung den besonderen Weg, den Alarich im Unterschied zu anderen Barbarenf\u00fchrern eingeschlagen hatte: Er hatte sich nicht einseitig f\u00fcr den Dienst im <em>Imperium Romanum <\/em>entschieden und dabei den Verzicht auf eine F\u00fchrungsposition innerhalb eines barbarischen Kontextes in Kauf genommen; er hatte sich aber auch nicht mit seinem Barbarenverband vollst\u00e4ndig au\u00dferhalb der r\u00f6mischen Strukturen verankert und das Reich lediglich als Reservoir f\u00fcr Pl\u00fcnderungen betrachtet.<\/p>\n<p>Alarichs Position changierte vielmehr zwischen den Strukturen des <em>Imperium Romanum <\/em>(das er nie verlie\u00df) und der Welt des <em>Barbaricum <\/em>(die er wohl nie betrat). Daraus gewann sein Verband eine bis dahin unbekannte Geschlossenheit und innere Koh\u00e4sionskraft, insbesondere mit der Fundierung auf dem Amt des <em>magister militum <\/em>dar\u00fcber hinaus auch eine Vorbildwirkung f\u00fcr sp\u00e4tere Akteure; dem gotischen K\u00f6nig selbst erwuchsen daraus indes zugleich die Ursachen f\u00fcr sein pers\u00f6nliches Scheitern.<\/p>\n<p>Dieses Scheitern resultierte konkret daraus, dass es Alarich bis zuletzt nicht gelang, sich aus der Abh\u00e4ngigkeit vom R\u00f6mischen Reich und seinen Autorit\u00e4ten zu emanzipieren, in die er sich selbst dadurch begeben hatte, dass er sein und seines Verbandes Schicksal an die Erf\u00fcllung seiner Forderungen gekn\u00fcpft hatte. Bis zuletzt blieb ihm die n\u00f6tige Autonomie versagt, um nach einer m\u00f6glichen Landnahme ein auch politisch unabh\u00e4ngiges und milit\u00e4risch hinreichend abgesichertes Gebilde aufzubauen. Selbst im r\u00f6mischen Westen, der im ersten Jahrzehnt des 5. Jahrhunderts eine h\u00f6chst turbulente Phase durchmachte, hatten sich die Strukturen noch nicht so weit gelockert, dass die Etablierung eines unabh\u00e4ngigen gotischen <em>regnum <\/em>m\u00f6glich gewesen w\u00e4re.<\/p>\n<p>Stattdessen wurde Alarich immer wieder zum Spielball der widerstreitenden Machtinteressen politischer Amtstr\u00e4ger im Osten und im Westen degradiert. Dadurch wurde sein Verband zwar mehrfach vor der Vernichtung bewahrt (weil man sein milit\u00e4risches Potential ben\u00f6tigte), aber er verblieb umso mehr in wechselnden Abh\u00e4ngigkeiten, und selbst die Eroberung Roms sollte an dieser Situation zun\u00e4chst nichts \u00e4ndern. Alarich wurde auf diese Weise zum ersten prominenten Opfer des sich zuspitzenden Entfremdungsprozesses zwischen dem r\u00f6mischen Westen und dem r\u00f6mischen Osten; nicht nur sein Pendeln zwischen gentilen und r\u00f6mischen Strukturen wurde ihm also zum Verh\u00e4ngnis, sondern vor allem sein innerr\u00f6misches Changieren zwischen den Reichsteilen, seine mangelnde interne Festlegung.<\/p>\n<p>So kann man abschlie\u00dfend res\u00fcmieren, dass ausgerechnet Alarich, der vielfach als Inbegriff des germanischen Heldenk\u00f6nigs der V\u00f6lkerwanderungszeit, ja sogar als fr\u00fcher Exponent des \u201eGedanken[s] eines r\u00f6mischen Reiches deutscher Nation\u201c gilt, in jeder Hinsicht ein Produkt r\u00f6mischer Politik und r\u00f6mischer Strukturen war (auch wenn er sie partiell aufbrach) \u2013 beginnend mit seiner Funktion als untergeordneter Anf\u00fchrer eines barbarischen Truppenkontingents \u00fcber seine zahllosen Anl\u00e4ufe, eine feste Einbindung in die r\u00f6mische Milit\u00e4rhierarchie zu erreichen, bis hin zu seiner Einsetzung eines r\u00f6mischen Usurpators und zum Ausspielen seiner letzten, allerdings weit \u00fcbersch\u00e4tzten Trumpfkarte in Gestalt der Ewigen Stadt Rom.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I. &nbsp; Am 24. August 410 war es dem terwingischen Goten Alarich gelungen, in das Zentrum der antiken Welt einzudringen; drei Tage pl\u00fcnderten seine Truppen die Tiberstadt, bevor sie sich am 27. August in Richtung S\u00fcden zur\u00fcckzogen. Bis heute wird dar\u00fcber ger\u00e4tselt, wie es so weit hatte kommen k\u00f6nnen; bereits direkt nach dem Fall der&hellip;<\/p>","protected":false},"author":5,"featured_media":32556,"menu_order":636,"template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"class_list":["post-104411","media-library","type-media-library","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alarich I. Karriere eines Getriebenen - Katholische Akademie in Bayern<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kath-akademie-bayern.de\/en\/mediathek-eintrag\/alarich-i-karriere-eines-getriebenen\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alarich I. Karriere eines Getriebenen - Katholische Akademie in Bayern\" \/>\n<meta property=\"og:description\" content=\"I. &nbsp; Am 24. August 410 war es dem terwingischen Goten Alarich gelungen, in das Zentrum der antiken Welt einzudringen; drei Tage pl\u00fcnderten seine Truppen die Tiberstadt, bevor sie sich am 27. August in Richtung S\u00fcden zur\u00fcckzogen. Bis heute wird dar\u00fcber ger\u00e4tselt, wie es so weit hatte kommen k\u00f6nnen; bereits direkt nach dem Fall der&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kath-akademie-bayern.de\/en\/mediathek-eintrag\/alarich-i-karriere-eines-getriebenen\/\" \/>\n<meta property=\"og:site_name\" content=\"Katholische Akademie in Bayern\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/katholische.akademie.bayern\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-29T07:30:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kath-akademie-bayern.de\/wp-content\/uploads\/Geschichte.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"872\" \/>\n\t<meta property=\"og:image:height\" content=\"490\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"32 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/mediathek-eintrag\\\/alarich-i-karriere-eines-getriebenen\\\/\",\"url\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/mediathek-eintrag\\\/alarich-i-karriere-eines-getriebenen\\\/\",\"name\":\"Alarich I. Karriere eines Getriebenen - Katholische Akademie in Bayern\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/mediathek-eintrag\\\/alarich-i-karriere-eines-getriebenen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/mediathek-eintrag\\\/alarich-i-karriere-eines-getriebenen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/wp-content\\\/uploads\\\/Geschichte.jpg\",\"datePublished\":\"2025-04-28T13:39:28+00:00\",\"dateModified\":\"2025-04-29T07:30:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/mediathek-eintrag\\\/alarich-i-karriere-eines-getriebenen\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kath-akademie-bayern.de\\\/mediathek-eintrag\\\/alarich-i-karriere-eines-getriebenen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/mediathek-eintrag\\\/alarich-i-karriere-eines-getriebenen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/wp-content\\\/uploads\\\/Geschichte.jpg\",\"contentUrl\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/wp-content\\\/uploads\\\/Geschichte.jpg\",\"width\":872,\"height\":490},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/mediathek-eintrag\\\/alarich-i-karriere-eines-getriebenen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alarich I. Karriere eines Getriebenen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/#website\",\"url\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/\",\"name\":\"Katholische Akademie in Bayern\",\"description\":\"Kirche braucht Debatte: \u201ekatholisch\u201c mit Blick auf das Ganze \u2013 und \u201eakademisch\u201c im Vertrauen auf die Kraft der Argumente\",\"publisher\":{\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/#organization\",\"name\":\"Katholische Akademie in Bayern\",\"url\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/wp-content\\\/uploads\\\/Menue-Logo-Home@2x.png\",\"contentUrl\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/wp-content\\\/uploads\\\/Menue-Logo-Home@2x.png\",\"width\":496,\"height\":216,\"caption\":\"Katholische Akademie in Bayern\"},\"image\":{\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/katholische.akademie.bayern\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alarich I. Karriere eines Getriebenen - Katholische Akademie in Bayern","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kath-akademie-bayern.de\/en\/mediathek-eintrag\/alarich-i-karriere-eines-getriebenen\/","og_locale":"en_GB","og_type":"article","og_title":"Alarich I. Karriere eines Getriebenen - Katholische Akademie in Bayern","og_description":"I. &nbsp; Am 24. August 410 war es dem terwingischen Goten Alarich gelungen, in das Zentrum der antiken Welt einzudringen; drei Tage pl\u00fcnderten seine Truppen die Tiberstadt, bevor sie sich am 27. August in Richtung S\u00fcden zur\u00fcckzogen. Bis heute wird dar\u00fcber ger\u00e4tselt, wie es so weit hatte kommen k\u00f6nnen; bereits direkt nach dem Fall der&hellip;","og_url":"https:\/\/kath-akademie-bayern.de\/en\/mediathek-eintrag\/alarich-i-karriere-eines-getriebenen\/","og_site_name":"Katholische Akademie in Bayern","article_publisher":"https:\/\/www.facebook.com\/katholische.akademie.bayern\/","article_modified_time":"2025-04-29T07:30:54+00:00","og_image":[{"width":872,"height":490,"url":"https:\/\/kath-akademie-bayern.de\/wp-content\/uploads\/Geschichte.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"32 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kath-akademie-bayern.de\/mediathek-eintrag\/alarich-i-karriere-eines-getriebenen\/","url":"https:\/\/kath-akademie-bayern.de\/mediathek-eintrag\/alarich-i-karriere-eines-getriebenen\/","name":"Alarich I. Karriere eines Getriebenen - Katholische Akademie in Bayern","isPartOf":{"@id":"https:\/\/kath-akademie-bayern.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kath-akademie-bayern.de\/mediathek-eintrag\/alarich-i-karriere-eines-getriebenen\/#primaryimage"},"image":{"@id":"https:\/\/kath-akademie-bayern.de\/mediathek-eintrag\/alarich-i-karriere-eines-getriebenen\/#primaryimage"},"thumbnailUrl":"https:\/\/kath-akademie-bayern.de\/wp-content\/uploads\/Geschichte.jpg","datePublished":"2025-04-28T13:39:28+00:00","dateModified":"2025-04-29T07:30:54+00:00","breadcrumb":{"@id":"https:\/\/kath-akademie-bayern.de\/mediathek-eintrag\/alarich-i-karriere-eines-getriebenen\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kath-akademie-bayern.de\/mediathek-eintrag\/alarich-i-karriere-eines-getriebenen\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/kath-akademie-bayern.de\/mediathek-eintrag\/alarich-i-karriere-eines-getriebenen\/#primaryimage","url":"https:\/\/kath-akademie-bayern.de\/wp-content\/uploads\/Geschichte.jpg","contentUrl":"https:\/\/kath-akademie-bayern.de\/wp-content\/uploads\/Geschichte.jpg","width":872,"height":490},{"@type":"BreadcrumbList","@id":"https:\/\/kath-akademie-bayern.de\/mediathek-eintrag\/alarich-i-karriere-eines-getriebenen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/kath-akademie-bayern.de\/"},{"@type":"ListItem","position":2,"name":"Alarich I. Karriere eines Getriebenen"}]},{"@type":"WebSite","@id":"https:\/\/kath-akademie-bayern.de\/#website","url":"https:\/\/kath-akademie-bayern.de\/","name":"Catholic Academy in Bavaria","description":"Church needs debate: \"catholic\" looking at the whole - and \"academic\" trusting in the power of arguments","publisher":{"@id":"https:\/\/kath-akademie-bayern.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kath-akademie-bayern.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/kath-akademie-bayern.de\/#organization","name":"Catholic Academy in Bavaria","url":"https:\/\/kath-akademie-bayern.de\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/kath-akademie-bayern.de\/#\/schema\/logo\/image\/","url":"https:\/\/kath-akademie-bayern.de\/wp-content\/uploads\/Menue-Logo-Home@2x.png","contentUrl":"https:\/\/kath-akademie-bayern.de\/wp-content\/uploads\/Menue-Logo-Home@2x.png","width":496,"height":216,"caption":"Katholische Akademie in Bayern"},"image":{"@id":"https:\/\/kath-akademie-bayern.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/katholische.akademie.bayern\/"]}]}},"_links":{"self":[{"href":"https:\/\/kath-akademie-bayern.de\/en\/wp-json\/wp\/v2\/media-library\/104411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kath-akademie-bayern.de\/en\/wp-json\/wp\/v2\/media-library"}],"about":[{"href":"https:\/\/kath-akademie-bayern.de\/en\/wp-json\/wp\/v2\/types\/media-library"}],"author":[{"embeddable":true,"href":"https:\/\/kath-akademie-bayern.de\/en\/wp-json\/wp\/v2\/users\/5"}],"version-history":[{"count":1,"href":"https:\/\/kath-akademie-bayern.de\/en\/wp-json\/wp\/v2\/media-library\/104411\/revisions"}],"predecessor-version":[{"id":104412,"href":"https:\/\/kath-akademie-bayern.de\/en\/wp-json\/wp\/v2\/media-library\/104411\/revisions\/104412"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kath-akademie-bayern.de\/en\/wp-json\/wp\/v2\/media\/32556"}],"wp:attachment":[{"href":"https:\/\/kath-akademie-bayern.de\/en\/wp-json\/wp\/v2\/media?parent=104411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}