{"id":117997,"date":"2026-01-19T14:09:56","date_gmt":"2026-01-19T13:09:56","guid":{"rendered":"https:\/\/kath-akademie-bayern.de\/?post_type=media-library&#038;p=117997"},"modified":"2026-01-19T14:09:56","modified_gmt":"2026-01-19T13:09:56","slug":"paulus-vier-spotlights-auf-eine-vielschichtige-persoenlichkeit","status":"publish","type":"media-library","link":"https:\/\/kath-akademie-bayern.de\/en\/mediathek-eintrag\/paulus-vier-spotlights-auf-eine-vielschichtige-persoenlichkeit\/","title":{"rendered":"Paul - four spotlights on a multi-layered personality"},"content":{"rendered":"<h3><strong> Ein \u201einterkultureller\u201c Jude<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>Als nach Darstellung der Apostelgeschichte Paulus bei seinem letzten Aufenthalt in Jerusalem im Tempelreich von r\u00f6mischen Soldaten verhaftet wird, stellt er sich dem Oberst in griechischer Sprache so vor: \u201eIch bin ein Jude, aus Tarsus in Zilizien stammend, B\u00fcrger einer nicht unbedeutenden Stadt\u201c (Apg 21,39). Und wenig sp\u00e4ter \u2013 so wei\u00df der Historiograph Lukas zu erz\u00e4hlen \u2013 beginnt Paulus seine Verteidigungsrede vor den im Tempelbereich anwesenden j\u00fcdischen M\u00e4nnern, jetzt allerdings in hebr\u00e4ischer Sprache, mit ganz \u00e4hnlichen Worten: \u201eIch bin ein Jude, geboren in Tarsus in Zilizien\u201c (Apg 22,3a). Damit liefert Lukas hier zwei interessante Informationen: 1. Paulus ist ein Diasporajude aus Tarsus, der Hauptstadt der r\u00f6mischen Provinz Cilicia. Und 2. Paulus spricht nicht nur Griechisch, wie bei einem Diasporajuden selbstverst\u00e4ndlich zu erwarten ist, sondern er ist offenbar auch des Hebr\u00e4ischen (beziehungsweise des Aram\u00e4ischen) flie\u00dfend m\u00e4chtig.<\/p>\n<p>Blenden wir freilich f\u00fcr einen Moment die Informationen der Apostelgeschichte aus und beschr\u00e4nken uns auf die sporadischen autobiographischen Bemerkungen von Paulus selbst in seinen Briefen, so bietet sich auf den ersten Blick ein anderes Bild.<\/p>\n<p>In 2 Kor 11,22 vergleicht sich Paulus hinsichtlich seiner Herkunft mit rivalisierenden Verk\u00fcndigern, die in die korinthische Gemeinde eingedrungen sind. Jetzt wollen sie, die Paulus ironisch als \u201eSuperapostel\u201c (11,5) und abwertend als \u201ePseudoapostel\u201c und \u201ebetr\u00fcgerische Arbeiter\u201c (11,13) bezeichnen, offenbar gegen ihn als den Gemeindegr\u00fcnder punkten. Dazu betonen sie wohl unter anderem auch ihre geographische, kulturelle und religi\u00f6se Verwurzelung im j\u00fcdischen Mutterland. Jedenfalls weist Paulus die korinthische Gemeinde selbstbewusst darauf hin, dass er seinen Konkurrenten in dieser Hinsicht durchaus das Wasser reichen kann: \u201eSie sind Hebr\u00e4er? Ich auch! Sie sind Israeliten? Ich auch! Sie sind Nachkommen Abrahams? Ich auch!\u201c (11,22).<\/p>\n<p>Ganz \u00e4hnlich \u00e4u\u00dfert er sich im Philipperbrief. Erneut steht das Wirken rivalisierender Verk\u00fcndiger im Hintergrund, gegen deren Einfluss Paulus die Gemeinde in Philippi immunisieren will (Phil 3,2-16) und die er daher gleich zu Beginn seiner Invektive als \u201eHunde\u201c und \u201eb\u00f6se Arbeiter\u201c disqualifiziert (3,2). Deutlicher als in 2 Kor aber wird hier, dass es sich bei diesen Konkurrenten um toraobservante christusgl\u00e4ubige Juden handelt, denen die beschneidungsfreie paulinische Verk\u00fcndigung unter den Heiden ein Dorn im Auge ist. Wahrscheinlich stammten sie aus Jerusalem beziehungsweise Jud\u00e4a, also aus dem j\u00fcdischen Mutterland. Und wie in Korinth scheinen auch diese rivalisierenden Verk\u00fcndiger ihre pal\u00e4stina-j\u00fcdische Identit\u00e4t als Vorzug gegen\u00fcber Paulus pr\u00e4sentiert zu haben. Kaum zuf\u00e4llig n\u00e4mlich schreibt er in 3,4b-5: \u201eWenn irgendein anderer meint, auf das Fleisch (meint: irdische Faktoren) vertrauen zu k\u00f6nnen, k\u00f6nnte ich das noch viel mehr: Am 8. Tag beschnitten, aus dem Volk Israel, vom Stamm Benjamin, Hebr\u00e4er von Hebr\u00e4ern.\u201c<\/p>\n<p>Betrachtet man nun die Informationen, die Paulus selbst in 2 Kor 11,22 und Phil 3,5 zu seiner Herkunft bietet, losgel\u00f6st vom brieflichen Kontext, so besteht scheinbar ein deutlicher Widerspruch zu den Informationen der Apg. Denn als \u201eHebr\u00e4er\u201c (2 Kor 11,22) und sogar als \u201eHebr\u00e4er von Hebr\u00e4ern\u201c (Phil 3,5) ordnet sich Paulus seiner Herkunft nach explizit dem j\u00fcdischen Mutterland und nicht der Diaspora zu. Unter Ber\u00fccksichtigung aber der jeweils apologetischen Einbindung bieten seine \u00c4u\u00dferungen sogar eine implizite Best\u00e4tigung daf\u00fcr, dass seine Rivalen ihn als Diasporajuden einstuften. Und dass sie damit durchaus richtig lagen, gibt Paulus ebenfalls selbst unausgesprochen durch seine Briefe zu erkennen. So weist ihn seine hohe griechische Sprachkompetenz als \u201enative speaker\u201c aus. Zudem greift er dort, wo er die Heiligen Schriften Israels bem\u00fcht, wie selbstverst\u00e4ndlich auf die Septuaginta zur\u00fcck, also auf die prominenteste Bibelversion der Diasporajuden. Und nicht zuletzt verbringt er die erste Phase seiner Verk\u00fcndigungst\u00e4tigkeit \u2013 noch ganz auf sich gestellt \u2013 nach eigener Auskunft in Syrien und Zilizien (Gal 1,21-23), also aus j\u00fcdischer Sicht in der Diaspora. Dies aber d\u00fcrfte nicht nur seiner \u00dcberzeugung geschuldet sein, einen g\u00f6ttlichen Auftrag zur Verk\u00fcndigung unter den Heiden erhalten zu haben (Gal 1,16). Betrachtet man n\u00e4mlich die Wahl seines ersten Bet\u00e4tigungsfeldes im Licht der Information \u00fcber seine Herkunft aus Tarsus in Zilizien, die Lukas bietet (Apg 21,39; 22,3a), so wird sie leicht nachvollziehbar: Paulus macht die ersten, vorsichtigen Gehversuche als Verk\u00fcndiger in einem Umfeld, das ihm geographisch, kulturell und religi\u00f6s von Kindheit an vertraut ist.<\/p>\n<p>Die Indizien sind also erdr\u00fcckend, dass Paulus tats\u00e4chlich in der Diaspora geboren und aufgewachsen ist. Trotzdem bezeichnet er sich zweimal explizit in seinen Briefen als \u201eHebr\u00e4er (von Hebr\u00e4ern)\u201c (2 Kor 11,22; Phil 3,5). Wollte er seinen Rivalen in Korinth und Philippi damit nicht ins offene Messer laufen, kann dies nur bedeuten: Die Vorfahren des Paulus stammten urspr\u00fcnglich aus dem j\u00fcdischen Mutterland, und das Wissen darum wurde in seiner Familie offenbar auch wachgehalten. Oder anders gesagt: Die Familie des Paulus pflegte bewusst ihre pal\u00e4stina-j\u00fcdischen Wurzeln und die daraus erwachsende Identit\u00e4t.<\/p>\n<p>Paulus lernt also von Kindesbeinen an eine hellenistisch gepr\u00e4gte st\u00e4dtische Kultur einer r\u00f6mischen Provinz in der \u00f6stlichen Reichsh\u00e4lfte kennen. Seine schulische Grundausbildung erh\u00e4lt er als Sohn j\u00fcdischer Eltern innerhalb des hellenistisch-j\u00fcdischen Bildungswesens. Angesichts der in seiner Familie hochgehaltenen Erinnerung an ihre pal\u00e4stina-j\u00fcdische Herkunft hat Paulus aber wohl auch schon fr\u00fch Hebr\u00e4isch und\/oder Aram\u00e4isch gelernt. Jedenfalls geht er als junger Mann \u2013 wahrscheinlich best\u00e4rkt durch seine Familie \u2013 in die Heimat seiner Vorfahren. Daf\u00fcr spricht ganz entschieden, dass Paulus sich in Phil 3,5 nicht nur als \u201eHebr\u00e4er von Hebr\u00e4ern\u201c bezeichnet, sondern sofort darauf als \u201edem Gesetz(esverst\u00e4ndnis) nach Pharis\u00e4er\u201c. Durch seine differenzierte Formulierung stellt er hier klar: Er stammt zwar aus einem Elternhaus mit pal\u00e4stina-j\u00fcdischen Wurzeln, jedoch nicht aus einem pharis\u00e4isch gepr\u00e4gten Elternhaus. Vielmehr verdankt sich sein Anschluss an das pharis\u00e4ische Gesetzesverst\u00e4ndnis seiner eigenen Entscheidung. Doch diese Entscheidung war nur im j\u00fcdischen Mutterland realisierbar. Denn die zahlreichen rituell-kultischen Bestimmungen des Alltagslebens, auf die ein Pharis\u00e4er gem\u00e4\u00df seinem Gesetzesverst\u00e4ndnis verpflichtet war, lie\u00dfen sich nur in einem j\u00fcdisch gepr\u00e4gten Wirtschaftsraum, konkret vor allem in der Tempelstadt Jerusalem, erf\u00fcllen.<\/p>\n<p>Mit seinem Entschluss, sich der Gruppe der Pharis\u00e4er anzuschlie\u00dfen, distanzierte sich Paulus zugleich von der ihm vertrauten hellenistischen Kultur. Diese hatte seit Beginn der ptolem\u00e4ischen und seleukidischen Vorherrschaft ab dem 4. Jahrhundert vor Christus zunehmend auch Einfluss in Pal\u00e4stina gehalten. Doch es war ein religi\u00f6s motivierter Kreis von \u201eFrommen\u201c (Chassidim), der sich den Ver\u00e4nderungen durch die Kultur des Hellenismus von Anfang an widersetzte. Aus diesem Kreis der Chassidim bildeten sich im Laufe der Zeit verschiedene religi\u00f6se Gruppen heraus, wie etwa die Pharis\u00e4er. Sie bildeten auch im 1. Jahrhundert nach Christus noch ein Gegengewicht gegen die unter der Vorherrschaft der R\u00f6mer und ihren j\u00fcdischen Klientelf\u00fcrsten weiter fortschreitende Hellenisierung des j\u00fcdischen Mutterlandes. Indem sich Paulus den Pharis\u00e4ern anschloss, tauchte er also in eine f\u00fcr ihn als Diasporajuden bisher unbekannte, ganz und gar von der Tora beziehungsweise einem spezifischen Toraverst\u00e4ndnis bestimmte kulturelle Welt ein.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Vom gewaltbereiten Fundamentalisten zum Apostel Christi Jesu<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>W\u00e4hrend seiner pharis\u00e4ischen Phase, die Paulus wohl haupts\u00e4chlich in Jerusalem verbrachte (Apg 22,3b), entwickelt er sich einerseits zum gewaltbereiten Fundamentalisten und trifft andererseits auf christusgl\u00e4ubige Juden, die die Auswirkungen seiner religi\u00f6sen Radikalisierung zu sp\u00fcren bekommen. Diese Phase spricht Paulus selbst in Phil (3,5f) und ausf\u00fchrlicher noch im Galaterbrief an. In Gal 1,13f blendet er zu Beginn des umfangreichen autobiographischen Briefabschnitts (1,13-2,21) in die Lebensphase zur\u00fcck, die seiner Annahme des Christusglaubens unmittelbar vorausging. Dabei stellt er sie unter die \u00dcberschrift \u201eMein Wandel einst im Judentum\u201c (V. 13a). Diesen Wandel thematisiert Paulus zun\u00e4chst hinsichtlich seiner geradezu fanatischen (\u201e\u00fcber die Ma\u00dfen\u201c) Verfolgung der Christusgl\u00e4ubigen (V. 13b), bei denen es sich in dieser fr\u00fchnach\u00f6sterlichen Zeit in Jerusalem durchweg um christusgl\u00e4ubige Juden handelte. Wenn Paulus daher von seinem \u201eWandel im Judentum\u201c spricht, meint er also seine theologisch-religi\u00f6se Orientierung innerhalb des pluralen, fr\u00fchen Judentums. Darin aber unterschied er sich so stark von den christusgl\u00e4ubigen Juden, dass er sie zu vernichten trachtete.<\/p>\n<p>Wenngleich Paulus sich in Gal 1,13f anders als in Phil 3,5 nicht explizit als Pharis\u00e4er bezeichnet, gibt er sich doch implizit als solcher zu erkennen. Denn er erw\u00e4hnt die \u201e\u00dcberlieferungen seiner V\u00e4ter\u201c, also die m\u00fcndliche Tradition, die f\u00fcr Pharis\u00e4er unter dem Kriterium der Offenbarungsqualit\u00e4t dieselbe W\u00fcrde besa\u00df wie die schriftliche Tora. Doch pr\u00e4zisiert Paulus seine Information noch, indem er sich einen \u201eEiferer (gr. z\u0113l\u014dt\u0113s) im \u00dcberma\u00df\u201c f\u00fcr diese v\u00e4terlichen \u00dcberlieferungen nennt (V. 14). Damit aber outet er sich als Sympathisant des radikalen zelotischen Fl\u00fcgels der Pharis\u00e4er. Der Eifer dieser Splittergruppe richtete sich auf das strikte Einhalten des j\u00fcdischen Religionsgesetzes pharis\u00e4ischer Lesart, und nach dem Vorbild des Pinhas (Num 25) waren ihre Mitglieder bereit, ihr Ziel auch gewaltsam durchzusetzen. Paulus bezeugt in Gal 1,13f nun selbst, dass sich seine zelotische Gewaltbereitschaft gegen christusgl\u00e4ubige Juden wendete. Das aber impliziert: Er warf den Anh\u00e4ngern des Messias Jesus von Nazaret Abfall vom j\u00fcdischen Religionsgesetz vor.<\/p>\n<p>Mitten hinein in diese Phase seines fanatischen Gesetzeseifers trifft Paulus nun nach eigenem Bekunden eine Offenbarung Gottes (Gal 1,15f). Sie hat Gottes Sohn zum Inhalt, und zwar verbunden mit dem Auftrag, ihn als Evangelium unter den Heiden zu verk\u00fcnden. Im scharfen Kontrast zu seiner bisherigen \u00dcberzeugung gelangt Paulus jetzt also zur Gewissheit: Der ihm als Sohn Gottes offenbarte Jesus Christus (Gal 1,12) ist in Person das Evangelium, also die Heilsbotschaft. Dadurch sieht er sich gezwungen, den neuralgischen Punkt zu akzeptieren, der ihn als pharis\u00e4ischen Eiferer Gewalt gegen christusgl\u00e4ubige Juden \u00fcben lie\u00df, n\u00e4mlich: In Jesus Christus kommt die Heilsfunktion der Tora an ihr Ende und ihr Ziel (R\u00f6m 10,4). Die logische Schlussfolgerung daraus war f\u00fcr ihn, Jesus Christus als Evangelium dem g\u00f6ttlichen Auftrag gem\u00e4\u00df unter den Heiden zu verk\u00fcnden \u2013 und zwar ohne deren Verpflichtung auf das j\u00fcdische Religionsgesetz.<\/p>\n<p>Bis Paulus entsprechend seiner Beauftragung mit der Verk\u00fcndigungsarbeit unter den Heiden beginnt, vergehen allerdings noch rund zwei Jahre (Gal 1,16-23). Diese Zeit brauchte er wohl, um seinen theologischen \u201eKompass\u201c im Licht seines Offenbarungserlebnisses neu auszurichten. W\u00e4hrend der ersten Verk\u00fcndigungsphase in Syrien und Zilizien st\u00f6\u00dft er dann zur Gemeinde im syrischen Antiochia, wo er f\u00fcr sein Projekt der auflagenfreien (keine Beschneidung; keine Verpflichtung auf die Kulttora) Heidenmission auf Gleichgesinnte trifft (Apg 11,19-26) und Mitglied im Gemeindeleitungsteam wird (Apg 13,1f). In Anbindung an die antiochenische Gemeinde setzt Paulus gemeinsam mit Barnabas bei der Jerusalemer Gemeindeleitung durch, dass christusgl\u00e4ubig gewordene Heiden nicht zum Judentum konvertieren m\u00fcssen (Gal 2,1-10; Apg 15,1-19). In zun\u00e4chst engerer, dann loserer Anbindung an die antiochenische Gemeinde erzielt Paulus auf zwei Missionsreisen mit Barnabas und Johannes Markus (Apg 13,1-14,28) beziehungsweise mit Silas und Timotheus (Apg 15,40-18,22) beachtliche Missionserfolge unter den Heiden. Doch dann gibt die Gruppe christusgl\u00e4ubiger Juden in Antiochia zun\u00e4chst dem Dr\u00e4ngen konservativer Jerusalemer Kreise um Jakobus nach und beendet dem Beispiel des Petrus folgend die Tischgemeinschaft mit den Gemeindemitgliedern heidnischer Herkunft (Gal 2,11-13). Wenig sp\u00e4ter akzeptiert sie einen Kompromiss, den Lukas in der Darstellung von Apg 15,20.29 \u2013 einem breiten Forschungskonsens nach historisch unzutreffend \u2013 bereits beim Jerusalemer Aposteltreffen verankert. Dieser Kompromiss (in der Fachwelt Jakobusklauseln genannt) erwartet von den Heidenchristen die Beachtung bestimmter ritueller Mindeststandards als Vorbedingung f\u00fcr eine Tischgemeinschaft mit christusgl\u00e4ubigen Juden. Der grunds\u00e4tzliche Verzicht auf eine Beschneidungsforderung und eine Verpflichtung auf die gesamte Kulttora steht dabei keinesfalls zur Debatte. Paulus jedoch zeigt sich nicht kompromissbereit. Denn f\u00fcr ihn stellen die geforderten Mindeststandards bereits ein Einfallstor f\u00fcr \u201edie Werke des Gesetzes\u201c dar, unterminieren also die alleinige Heilsfunktion Christi. Mit dieser Sichtweise steht er offenkundig unter den christusgl\u00e4ubigen Juden Antiochias isoliert dar. Konsequent bricht er daher die Verbindung zur dortigen Gemeinde ab.<\/p>\n<p>W\u00e4hrend seiner anschlie\u00dfenden dritten Missionsreise (52-56) bekommt Paulus den Druck konservativ-toraobservanter Judenchristen noch st\u00e4rker zu sp\u00fcren. Wenn die Anzeichen nicht tr\u00fcgen, setzt um die Mitte der 50er Jahre eine gezielte \u201eNachmissionierung\u201c dieser Gruppe in den von Paulus gegr\u00fcndeten heidenchristlichen Gemeinden ein. Am unmittelbarsten greifbar werden ihr Wirken und ihre Zielsetzung im Galaterbrief. Im offenkundigen Widerspruch zu der einige Jahre zuvor in Jerusalem getroffenen Vereinbarung (Gal 2,1-10; Apg 15,1-19) fordern die \u201eKonkurrenzverk\u00fcndiger\u201c, die den damals unterlegenen toraoberservanten Kreisen theologisch nahe gestanden haben d\u00fcrften, von den galatischen Heidenchristen sich beschneiden zu lassen (Gal 6,12f). Die Beschneidung aber impliziert Verpflichtung auf die Tora, und daf\u00fcr steht exemplarisch die Beachtung eines aus der Tora abgeleiteten und an den Gestirnen orientierten Festkalenders (Gal 4,8-10). Doch nicht nur in Galatien, auch in Philippi (3,2-11) und Korinth (2 Kor 11,4 mit Gal 1,6-9) haben die konservativ-judenchristlichen Rivalen des Paulus offenbar versucht, die Gemeinden von der Heilsinsuffizienz seiner auflagenfreien Evangeliumsverk\u00fcndigung zu \u00fcberzeugen. Paulus nimmt die Herausforderung an und stellt sich dem Kampf um seine Gemeinden. Denn er ist sich gewiss: Die erfolgreiche Verteidigung des ihm von Gott selbst anvertrauten, authentischen Evangeliums (Gal 1,11f. 15f) entscheidet gleicherma\u00dfen \u00fcber das Heil der christusgl\u00e4ubig gewordenen Heiden wie \u00fcber seine Glaubw\u00fcrdigkeit als Apostel Christi. Wie schon zuvor beim antiochenischen Zwischenfall, so blitzt auch jetzt erneut die kompromisslose Entschiedenheit des einstigen zelotisch-pharis\u00e4ischen Fundamentalisten in der Frage hervor, die den Dreh- und Angelpunkt seiner theologischen \u00dcberzeugung bildet. Anders freilich als zuvor der pharis\u00e4ische Paulus f\u00fchrt der christusgl\u00e4ubige Paulus jetzt seinen Kampf ohne Gewalt gegen die Andersdenkenden.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Verk\u00fcndiger mit Managerqualit\u00e4ten<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>Paulus war ein urbaner Mensch. Die meiste Zeit seines Lebens verbrachte er in st\u00e4dtischen Zentren, die nach antiken Ma\u00dfst\u00e4ben Gro\u00dfst\u00e4dte waren. Selbst sein R\u00fcckzug in die Arabia unmittelbar nach seinem Offenbarungserlebnis (Gal 1,17) bildet keine Ausnahme. Denn in der Arabia waren bedeutende hellenistische St\u00e4dte gelegen, die Handelszentren der Nabat\u00e4er bildeten.<\/p>\n<p>Diese Urbanit\u00e4t bestimmte auch das missionarische Wirken des Paulus. Er machte sich die gesellschaftlichen, \u00f6konomischen und kulturellen Strukturen hellenistischer St\u00e4dte, die ihm seit jeher vertraut waren, zunutze, um Gemeinden zu gr\u00fcnden und sie auf eine funktionierende infrastrukturelle Basis stellen zu k\u00f6nnen. Sein planvoll-strategisches Vorgehen h\u00e4tte dabei jedem modernen Manager Ehre gemacht. So suchte sich Paulus, wenn er in einer Stadt zu verk\u00fcndigen begann, seine ersten Ansprechpartner unter den gottesf\u00fcrchtigen Heiden im Umfeld der st\u00e4dtischen Diasporasynagogen. Diese heidnischen Sympathisanten des j\u00fcdischen Glaubens geh\u00f6rten nicht zu den \u00e4rmsten Schichten der st\u00e4dtischen Bev\u00f6lkerung. Sie verdienten ihren Lebensunterhalt nicht selten durch Handwerk und\/oder Handel. Damit verbunden standen sie in der Regel auch einem Hauswesen vor, das gem\u00e4\u00df den zeitgen\u00f6ssischen sozialen und \u00f6konomischen Strukturen eine komplexe Lebens- und Produktionsgemeinschaft mit entsprechendem Geb\u00e4ude bildete. Wenn es Paulus gelang, einige solcher Hausvorst\u00e4nde f\u00fcr seine Botschaft zu gewinnen, war damit die Keimzelle f\u00fcr eine neue Gemeinde von Christusgl\u00e4ubigen gegeben. Denn erstens war es angesichts der religi\u00f6s-kultischen Dimension einer antiken Hausgemeinschaft wahrscheinlich, dass auch die \u00fcbrigen Mitglieder des Hauses fr\u00fcher oder sp\u00e4ter den Christusglauben annahmen; und zweitens boten die H\u00e4user die infrastrukturelle Basis in r\u00e4umlicher, finanzieller und personeller Hinsicht, um eine Gemeindeorganisation aufzubauen. So ist es alles andere als Zufall, dass gerade namentlich genannte Gemeindemitglieder verschiedentlich mit ihrem Hauswesen beziehungsweise dessen Einsatz f\u00fcr die Gemeinde erw\u00e4hnt werden (vgl. etwa Stephanas: 1 Kor 1,16; 16,15-18; Gaius: 1 Kor 1,14; R\u00f6m 16,23; Priska und Aquila: 1 Kor 16,19; R\u00f6m 16,3-5). Wichtig war aber auch der Faktor der Mobilit\u00e4t dieser f\u00fcr den Erfolg der paulinischen Verk\u00fcndigung entscheidenden Zielgruppe. Denn gerade die Vermarktung von Waren au\u00dferhalb der eigenen Stadt erm\u00f6glichte den Hausvorst\u00e4nden oder anderen Hausangeh\u00f6rigen, auf ihren Reisen Kurierdienste in Gemeindeangelegenheiten und\/oder f\u00fcr Paulus zu \u00fcbernehmen (etwa Stephanas: 1 Kor 16,17f; Phoebe: R\u00f6m 16,1f). Nicht zuletzt kam die Mobilit\u00e4t dieser Gemeindemitglieder auch der Verbreitung des Evangeliums zugute (etwa 1Thess 1,8). Die gerade unter dem Vorzeichen der zeitnah erwarteten Wiederkunft Christi marketingstrategisch kluge Schwerpunktmission des Paulus in ausgew\u00e4hlten st\u00e4dtischen Zentren erm\u00f6glichte ihm also, \u00e4u\u00dferst arbeits\u00f6konomisch eine gr\u00f6\u00dftm\u00f6gliche Zahl an Menschen mit der Evangeliumsbotschaft zu erreichen. So kann er bereits Mitte der 50er-Jahre seine Arbeit in der Osth\u00e4lfte des Imperiums als erf\u00fcllt betrachten und seinen Blick nach Westen richten (R\u00f6m 15, 17-24).<\/p>\n<p>Zu den Managerqualit\u00e4ten des Paulus geh\u00f6rt ebenfalls, dass er ein \u201enetworker\u201c war. Davon zeugt die Vielzahl von Personen, die er in seinen Briefen namentlich erw\u00e4hnt. Selbst in der r\u00f6mischen Gemeinde, die er weder gegr\u00fcndet noch bei Abfassung des R\u00f6merbriefes bis dato besucht hatte, pflegte er zahlreiche pers\u00f6nliche Kontakte zu einzelnen Gemeindemitgliedern (R\u00f6m 16,1-16). Auf diesen gro\u00dfen Personenkreis konnte er sich verlassen und bei Bedarf um Unterst\u00fctzung bitten. Als Managertyp erweist sich Paulus jedoch auch darin, dass er sich konsequent von Begleitern trennte, die sich als nicht zuverl\u00e4ssig oder kooperativ genug erwiesen. So weigert er sich nach den Erfahrungen der ersten Missionsreise, Johannes Markus ein weiteres Mal mitzunehmen. Als Barnabas das nicht akzeptieren will, setzt er die bis dahin bew\u00e4hrte Zusammenarbeit mit ihm nicht fort (Apg 15,36-39). \u00c4hnlich d\u00fcrfte es Silas\/Silvanus ergangen sein, der Paulus gemeinsam mit Timotheus auf der zweiten Missionsreise begleitet (1 Thess 1,1; Apg 15,40-18,5). An der dritten Missionsreise nimmt Silas jedoch nicht mehr teil. Die Vermutung liegt nahe, dass Paulus sich von ihm trennte, weil Silas als Jerusalemer Judenchrist (Apg 15,22) ihn beim antiochenischen Zwischenfall in seiner kompromisslosen Haltung nicht unterst\u00fctzte.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>\u201eWenn ich schwach bin, bin ich stark\u201c<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>Mehr als zwei Jahrzehnte hat Paulus unerm\u00fcdlich das Evangelium unter den Heiden verk\u00fcndigt und dabei weit \u00fcber 30.000 Kilometer unter den beschwerlichen Reisebedingungen der Antike zur\u00fcckgelegt. Er selbst bezeugt in 2 Kor 11,23-27 \u00fcber die Strapazen der Reisen hinaus noch zahlreiche weitere M\u00fchsale, die er als Diener Christi (V. 23) zu ertragen hatte, darunter mehrere Gef\u00e4ngnisaufenthalte, K\u00f6rperstrafen und sonstige Misshandlungen. Wenngleich Paulus pers\u00f6nliche Themen nur anspricht, sofern sie seine Argumentation st\u00fctzen, ist angesichts dieser gro\u00dfen Strapazen doch eine Beobachtung bemerkenswert: In seinen \u00fcberlieferten Briefen gibt es nur zwei Indizien f\u00fcr eine physische Erkrankung. So k\u00f6nnte Paulus in Erinnerung an seine Erstverk\u00fcndigung in Galatien mit Gal 4,15 auf ein Augenleiden anspielen. Auch beim \u201eStachel\/Dorn im Fleisch\u201c (2 Kor 12,7), der Paulus offenbar massiv qu\u00e4lt, d\u00fcrfte es sich um ein k\u00f6rperliches Leiden handeln, das \u2013 wie der Kontext nahelegt \u2013 bereits vor l\u00e4ngerer Zeit ausgebrochen und inzwischen chronisch geworden war. Trotz der damit verbundenen Schmerzen hinderte es Paulus aber nicht daran, seine Missionsarbeit weiterhin intensiv zu betreiben. Damit spricht der Befund insgesamt daf\u00fcr, dass er eine robuste k\u00f6rperliche Konstitution besa\u00df.<\/p>\n<p>Im 2 Kor gibt es allerdings einige Hinweise, die erahnen lassen, dass die Situation der Gemeinden in Korinth und Galatien um das Jahr 55 Paulus psychisch schwer belastet hat. Nach Abfassung des ersten Korintherbriefes hatte sich das Verh\u00e4ltnis der Gemeinde zu Paulus so verschlechtert, dass er sich kurzfristig zu einem spontanen Besuch in Korinth entschloss. Vor Ort wurde er von einem Gemeindemitglied offenbar mit schweren Vorw\u00fcrfen attackiert, ohne dass sich die Gesamtgemeinde sofort davon distanzierte. Paulus brach deshalb seinen Besuch ab und schrieb bald darauf einen geharnischten Brief an die Gemeinde, mit dem er Titus nach Korinth schickte (2 Kor 2,1-13). Der zeitnah zum zweiten Korintherbrief verfasste Galaterbrief belegt, dass Paulus auch um die galatischen Gemeinden in gro\u00dfer Sorge sein musste. Denn sie standen unmittelbar davor, dem Werben der toraobservanten judenchristlichen Konkurrenzmissionare nachzugeben (Gal 4,10.21; 5,2-4; 6,12). Diese Phase der Ungewissheit, bevor er von Titus beruhigende Nachrichten aus Korinth erhielt (2 Kor 7,5-16), hat Paulus anscheinend in eine schwere Krise gest\u00fcrzt (2 Kor 2,12f; 7,5). Vielleicht darf man sogar 2 Kor 1,8-10 als Hinweis auf einen depressiven Ersch\u00f6pfungszustand (\u201eBurn-Out\u201c) deuten. Gewiss muss eine solche Diagnose spekulativ bleiben. Doch f\u00fcr sie spricht, dass die akute Gefahr, die Gemeinden in Korinth und Galatien zu verlieren, Paulus in seinem apostolischen Selbstverst\u00e4ndnis mit einem drohenden \u201eSuper-GAU\u201c konfrontierte. Denn wenn er die von ihm gegr\u00fcndeten Gemeinden als \u201eSiegel seines Apostelamtes\u201c (1 Kor 9,2) und als \u201esein Empfehlungsschreiben\u201c (2 Kor 3,2) verstand, dann musste f\u00fcr ihn ein Scheitern seiner apostolischen Beziehung zu ihnen gleichbedeutend sein mit einem Scheitern an seinem von Gott erhaltenen Auftrag als Apostel. Dass ihm eine solche Perspektive tats\u00e4chlich wie ein Todesurteil vorkommen konnte (2 Kor 1,9), die wohl schon nicht mehr zu hoffen gewagte Auss\u00f6hnung mit der korinthischen Gemeinde aber als eine von Gott gewirkte Rettung aus Todesnot (2 Kor 1,10), ist keinesfalls abwegig.<\/p>\n<p>Letztlich ist Paulus aus dieser tiefen Krise wahrscheinlich gest\u00e4rkt hervorgegangen. Denn er stellt sich auf breiter Front \u2013 mal mehr abwehrend, mal mehr vorbeugend, mal mehr invektiv, mal mehr argumentativ, auf jeden Fall aber offensiv (2 Kor 10-13; R\u00f6m 1,16-8,39; Phil 3,2-16) \u2013 der Auseinandersetzung mit den Konkurrenzverk\u00fcndigern, die schon bald auch in der korinthischen Gemeinde f\u00fcr erneute Unruhe sorgten. Ja, er plant sogar die Verlagerung seiner Verk\u00fcndigungsaktivit\u00e4ten nach Spanien (R\u00f6m 15,23f). Doch bei seinem zuvor absolvierten Jerusalembesuch, auf den er in R\u00f6m 15,30f bereits mit unguten Gef\u00fchlen vorausblickt, wird Paulus wohl auf Betreiben streng toratreuer Jerusalemer Gruppen aufgrund seiner christologisch begr\u00fcndeten Haltung zu Gesetz und Tempel verhaftet (Apg 21,27f). Damit aber wird er zum Opfer eines Kreises von Gesetzeseiferen, dem er selbst vor seiner Lebenswende einst angeh\u00f6rt hatte.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ein \u201einterkultureller\u201c Jude &nbsp; Als nach Darstellung der Apostelgeschichte Paulus bei seinem letzten Aufenthalt in Jerusalem im Tempelreich von r\u00f6mischen Soldaten verhaftet wird, stellt er sich dem Oberst in griechischer Sprache so vor: \u201eIch bin ein Jude, aus Tarsus in Zilizien stammend, B\u00fcrger einer nicht unbedeutenden Stadt\u201c (Apg 21,39). Und wenig sp\u00e4ter \u2013 so wei\u00df&hellip;<\/p>","protected":false},"author":5,"featured_media":32561,"menu_order":258,"template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"class_list":["post-117997","media-library","type-media-library","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Paulus \u2013 vier Spotlights auf eine vielschichtige Pers\u00f6nlichkeit - Katholische Akademie in Bayern<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kath-akademie-bayern.de\/en\/mediathek-eintrag\/paulus-vier-spotlights-auf-eine-vielschichtige-persoenlichkeit\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paulus \u2013 vier Spotlights auf eine vielschichtige Pers\u00f6nlichkeit - Katholische Akademie in Bayern\" \/>\n<meta property=\"og:description\" content=\"Ein \u201einterkultureller\u201c Jude &nbsp; Als nach Darstellung der Apostelgeschichte Paulus bei seinem letzten Aufenthalt in Jerusalem im Tempelreich von r\u00f6mischen Soldaten verhaftet wird, stellt er sich dem Oberst in griechischer Sprache so vor: \u201eIch bin ein Jude, aus Tarsus in Zilizien stammend, B\u00fcrger einer nicht unbedeutenden Stadt\u201c (Apg 21,39). Und wenig sp\u00e4ter \u2013 so wei\u00df&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kath-akademie-bayern.de\/en\/mediathek-eintrag\/paulus-vier-spotlights-auf-eine-vielschichtige-persoenlichkeit\/\" \/>\n<meta property=\"og:site_name\" content=\"Katholische Akademie in Bayern\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/katholische.akademie.bayern\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kath-akademie-bayern.de\/wp-content\/uploads\/Theologie_Kirche_Spiritualitaet.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"872\" \/>\n\t<meta property=\"og:image:height\" content=\"490\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"19 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/en\\\/mediathek-eintrag\\\/paulus-vier-spotlights-auf-eine-vielschichtige-persoenlichkeit\\\/\",\"url\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/en\\\/mediathek-eintrag\\\/paulus-vier-spotlights-auf-eine-vielschichtige-persoenlichkeit\\\/\",\"name\":\"Paulus \u2013 vier Spotlights auf eine vielschichtige Pers\u00f6nlichkeit - Katholische Akademie in Bayern\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/en\\\/mediathek-eintrag\\\/paulus-vier-spotlights-auf-eine-vielschichtige-persoenlichkeit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/en\\\/mediathek-eintrag\\\/paulus-vier-spotlights-auf-eine-vielschichtige-persoenlichkeit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/wp-content\\\/uploads\\\/Theologie_Kirche_Spiritualitaet.jpg\",\"datePublished\":\"2026-01-19T13:09:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/en\\\/mediathek-eintrag\\\/paulus-vier-spotlights-auf-eine-vielschichtige-persoenlichkeit\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kath-akademie-bayern.de\\\/en\\\/mediathek-eintrag\\\/paulus-vier-spotlights-auf-eine-vielschichtige-persoenlichkeit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/en\\\/mediathek-eintrag\\\/paulus-vier-spotlights-auf-eine-vielschichtige-persoenlichkeit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/wp-content\\\/uploads\\\/Theologie_Kirche_Spiritualitaet.jpg\",\"contentUrl\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/wp-content\\\/uploads\\\/Theologie_Kirche_Spiritualitaet.jpg\",\"width\":872,\"height\":490},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/en\\\/mediathek-eintrag\\\/paulus-vier-spotlights-auf-eine-vielschichtige-persoenlichkeit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paulus \u2013 vier Spotlights auf eine vielschichtige Pers\u00f6nlichkeit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/#website\",\"url\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/\",\"name\":\"Katholische Akademie in Bayern\",\"description\":\"Kirche braucht Debatte: \u201ekatholisch\u201c mit Blick auf das Ganze \u2013 und \u201eakademisch\u201c im Vertrauen auf die Kraft der Argumente\",\"publisher\":{\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/#organization\",\"name\":\"Katholische Akademie in Bayern\",\"url\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/wp-content\\\/uploads\\\/Menue-Logo-Home@2x.png\",\"contentUrl\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/wp-content\\\/uploads\\\/Menue-Logo-Home@2x.png\",\"width\":496,\"height\":216,\"caption\":\"Katholische Akademie in Bayern\"},\"image\":{\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/katholische.akademie.bayern\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paulus \u2013 vier Spotlights auf eine vielschichtige Pers\u00f6nlichkeit - Katholische Akademie in Bayern","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kath-akademie-bayern.de\/en\/mediathek-eintrag\/paulus-vier-spotlights-auf-eine-vielschichtige-persoenlichkeit\/","og_locale":"en_GB","og_type":"article","og_title":"Paulus \u2013 vier Spotlights auf eine vielschichtige Pers\u00f6nlichkeit - Katholische Akademie in Bayern","og_description":"Ein \u201einterkultureller\u201c Jude &nbsp; Als nach Darstellung der Apostelgeschichte Paulus bei seinem letzten Aufenthalt in Jerusalem im Tempelreich von r\u00f6mischen Soldaten verhaftet wird, stellt er sich dem Oberst in griechischer Sprache so vor: \u201eIch bin ein Jude, aus Tarsus in Zilizien stammend, B\u00fcrger einer nicht unbedeutenden Stadt\u201c (Apg 21,39). Und wenig sp\u00e4ter \u2013 so wei\u00df&hellip;","og_url":"https:\/\/kath-akademie-bayern.de\/en\/mediathek-eintrag\/paulus-vier-spotlights-auf-eine-vielschichtige-persoenlichkeit\/","og_site_name":"Katholische Akademie in Bayern","article_publisher":"https:\/\/www.facebook.com\/katholische.akademie.bayern\/","og_image":[{"width":872,"height":490,"url":"https:\/\/kath-akademie-bayern.de\/wp-content\/uploads\/Theologie_Kirche_Spiritualitaet.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"19 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kath-akademie-bayern.de\/en\/mediathek-eintrag\/paulus-vier-spotlights-auf-eine-vielschichtige-persoenlichkeit\/","url":"https:\/\/kath-akademie-bayern.de\/en\/mediathek-eintrag\/paulus-vier-spotlights-auf-eine-vielschichtige-persoenlichkeit\/","name":"Paulus \u2013 vier Spotlights auf eine vielschichtige Pers\u00f6nlichkeit - Katholische Akademie in Bayern","isPartOf":{"@id":"https:\/\/kath-akademie-bayern.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kath-akademie-bayern.de\/en\/mediathek-eintrag\/paulus-vier-spotlights-auf-eine-vielschichtige-persoenlichkeit\/#primaryimage"},"image":{"@id":"https:\/\/kath-akademie-bayern.de\/en\/mediathek-eintrag\/paulus-vier-spotlights-auf-eine-vielschichtige-persoenlichkeit\/#primaryimage"},"thumbnailUrl":"https:\/\/kath-akademie-bayern.de\/wp-content\/uploads\/Theologie_Kirche_Spiritualitaet.jpg","datePublished":"2026-01-19T13:09:56+00:00","breadcrumb":{"@id":"https:\/\/kath-akademie-bayern.de\/en\/mediathek-eintrag\/paulus-vier-spotlights-auf-eine-vielschichtige-persoenlichkeit\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kath-akademie-bayern.de\/en\/mediathek-eintrag\/paulus-vier-spotlights-auf-eine-vielschichtige-persoenlichkeit\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/kath-akademie-bayern.de\/en\/mediathek-eintrag\/paulus-vier-spotlights-auf-eine-vielschichtige-persoenlichkeit\/#primaryimage","url":"https:\/\/kath-akademie-bayern.de\/wp-content\/uploads\/Theologie_Kirche_Spiritualitaet.jpg","contentUrl":"https:\/\/kath-akademie-bayern.de\/wp-content\/uploads\/Theologie_Kirche_Spiritualitaet.jpg","width":872,"height":490},{"@type":"BreadcrumbList","@id":"https:\/\/kath-akademie-bayern.de\/en\/mediathek-eintrag\/paulus-vier-spotlights-auf-eine-vielschichtige-persoenlichkeit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/kath-akademie-bayern.de\/"},{"@type":"ListItem","position":2,"name":"Paulus \u2013 vier Spotlights auf eine vielschichtige Pers\u00f6nlichkeit"}]},{"@type":"WebSite","@id":"https:\/\/kath-akademie-bayern.de\/#website","url":"https:\/\/kath-akademie-bayern.de\/","name":"Catholic Academy in Bavaria","description":"Church needs debate: \"catholic\" looking at the whole - and \"academic\" trusting in the power of arguments","publisher":{"@id":"https:\/\/kath-akademie-bayern.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kath-akademie-bayern.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/kath-akademie-bayern.de\/#organization","name":"Catholic Academy in Bavaria","url":"https:\/\/kath-akademie-bayern.de\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/kath-akademie-bayern.de\/#\/schema\/logo\/image\/","url":"https:\/\/kath-akademie-bayern.de\/wp-content\/uploads\/Menue-Logo-Home@2x.png","contentUrl":"https:\/\/kath-akademie-bayern.de\/wp-content\/uploads\/Menue-Logo-Home@2x.png","width":496,"height":216,"caption":"Katholische Akademie in Bayern"},"image":{"@id":"https:\/\/kath-akademie-bayern.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/katholische.akademie.bayern\/"]}]}},"_links":{"self":[{"href":"https:\/\/kath-akademie-bayern.de\/en\/wp-json\/wp\/v2\/media-library\/117997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kath-akademie-bayern.de\/en\/wp-json\/wp\/v2\/media-library"}],"about":[{"href":"https:\/\/kath-akademie-bayern.de\/en\/wp-json\/wp\/v2\/types\/media-library"}],"author":[{"embeddable":true,"href":"https:\/\/kath-akademie-bayern.de\/en\/wp-json\/wp\/v2\/users\/5"}],"version-history":[{"count":1,"href":"https:\/\/kath-akademie-bayern.de\/en\/wp-json\/wp\/v2\/media-library\/117997\/revisions"}],"predecessor-version":[{"id":117998,"href":"https:\/\/kath-akademie-bayern.de\/en\/wp-json\/wp\/v2\/media-library\/117997\/revisions\/117998"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kath-akademie-bayern.de\/en\/wp-json\/wp\/v2\/media\/32561"}],"wp:attachment":[{"href":"https:\/\/kath-akademie-bayern.de\/en\/wp-json\/wp\/v2\/media?parent=117997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}