{"id":120718,"date":"2026-03-20T11:35:19","date_gmt":"2026-03-20T10:35:19","guid":{"rendered":"https:\/\/kath-akademie-bayern.de\/?post_type=media-library&#038;p=120718"},"modified":"2026-03-20T11:35:19","modified_gmt":"2026-03-20T10:35:19","slug":"die-verborgenheit-gottes-und-die-sozialen-dimensionen-religioeser-erkenntnis","status":"publish","type":"media-library","link":"https:\/\/kath-akademie-bayern.de\/en\/mediathek-eintrag\/die-verborgenheit-gottes-und-die-sozialen-dimensionen-religioeser-erkenntnis\/","title":{"rendered":"The hiddenness of God and the social dimensions of religious knowledge"},"content":{"rendered":"<h3><strong>Das Problem der Verborgenheit Gottes und das Problem des Leidens<\/strong><\/h3>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Das Problem der Verborgenheit Gottes besteht in der Erkl\u00e4rung von Unglauben: Warum offenbart sich Gott angesichts seiner liebenden und allm\u00e4chtigen Natur nicht allen Menschen gleicherma\u00dfen? Diese Frage kann zu Zweifeln f\u00fchren (und tut dies auch) oder gar in ein Argument gegen die Existenz Gottes umgem\u00fcnzt werden. An dieser Stelle l\u00e4sst sich eine strukturelle Analogie zum Problem des Leidens feststellen. In beiden F\u00e4llen gehen wir von Annahmen \u00fcber die Natur Gottes aus (Gott ist liebend, allm\u00e4chtig), welche die Existenz von Leiden (oder Unglauben) wiederum problematisch erscheinen lassen. In der Tat verlangen sowohl Leiden als auch Unglauben eine Erkl\u00e4rung: Wie ist Gottes Existenz mit dem strittigen Umstand vereinbar? Und in beiden F\u00e4llen kann die Frage in ein Argument gegen die Existenz Gottes m\u00fcnden. Die Argumentation w\u00e4re die, dass Gottes Existenz nicht mit der Existenz von Leiden (Unglauben) vereinbar ist; da aber die Existenz von Leiden (Unglauben) unbestreitbar ist, sollten wir daraus schlie\u00dfen, dass Gott nicht existiert.<\/p>\n<p>Erwiderungen auf diesen Gedankengang f\u00fchren die Analogie fort. Dementsprechend suchen Entgegnungen bez\u00fcglich des Problems des Leidens die Erkl\u00e4rung f\u00fcr Leiden oft in etwas au\u00dferhalb Gottes, beispielsweise in der Aus\u00fcbung der menschlichen Willensfreiheit. Auch die Argumentation \u00fcber den \u201eunzul\u00e4nglichen Atheisten\u201c zum Problem der Verborgenheit Gottes verwendet diese Strategie: Unglauben wird mittels moralischer und\/oder intellektueller Unzul\u00e4nglichkeit auf Seiten des Ungl\u00e4ubigen erkl\u00e4rt. Genauer lautet die Argumentation wie folgt: Die Tatsache, dass einige Leute Gott nicht kennen und nicht einmal an ihn glauben, kann auf eine Unzul\u00e4nglichkeit in ihnen selbst zur\u00fcckgef\u00fchrt werden. Das hei\u00dft, Gott offenbart sich zwar allen Menschen gleicherma\u00dfen, allerdings str\u00e4uben sich manche Menschen dagegen.<\/p>\n<p>Manchen Gl\u00e4ubigen d\u00fcrfte eine derartige Erwiderung auf das Problem des Unglaubens unangenehm erscheinen, wenn nicht gar unwirsch. Nat\u00fcrlich kann man sie in ihrer H\u00e4rte auch abmildern. So k\u00f6nnte man leicht erg\u00e4nzen, dass wir alle S\u00fcnder sind, oder man k\u00f6nnte zwischen Erbs\u00fcnde und pers\u00f6nlicher S\u00fcnde unterscheiden. Aber selbst mit diesen Erg\u00e4nzungen scheint mir die Entgegnung \u00fcber die Unzul\u00e4nglichkeit des Atheisten immer noch suboptimal. Dies zeigt sich beispielsweise in der Herausarbeitung gemeinsamer Strukturen der zwei jeweiligen Gedankeng\u00e4nge. (Nochmal: Wir sehen eine Analogie zum Problem des Leidens.)<\/p>\n<p>Der zeitgen\u00f6ssische Atheist denkt also:<\/p>\n<ol>\n<li>Die Belege gegen Gott sind \u00fcberw\u00e4ltigend.<\/li>\n<li>F\u00fcr alle sind die gleichen Belege verf\u00fcgbar, den Theisten eingeschlossen.<\/li>\n<\/ol>\n<p>Daher:<\/p>\n<ol start=\"3\">\n<li>Der Theist muss die verf\u00fcgbaren Belege entweder ignorieren oder falsch beurteilen.<\/li>\n<\/ol>\n<p>Ein analoger Gedankengang steckt hinter der Strategie bez\u00fcglich des unzul\u00e4nglichen Atheisten:<\/p>\n<ol>\n<li>Theisten haben umfassende Belege f\u00fcr die Pr\u00e4senz Gottes.<\/li>\n<li>F\u00fcr alle sind die gleichen Belege verf\u00fcgbar, den Atheisten eingeschlossen.<\/li>\n<\/ol>\n<p>Daher:<\/p>\n<ol start=\"3\">\n<li>Der Atheist muss sich gegen die verf\u00fcgbaren Belege str\u00e4uben.<\/li>\n<\/ol>\n<p>Der Ansatz, den ich verteidigen m\u00f6chte, lehnt die gemeinsame Pr\u00e4misse in diesen beiden Gedankeng\u00e4ngen ab, also die Annahme, dass die gleichen Belege f\u00fcr Theisten und Atheisten verf\u00fcgbar sind. Eine M\u00f6glichkeit, diesen Ansatz zu begr\u00fcnden, liegt darin, die sozialen Dimensionen von Erkenntnis hervorzuheben und zu argumentieren, dass Gl\u00e4ubige und Ungl\u00e4ubige h\u00e4ufig unterschiedliche soziale Orte besetzen. Genauer: Die epistemische Lage einschlie\u00dflich der Belege, \u00fcber die man verf\u00fcgt, ist teilweise durch die soziale Verortung bestimmt. Dementsprechend k\u00f6nnen Unterschiede im epistemischen Standpunkt manchmal durch Unterschiede in der sozialen Verortung erkl\u00e4rt werden, ohne jemandem intellektuelle oder moralische Unzul\u00e4nglichkeit zuschreiben zu m\u00fcssen.<\/p>\n<p>Es gibt noch weitere Vorteile dieses Ansatzes zur Verborgenheit Gottes. Erstens wird eine Verbindung zwischen religi\u00f6ser Epistemologie und dem wachsenden Feld der sozialen Epistemologie hergestellt, woraus sich interessante Fragen \u00fcber die epistemische Signifikanz verschiedener sozialer Ph\u00e4nomene ergeben und zwar einschlie\u00dflich pers\u00f6nlicher Beziehungen, sozialer Normen, der Mitgliedschaft in Gemeinschaften und institutioneller Autorit\u00e4t. Aus der Perspektive von Theisten verschiebt der Ansatz au\u00dferdem den Fokus weg vom Atheisten und hin zu sich selbst. Den Theisten wird somit dabei geholfen, die Aufmerksamkeit vom \u201eSplitter im Auge deines Bruders\u201c auf \u201eden Balken in deinem Auge\u201c zu lenken.<\/p>\n<p>Hieraus ergibt sich die Gliederung f\u00fcr meine weiteren Ausf\u00fchrungen: Im zweiten Teil wird ein generelles Denkmodell zu einigen wichtigen Problemen in der sozialen Epistemologie sowie in der Epistemologie von Zeugnissen im Besonderen entwickelt. Anschlie\u00dfend wird dieses Modell in Teil drei dann auf die religi\u00f6se Epistemologie und speziell auf das Problem der Verborgenheit Gottes angewandt.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Soziale Epistemologie<\/strong><\/h3>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Ein Problem in der Epistemologie von Zeugnissen. <\/strong>Es gibt ein gravierendes und hartn\u00e4ckiges Problem in der Epistemologie von Zeugnissen: Unterschiedliche F\u00e4lle von Zeugniswissen scheinen sehr verschiedene Anforderungen an den H\u00f6rer zu beinhalten. In manchen F\u00e4llen scheint n\u00e4mlich eine Menge Arbeit auf Seiten des H\u00f6rers n\u00f6tig zu sein, um sein Wissen zu erwerben. Andere F\u00e4lle scheinen den Erwerb von Zeugniswissen sehr einfach zu machen und dem H\u00f6rer nur wenig oder gar keine Arbeit abzuverlangen.<\/p>\n<p>Zur Veranschaulichung bedenke man die folgenden F\u00e4lle:<\/p>\n<p><strong>Fall 1.<\/strong> Ein polizeilicher Ermittler befragt einen potenziell unkooperativen Zeugen.<\/p>\n<p><strong>Fall 2.<\/strong> Ein Anwalt sagt Ihnen, dass sein Klient kein Geld hat.<\/p>\n<p><strong>Fall 3.<\/strong> Ein Job-Bewerber sagt dem Personaldirektor, dass er keine Vorstrafen hat.<\/p>\n<p><strong>Fall 4.<\/strong> Sie fragen eine fremde Frau nach dem Weg zum Bahnhof, und sie gibt Ihnen \u00fcberzeugt Auskunft.<\/p>\n<p><strong>Fall 5.<\/strong> Sie fragen einen Fremden, ob die Stadt \u00fcber ein U-Bahn-System verf\u00fcgt, und er sagt, das sei der Fall.<\/p>\n<p><strong>Fall 6. <\/strong>Ihr eigener Anwalt sagt Ihnen, wie man etwas Geld versteckt.<\/p>\n<p><strong>Fall 7. <\/strong>Sie fragen eine Freundin, ob sie schon einmal in den Vereinigten Staaten war, und sie sagt ja, war sie.<\/p>\n<p><strong>Fall 8.<\/strong> Ein Grundschullehrer sagt seinen Sch\u00fclern, dass M\u00fcnchen in Deutschland liegt.<\/p>\n<p><strong>Fall 9.<\/strong> Eine Mutter sagt ihrem Kind, dass Milch im K\u00fchlschrank ist.<\/p>\n<p><strong>Fall 10. <\/strong>Ein Vater sagt seinem Kind, dass es in den Vereinigten Staaten geboren wurde.<\/p>\n<p>Selbstverst\u00e4ndlich kann der Ermittler in Fall 1 nicht einfach glauben, was der Zeuge sagt. Genauso wenig kann der Personaldirektor einfach dem Job-Bewerber glauben. Je weiter die F\u00e4lle jedoch fortschreiten, desto plausibler wird es, dass der H\u00f6rer oder die H\u00f6rerin schlichtweg glaubt, was ihm oder ihr gesagt wird, und dass er oder sie dabei Wissen erwirbt. Es wird auch plausibler, dass epistemisch betrachtet etwas Besonderes passiert \u2013 beispielsweise, dass Sprecher und H\u00f6rer eine besondere Beziehung zueinander haben und dass das einen epistemischen Unterschied ausmacht.<\/p>\n<p>Hier liegt also das zu l\u00f6sende Problem: Warum scheint Zeugniswissen in manchen F\u00e4llen leicht zu erwerben, in anderen aber schwer? Anders ausgedr\u00fcckt: Warum erscheint die epistemische Last f\u00fcr den H\u00f6rer in den einzelnen F\u00e4llen so unterschiedlich auszufallen?<\/p>\n<p><strong>Das Modell der \u201eInformations-\u00d6konomie\u201c. <\/strong>Eine Reihe von Philosophen hat behauptet, ein zentraler Zweck unseres Erkenntniskonzepts sei es, qualitative Eigenschaften und ihre Quellen f\u00fcr den Gebrauch beim praktischen Schlussfolgern und Entscheiden zu markieren. Die allgemeine Idee dahinter l\u00e4sst sich zusammenfassen wie folgt: Das Erkenntniskonzept dient innerhalb einer Gemeinschaft, die Informationen teilt, der Produktion und Bewegung von umsetzbarer Information oder von Information, die im Handeln und praktischen Schlussfolgern gebraucht werden kann.<\/p>\n<p>Betrachten wir nun einige Ausf\u00fchrungen zu dieser allgemeinen Idee. Erstens sollten wir \u2013 wenn unsere allgemeine Idee zumindest weitgehend richtig ist \u2013 erwarten, dass es mindestens zwei Arten von Handlungen gibt, die von diesem Erkenntniskonzept beherrscht werden. Zum einen sind das Aktivit\u00e4ten, die mit dem Beschaffen oder Sammeln von Informationen zusammenh\u00e4ngen oder damit, Informationen \u00fcberhaupt erst in die Wissensgemeinschaft zu bringen. Empirische Beobachtung dient beispielsweise dazu, Informationen \u00fcber physikalische Objekte in unserer Umgebung zu generieren, w\u00e4hrend Introspektion der Gewinnung von Informationen \u00fcber die zug\u00e4nglichen mentalen Zust\u00e4nde dient. Zum anderen gibt es wohl Aktivit\u00e4ten, die mit der Distribution von Informationen innerhalb der Gemeinschaft der Wissenden zu tun haben; das hei\u00dft, es gibt Mechanismen zur Verteilung von Information, die sich bereits im sozialen System befindet. So dienen zum Beispiel das Lehren im Klassenzimmer, Zeugenaussagen vor Gericht und die Berichterstattung im Sitzungssaal als Distributionsfunktionen. Zusammengefasst: Es gibt Aktivit\u00e4ten, die Informationen \u00fcberhaupt erst in das System eingeben, und solche, die die Information weiter im Fluss halten.<\/p>\n<p>Nennen wir erstere Beschaffungsaktivit\u00e4ten und letztere Distributionsaktivit\u00e4ten. Normen, welche die Beschaffungsaktivit\u00e4ten regeln, spielen eine T\u00fcrh\u00fcter-Funktion \u2013 sie \u00fcben eine Qualit\u00e4tskontrolle aus, so dass nur Informationen von hoher Qualit\u00e4t in das soziale System zugelassen werden. Normen, die hingegen die Distributionsaktivit\u00e4ten regeln, entsprechen einer Distributionsfunktion \u2013 sie sorgen daf\u00fcr, dass Informationen von hoher Qualit\u00e4t, die sich bereits im System befinden, innerhalb der Wissensgemeinschaft je nach Bedarf verteilt werden. Zeugnisse, die diese Distributionsfunktion ausf\u00fchren, dienen somit dazu, bereits im System befindliche Informationen denjenigen zug\u00e4nglich zu machen, die sie brauchen.<\/p>\n<p>An dieser Stelle m\u00f6chte ich etwas anmerken, was f\u00fcr unsere Zwecke noch wichtig sein wird: Vern\u00fcnftigerweise ist anzunehmen, dass sich die Normen, welche die Beschaffung von Information regeln, von den Normen f\u00fcr die Distribution von Information unterscheiden werden. Nehmen wir nun an, wir w\u00fcrden f\u00fcr diese beiden Aktivit\u00e4ten die Regeln aufschreiben oder die Standards festlegen. Dann sollten wir es schwieriger machen, Information in das System hineinzubekommen als Information zu verbreiten, wenn sie einmal darin ist. Das liegt daran, dass die vorherrschende Aufgabe der Beschaffungsfunktion in der Qualit\u00e4tskontrolle besteht \u2013 hier wollen wir einen starken T\u00fcrh\u00fcter-Mechanismus. Die vorherrschende Aufgabe der Distributionsfunktion hingegen ist der einfache Zugang \u2013 Information, welche die Qualit\u00e4tskontrolle bereits bestanden hat, soll einfach und effizient f\u00fcr diejenigen verf\u00fcgbar sein, die sie brauchen. F\u00fcr diese unterschiedlichen Funktionen sind entsprechend auch verschiedene Regeln und Standards geeignet.<\/p>\n<p>Wissenschaftliche Kenntnisse bieten eine gute Veranschaulichung zu dieser allgemeinen Darstellung. Jedes Element von wissenschaftlichem Wissen muss urspr\u00fcnglich wissenschaftlichen Untersuchungsmethoden entstammen, einschlie\u00dflich des Sammelns von Beweisen, des Testens von Theorien und so weiter. Aber irgendwann verbreitet sich dieses Wissen mittels verschiedener Arten von Zeugnissen durch ein gemeinsames System. Was als Wissen einiger weniger beginnt, wird Wissen f\u00fcr viele, durch Dokumentation, formelles und informelles Lehren, Zeitschriftenartikel, \u00f6ffentliche Vorlesungen, Medienberichte und \u00c4hnliches. Dar\u00fcber hinaus sind die Normen zur Regelung der ersten Sorte von Aktivit\u00e4ten andere als die Normen zur Regelung der zweiten. Nat\u00fcrlich werden f\u00fcr beide Qualit\u00e4tskontrollen durchgef\u00fchrt, aber auf verschiedene Weise. Folglich sind auch die Regeln f\u00fcr den Austausch von Informationen durch Zeitschriften, Seminare und so weiter andere als die f\u00fcr experimentelles Design, statistische Analyse oder die Wahl von Theorien.<\/p>\n<p>Im Fall von wissenschaftlichem Wissen sind vielf\u00e4ltige institutionelle und soziale Praktiken vorhanden, um qualitativ hochwertige Information in das System zu bringen und innerhalb des Systems zu verbreiten. Diese verschiedenen Praktiken werden durch verschiedene Regeln beherrscht, je nach ihren charakteristischen Zwecken und Funktionen. Es scheint plausibel, dass das, was hier f\u00fcr wissenschaftliches Wissen gilt, auch f\u00fcr Wissen im Allgemeinen g\u00fcltig ist.<\/p>\n<p>Hier kommen wir zu einer weiteren Erg\u00e4nzung des Modells: Es ist eine sinnvolle Annahme, dass Zeugniswissen an sich in zweierlei Art auftritt. Das hei\u00dft, es ist anzunehmen, dass Zeugniswissen manchmal der Distributionsfunktion f\u00fcr das Wissenskonzept dient und manchmal der Beschaffungsfunktion. Die Distributionsfunktion liefert uns das, was man als paradigmatische F\u00e4lle von Zeugniswissen bezeichnen k\u00f6nnte; z.B. die obigen F\u00e4lle Anwalt\/Klient, Sch\u00fcler\/Lehrer und Eltern\/Kind. Aber ein Zeugnis dient manchmal auch der Beschaffungsfunktion, indem Information erstmalig in eine Wissensgemeinschaft eingebracht wird. Dies scheint in den F\u00e4llen des Ermittlers und des Job-Bewerbers der Fall zu sein. Somit erkl\u00e4rt das Modell, warum ein Sch\u00fcler und ein Kind schlichtweg glauben k\u00f6nnen, was ein Lehrer oder Elternteil ihm sagt, und gleichzeitig, warum ein Ermittler oder ein Personaler im Vorstellungsgespr\u00e4ch das nicht kann.<\/p>\n<p>Hier muss klargestellt werden, dass die Idee nicht die ist, dass Zeugniswissen in der Distributionsrolle keinerlei Belastung f\u00fcr den H\u00f6rer bedeutet. In den meisten oder gar allen unserer Fallbeispiele w\u00e4re es unsinnig, dass der H\u00f6rer ohne irgendein Zutun seiner eigenen kritischen F\u00e4higkeiten \u201eeinfach glaubt\u201c, was ihm gesagt wird. Es geht vielmehr darum, dass die Belastung der H\u00f6rer in der Distributionsrolle eine andere ist als die in der Beschaffungsrolle; und zwar insofern, als dass die Regeln f\u00fcr diese beiden Aktivit\u00e4ten verschiedenen Zwecken dienen. Das reicht aus, um die Unterschiede in den Belastungen im Zusammenhang mit F\u00e4llen von Zeugniswissen zu erkl\u00e4ren \u2013 ebenso wie die Unterschiede in den Belastungen im Zusammenhang mit (manchen F\u00e4llen von) Zeugniswissen und Nicht-Zeugniswissen.<\/p>\n<p><strong>Drei Arten von Zeugnisaustausch: interpersonell, sozial und institutionell. <\/strong>Aus hier dargestellter Sicht wird der Austausch von Zeugnissen also mittels zweier Gruppen von Regeln beherrscht: denen, welche die Beschaffung von qualitativer Information betreffen und denen f\u00fcr ihre Verbreitung. Dar\u00fcber hinaus sind die Regeln f\u00fcr den Zeugnisaustausch in der Verbreitungsrolle auch in sich verschieden, je nach zus\u00e4tzlichen Faktoren bez\u00fcglich der sozialen Verortung von Sprecher und H\u00f6rer. Wir k\u00f6nnen hier mindestens drei Arten von Beziehungen unterscheiden, die unser soziales Umfeld strukturieren und einen erfolgreichen Zeugnisaustausch in der Distributionsrolle beg\u00fcnstigen. Mangels besserer Bezeichnungen k\u00f6nnen wir sie \u201einterpersonell\u201c, \u201einformell sozial\u201c und \u201eformell institutionell\u201c nennen.<\/p>\n<p>Interpersonelle Beziehungen h\u00e4ngen vorrangig von interpersonellen Erfahrungen und \u201eGedankenlesen\u201c ab, die mehr oder weniger unabh\u00e4ngig von bestimmten sozialen oder institutionellen Rollen sind. Es gibt eher eine Person-zu-Person-Verbindung, die ein gewisses pers\u00f6nliches Vertrauen garantiert. Diese Art der Interaktion kann zwischen Eltern und Kindern stattfinden, Geschwistern oder Freunden, aber auch zwischen Fremden, die sich das erste Mal treffen. Man k\u00f6nnte auf Basis verh\u00e4ltnism\u00e4\u00dfig begrenzter Interaktionen mit zwei Personen zum Beispiel dem einen Fremden dahingehend vertrauen, dass er die Wahrheit sagt und einem anderen nicht. Das liegt daran, dass manchmal sogar schon begrenzte Interaktion ausreicht, um Aufrichtigkeit und Kompetenz von jemandem abzulesen, vor allem in eingeschr\u00e4nkten Sachlagen und f\u00fcr bestimmte Bereiche.<\/p>\n<p>Im Gegensatz zu \u201eblo\u00dfen\u201c interpersonellen Relationen h\u00e4ngen die Beziehungen mehr von klar definierten sozialen Rollen ab, beispielsweise Eltern-Kind, Geschwister, Nachbarn und verschiedene Arten von Freundschaft. Interaktionen in solchen Rollen sind wie oben von interpersonellen Kompetenzen bestimmt, aber zus\u00e4tzlich auch von sozialen Normen, die diesen spezifischen Beziehungen zugrunde liegen. So ist es zum Beispiel notwendig, Gedanken zu lesen, um mit seinen Nachbarn in einer Nachbarschaftsinitiative zusammenzuarbeiten, aber wie man kooperiert (welche Erwartungen man hat, was man bereit ist zu opfern und so weiter) wird auch von den Regeln beeinflusst, die die Nachbarschaftsbeziehung strukturieren.<\/p>\n<p>Hier ein Beispiel daf\u00fcr, wie Regeln zur Strukturierung von sozialen Beziehungen die verl\u00e4ssliche Verbreitung von qualitativer Information erm\u00f6glichen k\u00f6nnte: Wir k\u00f6nnten annehmen, dass es in vielen Kulturen als eine Sache von Liebe und Respekt verstanden wird, in Sachen der Kinderbetreuung seine Eltern um Rat zu fragen. Damit schaffen die die Beziehung strukturierenden Normen einen Kommunikationskanal von erfahrenen Eltern zu neuen Eltern. Die Information, die \u00fcber diesen Kanal l\u00e4uft, wird voraussichtlich eine hohe Qualit\u00e4t aufweisen, da die Eltern von Eltern im Bereich der Kinderbetreuung bereits einen gewissen Erfolg aufweisen k\u00f6nnen. Auch der Kanal selbst wird voraussichtlich eine hohe Qualit\u00e4t aufweisen, gemessen an den Normen, die die Kommunikation solcher Information zwischen Eltern und Kindern regeln. Die erfahrenen Eltern werden somit in gro\u00dfem Ma\u00dfe geneigt sein, aufrichtig und kompetent Rat zu geben, w\u00e4hrend die neuen Eltern hochgradig geneigt sein werden, diesen Rat ernstzunehmen, und beide Parteien werden dazu bereit sein, Vorkehrungen gegen Fehlinformation und\/oder Missverst\u00e4ndnisse zu treffen.<\/p>\n<p>Und jetzt kommt ein interessanter Punkt: Die interpersonellen Kompetenzen und sozialen Normen, die diesen erfolgreichen Austausch garantieren, m\u00fcssen nicht epistemisch motiviert sein oder ein epistemisches Ziel haben. Das hei\u00dft, weder der Sprecher noch der H\u00f6rer m\u00fcssen von \u00dcberlegungen zu Wahrheit, Wissen et cetera motiviert sein (zumindest nicht direkt). Im Gegenteil, der gesamte Austausch k\u00f6nnte mit Anspr\u00fcchen der Beziehung erkl\u00e4rt werden, wie Liebe und Respekt oder sogar Schuld. Gleicherma\u00dfen k\u00f6nnten gute Nachbarn verl\u00e4ssliche Informationen zu Busrouten oder irgendwelchen Nachbarschaftsangelegenheiten geben oder erfragen, und zwar vorrangig motiviert durch Werte wie Anstand, Hilfsbereitschaft und der gemeinsamen Zusammenarbeit, welche die Nachbarschaftsbeziehung strukturieren.<\/p>\n<p>Somit bewirken sowohl interpersonelle als auch soziale Beziehungen eine Strukturierung des Austauschs von Information zwischen Sprecher und H\u00f6rer. Beide Arten von Relation k\u00f6nnen dar\u00fcber hinaus zur epistemischen Qualit\u00e4t solch eines Austauschs beitragen. In den meisten F\u00e4llen von Zeugnisaustausch arbeiten wohl beide Arten von Relation zusammen. So gibt es zum Beispiel zwei Gr\u00fcnde, warum man einem Freund vertrauen k\u00f6nnte, einerseits basierend auf interpersoneller Interaktion, andererseits aufgrund der sozialen Beziehung. Man k\u00f6nnte einer Freundin also vertrauen, dass sie die Wahrheit sagt, weil \u201eich sie kenne\u201c. Andererseits k\u00f6nnte man einer Freundin aber auch deshalb vetrauen, weil \u201eFreunde sich so verhalten\u201c. Und nat\u00fcrlich kann das Vertrauen auch auf beiden Gr\u00fcnden beruhen. Gleiches gilt f\u00fcr das Vertrauen zwischen Eltern und Kind, Nachbarn und so weiter.<\/p>\n<p>Schlie\u00dflich sind manche Relationen durch eher formelle institutionelle Rollen definiert. Beziehungen zwischen Lehrer und Sch\u00fcler, Arzt und Patient, Anwalt und Klient oder zwischen Mitarbeitern sind in gro\u00dfem Ausma\u00df von entsprechenden institutionellen Regeln bestimmt. Auch hier gilt wieder, dass die betreffenden Regeln zus\u00e4tzlich zu den oben besprochenen interpersonellen Kompetenzen und informellen sozialen Normen oder gewisserma\u00dfen \u201e\u00fcber diese hinaus\u201c arbeiten. Und auch hier k\u00f6nnen institutionelle Regeln zur Qualit\u00e4t des Zeugnisaustauschs beitragen, wodurch zus\u00e4tzliche Gr\u00fcnde f\u00fcr Vertrauen geschaffen werden. So ist die Beziehung zwischen einem Arzt und seinen Patienten beispielsweise dadurch gesichert, dass institutionelle Regeln die Kompetenz und Redlichkeit praktizierender \u00c4rzte gew\u00e4hrleisten. Gleiches gilt f\u00fcr Beziehungen zwischen einem Anwalt und seinen Klienten oder zwischen Mitarbeitern. Solche Regeln k\u00f6nnen in Form von staatlichen Regulierungen auftreten, als rechtliche Vertr\u00e4ge, Standesregeln oder Berufsethiken.<\/p>\n<p>Zusammengenommen bieten sie eine zus\u00e4tzliche Strukturierung f\u00fcr die soziale Umgebung, wobei sie h\u00e4ufig zur epistemischen Qualit\u00e4t des Zeugnisaustauschs beitragen. Wie auch im Fall von interpersonellen Kompetenzen und informellen sozialen Normen m\u00fcssen auch bei institutionellen Regeln keine epistemischen Absichten als direkte oder vorrangige Motivation vorliegen. Einem bestimmten Anwalt k\u00f6nnte zum Beispiel nur wenig an der Wahrheit an sich gelegen sein, ebenso wie ein einzelner Arzt Wissen um seiner selbst willen nur geringe Bedeutung beimessen k\u00f6nnte. In jedem Fall bestehen aber institutionelle Mechanismen, um Aufrichtigkeit und Kompetenz in den relevanten Bereichen zu gew\u00e4hrleisten, die somit qualitative Informationskan\u00e4le schaffen, die ihrerseits wiederum von den Patienten und Klienten genutzt werden k\u00f6nnen.<\/p>\n<p>An dieser Stelle kann eine Analogie zum Informationsfluss bei der Wahrnehmungsaufnahme gezogen werden. Ein stabiles physikalisches Umfeld erlaubt es der Wahrnehmung, Information tragende Signale zu nutzen. Ein bestimmtes Profil signalisiert zum Beispiel zuverl\u00e4ssig Hund, w\u00e4hrend ein anderes Profil zuverl\u00e4ssig Katze signalisiert. Das ist nicht notwendigerweise der Fall \u2013 das Umfeld muss f\u00fcr die visuelle Wahrnehmung auch geeignet sein; das hei\u00dft, es muss die betreffenden Wahrnehmungsfertigkeiten aktivieren. Ein stabiles soziales Umfeld spielt dieselbe Rolle im Zusammenhang mit dem Informationsfluss beim Austausch von Zeugnissen. So wie Naturgesetze ein (mehr oder weniger) stabiles physikalisches Umfeld konstruieren, indem sie ihm den bestehenden Rahmen geben, konstruieren soziale Normen ein (mehr oder weniger) stabiles soziales Umfeld, indem sie ihm die entsprechenden Umrisse geben. Naturgesetze gew\u00e4hrleisten dabei Gesetzm\u00e4\u00dfigkeiten, die bei der Wahrnehmung ausgenutzt werden k\u00f6nnen. Soziale Normen sichern Regelm\u00e4\u00dfigkeiten, die bei Zeugnissen genutzt werden k\u00f6nnen.<\/p>\n<p>Kleine Kinder sind in diesem Zusammenhang interessant. Sie scheinen nur \u00fcber begrenzte Fertigkeiten zur Feststellung von Aufrichtigkeit und Kompetenz von Sprechern zu verf\u00fcgen. Das hei\u00dft, kleine Kinder, die auf sich allein gestellt sind, k\u00f6nnen ziemlich leichtgl\u00e4ubig sein. Wie schaffen es Kinder also, von Zeugnissen so gut zu lernen, wie sie es tun? Die Antwort liegt darin, dass Kinder kaum je auf sich allein gestellt sind. Im Gegenteil, wir konstruieren und \u00fcberwachen ihre sozialen Umgebungen, um sie von unaufrichtigen und inkompetenten Sprechern zu sch\u00fctzen. Anders gesagt: Wir errichten Umgebungen, die die Informations\u00fcbertragung erm\u00f6glichen, die ihre informelle Erziehung erfordert. Sp\u00e4ter im Leben schaffen wir Umgebungen, die ihre eher formelle Erziehung erm\u00f6glichen.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Implikationen f\u00fcr religi\u00f6se Epistemologie<\/strong><\/h3>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Abschlie\u00dfend sollen noch einige Implikationen unseres Modells f\u00fcr religi\u00f6se Epistemologie und speziell f\u00fcr das Problem der Verborgenheit Gottes dargestellt werden.<\/p>\n<p><strong>Die Relevanz unseres Modells f\u00fcr religi\u00f6se Epistemologie. <\/strong>Zu Beginn sei festgehalten, dass alle drei oben vorgestellten Arten des Zeugnisaustauschs (interpersonell, informell sozial und formell institutionell) in religi\u00f6ser Epistemologie Anwendung finden k\u00f6nnen. Das hei\u00dft, religi\u00f6se Zeugnisse treten manchmal im Kontext einer pers\u00f6nlichen Beziehung zwischen H\u00f6rer und zuverl\u00e4ssigem Sprecher auf. Andere Male treten Zeugnisse im Kontext von sch\u00e4rfer umrissenen sozialen Rollen auf, etwa wenn Eltern mit ihren Kindern \u00fcber ihren gemeinsamen Glauben sprechen. Und nat\u00fcrlich sind religi\u00f6se Einrichtungen zu dem Zweck organisiert, religi\u00f6se Zeugnisse in vielf\u00e4ltigen Kontexten hervorzubringen, einschlie\u00dflich formeller Bildung, Predigt, Ritual und vieler anderer religi\u00f6ser und kultureller Praktiken. Schlie\u00dflich kann unser Modell auch speziell im Bereich religi\u00f6sen Glaubens angewandt werden.<\/p>\n<p><strong>Die epistemische Bedeutung der sozialen Verortung. <\/strong>Sagen wir, jemandes \u201esoziale Verortung\u201c ist durch seine interpersonellen Beziehungen und seine Mitgliedschaft, Mitwirkung sowie seinen Rollen in einer Gemeinschaft vorgegeben, einschlie\u00dflich der formellen Institutionen einer solchen Gemeinschaft. Dann ist diese soziale Verortung nach dem vorliegenden Modell in mehrfacher Hinsicht epistemisch von Bedeutung. Erstens erlaubt es die soziale Verortung in einer Gemeinschaft \u00fcberhaupt erst, eine wichtige Art von Zeugnisbelegen zu erhalten. Genauer gesagt erlaubt sie es, Zeugnisse in ihrer Distributionsfunktion zu erhalten, im Gegensatz zu ihrer Beschaffungsfunktion. <em>(Abbildung 1<\/em><strong>)<\/strong><\/p>\n<p>Des Weiteren beeinflusst sie die epistemische Qualit\u00e4t dieser Belege, einschlie\u00dflich der Frage, ob damit \u00fcberhaupt Zeugniswissen \u00fcbermittelt wird. Genau genommen wird die soziale Verortung durch pers\u00f6nliche, soziale und institutionelle Relationen konstituiert, welche die verl\u00e4ssliche Distribution von Information und somit die erfolgreiche \u00dcbertragung von Wissen mehr oder weniger erm\u00f6glicht oder untergr\u00e4bt. Somit bestimmt die soziale Verortung den epistemischen Standpunkt ma\u00dfgeblich voraus. Anders gesagt: Der epistemische Standpunkt einer Person wird zum Teil von ihrer sozialen Verortung konstituiert.<\/p>\n<p>Und nat\u00fcrlich konstituieren die Mitgliedschaft und Mitwirkung einer Person in einer religi\u00f6sen Gemeinschaft (oder deren Nichtvorhandensein) zum Teil wiederum die soziale Verortung dieser Person. Wir sollten hier auch Raum f\u00fcr die Idee von \u201eanti-religi\u00f6sen\u201c Gemeinschaften schaffen, etwa von anti-religi\u00f6sen Gemeinschaften im Sinne begrenzter F\u00e4lle von religi\u00f6sen Gemeinschaften. Damit sind nicht einfach nur Gemeinschaften gemeint, denen eine religi\u00f6se Dimension fehlt, sondern eher solche, die eindeutig anti-religi\u00f6se Ansichten und Werte bef\u00f6rdern. Solche Gemeinschaften werden soziale Verortung, Strukturierungskan\u00e4le von Autorit\u00e4t, Vertrauen und Belege ganz genau so festlegen, wie es andere Gemeinschaften auch tun.<\/p>\n<p><strong>Epistemische Konsequenzen moralischer und praktischer Aspekte der sozialen Umgebung. <\/strong>Die verl\u00e4ssliche Verbreitung von Information und somit die effektive \u00dcbertragung von Zeugniswissen h\u00e4ngen von moralischen und praktischen Aspekten interpersoneller Relationen, informeller Gemeinschaften und formeller Institutionen ab. Daf\u00fcr gibt es mehrere Gr\u00fcnde.<\/p>\n<p>Erstens sind Zeugnisse in der Distributionsrolle von Ph\u00e4nomenen wie Vertrauen, Autorit\u00e4t, Expertise und sozialer Position abh\u00e4ngig, von denen offensichtlich alle praktische und\/oder moralische Dimensionen besitzen. Au\u00dferdem h\u00e4ngt die schiere Existenz pers\u00f6nlicher Beziehungen, informeller Gemeinschaften und Institutionen ebenso wie die Mitwirkung einer Person in diesen ma\u00dfgeblich von ihrem moralischen und praktischen Wert ab. So entscheidet man sich etwa f\u00fcr eine Schule oder eine Berufsorganisation vor allem aufgrund ihrer moralischen und praktischen Vorz\u00fcge, seien sie nun real oder empfunden. Oder aus einer anderen Perspektive: Man versp\u00fcrt den Drang ein soziales Umfeld zu verlassen, beziehungsweise es gar nicht erst zu betreten, wenn es keinen praktischen und\/oder moralischen Zwecken dient.<\/p>\n<p>Folglich beruht die epistemische Wirksamkeit eines sozialen Umfelds zu gro\u00dfen Teilen auf seiner praktischen und moralischen Wirksamkeit. Wenn es zum Beispiel einen verl\u00e4sslichen Kommunikationskanal zwischen Mutter und Kind vor allem deshalb gibt, weil die Mutter das Kind liebt und durch diesen Umstand (und andere moralische und praktische Erw\u00e4gungen) motiviert ist, f\u00fcr es zu sorgen. Zwischen einem Anwalt und seinen Klienten gibt es vor allem deshalb einen verl\u00e4sslichen Kommunikationskanal, weil der Anwalt von seinen Klienten bezahlt wird und dadurch (und andere moralische und praktische Erw\u00e4gungen) motiviert ist, in ihrem Interesse zu handeln. Das alles legt nahe, dass unsere Beziehungen ihren epistemischen Wert in gro\u00dfem Ausma\u00df aus ihrem praktischen und moralischen Wert sch\u00f6pft. Die epistemische Wirksamkeit unserer Beziehungen beruht also h\u00e4ufig auf ihrer moralischen und praktischen Wirksamkeit.<\/p>\n<p>Und nat\u00fcrlich ist das im Fall von religi\u00f6sen Gemeinschaften nicht anders. Tats\u00e4chlich erscheint es einleuchtend, dass die vorrangigen Beweggr\u00fcnde f\u00fcr die Mitgliedschaft und Mitwirkung in religi\u00f6sen Gemeinschaften (formell und informell) eher moralischer und praktischer Natur sind als epistemischer. Nichtsdestoweniger impliziert unser Modell, dass der moralische und praktische Wert unserer religi\u00f6sen Gemeinschaften definitiv epistemische Konsequenzen mit sich bringt. Zu dem Grad, zu dem die moralische G\u00fcte und die praktischen Vorteile solcher Gemeinschaften abgetragen werden, wird das auch mit den epistemischen Ressourcen geschehen, die solche Gemeinschaften bieten.<\/p>\n<p><strong>Verschiedene Hindernisse f\u00fcr \u00dcbertragung. <\/strong>Eine vierte Schlussfolgerung aus unserem Modell ist die, dass die Gr\u00fcnde f\u00fcr ein Scheitern von \u00dcbertragung vielf\u00e4ltig sind. Das hei\u00dft, wenn es nicht gut l\u00e4uft, kann die Erkl\u00e4rung daf\u00fcr verschieden ausfallen. Der Fall religi\u00f6sen Glaubens bietet uns hier einleuchtende Beispiele.<\/p>\n<p>Zum einen k\u00f6nnte das Problem beim pers\u00f6nlichen Charakter des Sprechers liegen (einem Gl\u00e4ubigen etwa), dem die moralische Tugend, die Motivation, das praktische Talent oder die intellektuelle Kompetenz fehlt, beim H\u00f6rer Vertrauen aufzubauen. Zum anderen k\u00f6nnte das Problem bei der informellen Gemeinschaft (zum Beispiel einer Familie) liegen, der die Motivation oder die Ressourcen fehlen, um ihren Kindern etwas \u00fcber ihre eigene religi\u00f6se Tradition beizubringen. Drittens k\u00f6nnte das Problem bei der formellen Institution liegen (etwa bei einer Kirche), der es an der moralischen Integrit\u00e4t oder praktischen Kompetenz mangelt, neue Mitglieder anzuziehen und alte zu behalten.<\/p>\n<p>Um ein spezifischeres Beispiel anzubringen: Eine Kombination aus institutioneller Arroganz und Inkompetenz untergrub die F\u00e4higkeit der katholischen Kirche in den Vereinigten Staaten, zahlreiche Missbrauchsskandale zu thematisieren. F\u00fcr viele ihrer Mitglieder untergrub dieses Verhalten seinerseits die moralische Autorit\u00e4t der Kirche, was wiederum ihre Lehrautorit\u00e4t untergrub. Der Fall zeigt eindrucksvoll, wie die \u00dcbertragung von Wissen von praktischen und moralischen Erw\u00e4gungen nachteilig beeinflusst werden kann. Es sei klargestellt, dass die Idee nicht die ist, dass Kirchenmitglieder in ihrer Argumentation von Pr\u00e4missen \u00fcber praktisches und moralisches Scheitern zu Schlussfolgerungen \u00fcber epistemische Autorit\u00e4t kommen. Vielmehr wurden wirksame Zeugniskan\u00e4le erodiert oder zerst\u00f6rt, weil Kirchenmitglieder weniger Vertrauen in die Institution und ihre Autorit\u00e4ten legten oder gleich ganz ausstiegen.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Concluding remarks<\/strong><\/h3>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Ich habe eingangs die Behauptung aufgestellt, der \u201eunzul\u00e4ngliche Atheist\u201c als Entgegnung auf das Problem der Verborgenheit Gottes sei nicht durch eine ad\u00e4quate Epistemologie oder religi\u00f6se \u00dcberzeugung gest\u00fctzt, insofern als dass diese Argumentation die Erkl\u00e4rung f\u00fcr Unglauben nur im Atheisten sieht. Nach der dargestellten Auffassung k\u00f6nnten Erkl\u00e4rungen f\u00fcr Unglauben auch in den Gl\u00e4ubigen und im sozialen Umfeld gefunden werden, wobei letzteres auch die Natur und Qualit\u00e4t interpersoneller Beziehungen, informeller Gemeinschaften und formeller Institutionen sowohl unter moralischen als auch praktischen Aspekten beinhaltet.<\/p>\n<p>Eine zweite Schlussfolgerung ist die, dass eine Aufmerksamkeitsverschiebung hin zu sozialer Epistemologie und Epistemologie von Zeugnissen einen bereichernden Effekt auf religi\u00f6se Epistemologie hat. Der dargestellte Ansatz richtet unser Augenmerk auf pers\u00f6nliche Beziehungen, Gemeinschaften und Institutionen und zeigt, wie deren moralische und praktische Dimensionen von epistemischer Bedeutung sein k\u00f6nnen.<\/p>\n<p>Schlie\u00dflich d\u00fcrften Theisten durch die Verschiebung der Aufmerksamkeit weg von Atheisten hin zu ihnen selbst besser verstehen, wie Aspekte ihrer pers\u00f6nlichen Beziehungen, Gemeinschaften und Institutionen die \u00dcbertragung von religi\u00f6sem Wissen und Glauben unterwandern und so Unglauben hervorbringen k\u00f6nnen. In dieser Hinsicht d\u00fcrfte eine \u201esoziale Wende\u201c in religi\u00f6ser Epistemologie sowohl praktische als auch theoretische Vorteile in sich bergen.<\/p>","protected":false},"excerpt":{"rendered":"<p>Das Problem der Verborgenheit Gottes und das Problem des Leidens \u00a0 Das Problem der Verborgenheit Gottes besteht in der Erkl\u00e4rung von Unglauben: Warum offenbart sich Gott angesichts seiner liebenden und allm\u00e4chtigen Natur nicht allen Menschen gleicherma\u00dfen? Diese Frage kann zu Zweifeln f\u00fchren (und tut dies auch) oder gar in ein Argument gegen die Existenz Gottes&hellip;<\/p>","protected":false},"author":5,"featured_media":32560,"menu_order":139,"template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"class_list":["post-120718","media-library","type-media-library","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Verborgenheit Gottes und die sozialen Dimensionen religi\u00f6ser Erkenntnis - Katholische Akademie in Bayern<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kath-akademie-bayern.de\/en\/mediathek-eintrag\/die-verborgenheit-gottes-und-die-sozialen-dimensionen-religioeser-erkenntnis\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Verborgenheit Gottes und die sozialen Dimensionen religi\u00f6ser Erkenntnis - Katholische Akademie in Bayern\" \/>\n<meta property=\"og:description\" content=\"Das Problem der Verborgenheit Gottes und das Problem des Leidens \u00a0 Das Problem der Verborgenheit Gottes besteht in der Erkl\u00e4rung von Unglauben: Warum offenbart sich Gott angesichts seiner liebenden und allm\u00e4chtigen Natur nicht allen Menschen gleicherma\u00dfen? Diese Frage kann zu Zweifeln f\u00fchren (und tut dies auch) oder gar in ein Argument gegen die Existenz Gottes&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kath-akademie-bayern.de\/en\/mediathek-eintrag\/die-verborgenheit-gottes-und-die-sozialen-dimensionen-religioeser-erkenntnis\/\" \/>\n<meta property=\"og:site_name\" content=\"Katholische Akademie in Bayern\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/katholische.akademie.bayern\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kath-akademie-bayern.de\/wp-content\/uploads\/Philosophie_Humanwissenschaften.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"872\" \/>\n\t<meta property=\"og:image:height\" content=\"490\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"24 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/mediathek-eintrag\\\/die-verborgenheit-gottes-und-die-sozialen-dimensionen-religioeser-erkenntnis\\\/\",\"url\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/mediathek-eintrag\\\/die-verborgenheit-gottes-und-die-sozialen-dimensionen-religioeser-erkenntnis\\\/\",\"name\":\"Die Verborgenheit Gottes und die sozialen Dimensionen religi\u00f6ser Erkenntnis - Katholische Akademie in Bayern\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/mediathek-eintrag\\\/die-verborgenheit-gottes-und-die-sozialen-dimensionen-religioeser-erkenntnis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/mediathek-eintrag\\\/die-verborgenheit-gottes-und-die-sozialen-dimensionen-religioeser-erkenntnis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/wp-content\\\/uploads\\\/Philosophie_Humanwissenschaften.jpg\",\"datePublished\":\"2026-03-20T10:35:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/mediathek-eintrag\\\/die-verborgenheit-gottes-und-die-sozialen-dimensionen-religioeser-erkenntnis\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kath-akademie-bayern.de\\\/mediathek-eintrag\\\/die-verborgenheit-gottes-und-die-sozialen-dimensionen-religioeser-erkenntnis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/mediathek-eintrag\\\/die-verborgenheit-gottes-und-die-sozialen-dimensionen-religioeser-erkenntnis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/wp-content\\\/uploads\\\/Philosophie_Humanwissenschaften.jpg\",\"contentUrl\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/wp-content\\\/uploads\\\/Philosophie_Humanwissenschaften.jpg\",\"width\":872,\"height\":490},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/mediathek-eintrag\\\/die-verborgenheit-gottes-und-die-sozialen-dimensionen-religioeser-erkenntnis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Verborgenheit Gottes und die sozialen Dimensionen religi\u00f6ser Erkenntnis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/#website\",\"url\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/\",\"name\":\"Katholische Akademie in Bayern\",\"description\":\"Kirche braucht Debatte: \u201ekatholisch\u201c mit Blick auf das Ganze \u2013 und \u201eakademisch\u201c im Vertrauen auf die Kraft der Argumente\",\"publisher\":{\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/#organization\",\"name\":\"Katholische Akademie in Bayern\",\"url\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/wp-content\\\/uploads\\\/Menue-Logo-Home@2x.png\",\"contentUrl\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/wp-content\\\/uploads\\\/Menue-Logo-Home@2x.png\",\"width\":496,\"height\":216,\"caption\":\"Katholische Akademie in Bayern\"},\"image\":{\"@id\":\"https:\\\/\\\/kath-akademie-bayern.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/katholische.akademie.bayern\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Hiddenness of God and the Social Dimensions of Religious Knowledge - Katholische Akademie in Bayern","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kath-akademie-bayern.de\/en\/mediathek-eintrag\/die-verborgenheit-gottes-und-die-sozialen-dimensionen-religioeser-erkenntnis\/","og_locale":"en_GB","og_type":"article","og_title":"Die Verborgenheit Gottes und die sozialen Dimensionen religi\u00f6ser Erkenntnis - Katholische Akademie in Bayern","og_description":"Das Problem der Verborgenheit Gottes und das Problem des Leidens \u00a0 Das Problem der Verborgenheit Gottes besteht in der Erkl\u00e4rung von Unglauben: Warum offenbart sich Gott angesichts seiner liebenden und allm\u00e4chtigen Natur nicht allen Menschen gleicherma\u00dfen? Diese Frage kann zu Zweifeln f\u00fchren (und tut dies auch) oder gar in ein Argument gegen die Existenz Gottes&hellip;","og_url":"https:\/\/kath-akademie-bayern.de\/en\/mediathek-eintrag\/die-verborgenheit-gottes-und-die-sozialen-dimensionen-religioeser-erkenntnis\/","og_site_name":"Katholische Akademie in Bayern","article_publisher":"https:\/\/www.facebook.com\/katholische.akademie.bayern\/","og_image":[{"width":872,"height":490,"url":"https:\/\/kath-akademie-bayern.de\/wp-content\/uploads\/Philosophie_Humanwissenschaften.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"24 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kath-akademie-bayern.de\/mediathek-eintrag\/die-verborgenheit-gottes-und-die-sozialen-dimensionen-religioeser-erkenntnis\/","url":"https:\/\/kath-akademie-bayern.de\/mediathek-eintrag\/die-verborgenheit-gottes-und-die-sozialen-dimensionen-religioeser-erkenntnis\/","name":"The Hiddenness of God and the Social Dimensions of Religious Knowledge - Katholische Akademie in Bayern","isPartOf":{"@id":"https:\/\/kath-akademie-bayern.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kath-akademie-bayern.de\/mediathek-eintrag\/die-verborgenheit-gottes-und-die-sozialen-dimensionen-religioeser-erkenntnis\/#primaryimage"},"image":{"@id":"https:\/\/kath-akademie-bayern.de\/mediathek-eintrag\/die-verborgenheit-gottes-und-die-sozialen-dimensionen-religioeser-erkenntnis\/#primaryimage"},"thumbnailUrl":"https:\/\/kath-akademie-bayern.de\/wp-content\/uploads\/Philosophie_Humanwissenschaften.jpg","datePublished":"2026-03-20T10:35:19+00:00","breadcrumb":{"@id":"https:\/\/kath-akademie-bayern.de\/mediathek-eintrag\/die-verborgenheit-gottes-und-die-sozialen-dimensionen-religioeser-erkenntnis\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kath-akademie-bayern.de\/mediathek-eintrag\/die-verborgenheit-gottes-und-die-sozialen-dimensionen-religioeser-erkenntnis\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/kath-akademie-bayern.de\/mediathek-eintrag\/die-verborgenheit-gottes-und-die-sozialen-dimensionen-religioeser-erkenntnis\/#primaryimage","url":"https:\/\/kath-akademie-bayern.de\/wp-content\/uploads\/Philosophie_Humanwissenschaften.jpg","contentUrl":"https:\/\/kath-akademie-bayern.de\/wp-content\/uploads\/Philosophie_Humanwissenschaften.jpg","width":872,"height":490},{"@type":"BreadcrumbList","@id":"https:\/\/kath-akademie-bayern.de\/mediathek-eintrag\/die-verborgenheit-gottes-und-die-sozialen-dimensionen-religioeser-erkenntnis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/kath-akademie-bayern.de\/"},{"@type":"ListItem","position":2,"name":"Die Verborgenheit Gottes und die sozialen Dimensionen religi\u00f6ser Erkenntnis"}]},{"@type":"WebSite","@id":"https:\/\/kath-akademie-bayern.de\/#website","url":"https:\/\/kath-akademie-bayern.de\/","name":"Catholic Academy in Bavaria","description":"Church needs debate: \"catholic\" looking at the whole - and \"academic\" trusting in the power of arguments","publisher":{"@id":"https:\/\/kath-akademie-bayern.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kath-akademie-bayern.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/kath-akademie-bayern.de\/#organization","name":"Catholic Academy in Bavaria","url":"https:\/\/kath-akademie-bayern.de\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/kath-akademie-bayern.de\/#\/schema\/logo\/image\/","url":"https:\/\/kath-akademie-bayern.de\/wp-content\/uploads\/Menue-Logo-Home@2x.png","contentUrl":"https:\/\/kath-akademie-bayern.de\/wp-content\/uploads\/Menue-Logo-Home@2x.png","width":496,"height":216,"caption":"Katholische Akademie in Bayern"},"image":{"@id":"https:\/\/kath-akademie-bayern.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/katholische.akademie.bayern\/"]}]}},"_links":{"self":[{"href":"https:\/\/kath-akademie-bayern.de\/en\/wp-json\/wp\/v2\/media-library\/120718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kath-akademie-bayern.de\/en\/wp-json\/wp\/v2\/media-library"}],"about":[{"href":"https:\/\/kath-akademie-bayern.de\/en\/wp-json\/wp\/v2\/types\/media-library"}],"author":[{"embeddable":true,"href":"https:\/\/kath-akademie-bayern.de\/en\/wp-json\/wp\/v2\/users\/5"}],"version-history":[{"count":1,"href":"https:\/\/kath-akademie-bayern.de\/en\/wp-json\/wp\/v2\/media-library\/120718\/revisions"}],"predecessor-version":[{"id":120719,"href":"https:\/\/kath-akademie-bayern.de\/en\/wp-json\/wp\/v2\/media-library\/120718\/revisions\/120719"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kath-akademie-bayern.de\/en\/wp-json\/wp\/v2\/media\/32560"}],"wp:attachment":[{"href":"https:\/\/kath-akademie-bayern.de\/en\/wp-json\/wp\/v2\/media?parent=120718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}